{"id":3943,"date":"2026-03-18T11:15:59","date_gmt":"2026-03-18T11:15:59","guid":{"rendered":"https:\/\/changyupump.com\/?post_type=product&#038;p=3943"},"modified":"2026-04-24T02:09:22","modified_gmt":"2026-04-24T02:09:22","slug":"horizontal-multistage-centrifugal-pump","status":"publish","type":"product","link":"https:\/\/changyupump.com\/es\/product\/horizontal-multistage-centrifugal-pump\/","title":{"rendered":"Bomba centr\u00edfuga horizontal multietapa resistente a la corrosi\u00f3n de la serie DF"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id3943_83b503-88{margin-top:-20px;margin-bottom:50px;}.kb-row-layout-id3943_83b503-88 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_83b503-88 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_83b503-88 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3943_83b503-88 > .kt-row-layout-overlay{opacity:0.95;background-color:#f0f2f4;}@media all and (max-width: 1024px){.kb-row-layout-id3943_83b503-88 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3943_83b503-88 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_83b503-88 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3943_87ddad-d0 > .kt-inside-inner-col,.kadence-column3943_87ddad-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_87ddad-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_87ddad-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_87ddad-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_87ddad-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_87ddad-d0{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_87ddad-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_87ddad-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_87ddad-d0\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-type-thumbslider.kb-gallery-id-3943_073ce1-ca .kt-blocks-carousel-init {margin-bottom:10px;}.kb-gallery-id-3943_073ce1-ca .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-3943_073ce1-ca .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-3943_073ce1-ca alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-thumbslider kb-gallery-id-3943_073ce1-ca kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div id=\"kb-slider-3943_073ce1-ca\" class=\"kt-blocks-carousel-init splide kb-blocks-slider kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"4\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-thumb-slider-3943_073ce1-ca\"  data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg\" data-id=\"3955\" class=\"wp-image-3955 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-16x12.jpg 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg\" data-id=\"3956\" class=\"wp-image-3956 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-16x12.jpg 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg\" data-id=\"3957\" class=\"wp-image-3957 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-16x12.jpg 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-1024x768.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg\" data-id=\"3958\" class=\"wp-image-3958 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-16x12.jpg 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><div id=\"kb-thumb-slider-3943_073ce1-ca\" class=\"kb-blocks-slider splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-speed=\"7000\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-slider-3943_073ce1-ca\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump \" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg\" data-id=\"3955\" class=\"wp-image-3955 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1.jpg 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg\" data-id=\"3956\" class=\"wp-image-3956 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2.jpg 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-2-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg\" data-id=\"3957\" class=\"wp-image-3957 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3.jpg 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-3-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg\" width=\"1024\" height=\"768\" alt=\"Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg\" data-id=\"3958\" class=\"wp-image-3958 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4.jpg 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-300x225.jpg 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-1024x768.jpg 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-150x113.jpg 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-768x576.jpg 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-4-16x12.jpg 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column3943_dd0e27-22 > .kt-inside-inner-col,.kadence-column3943_dd0e27-22 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_dd0e27-22 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_dd0e27-22 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_dd0e27-22 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_dd0e27-22 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_dd0e27-22{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_dd0e27-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_dd0e27-22 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_dd0e27-22\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">DF Series Corrosion Resistant Horizontal Multistage Centrifugal Pump<\/h2>\n\n\n\n<p style=\"font-size:18px\">Type DF pumps are horizontal multistage corrosion-resistant centrifugal pumps, specifically engineered for seawater desalination, brine mining, and salt chemical industries. Designed with a segmental casing and advanced balancing system, they are ideal for conveying high-salinity brine and aggressive chemical fluids. By utilizing high-grade materials such as Duplex Stainless Steel or SS316L, the DF series ensures exceptional durability and reliable high-pressure performance in environments prone to pitting and stress corrosion.<\/p>\n\n\n<style>.kb-table-container3943_9b5d9d-13{overflow-x:auto;}.kb-table3943_9b5d9d-13 td:nth-of-type(1), .kb-table3943_9b5d9d-13 th:nth-of-type(1){width:30%;}.kb-table3943_9b5d9d-13{table-layout:fixed;width:100%;}.kb-table-container .kb-table3943_9b5d9d-13 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table3943_9b5d9d-13 caption{text-align:center;}.kb-table-container .kb-table3943_9b5d9d-13 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}.kb-table-container .kb-table3943_9b5d9d-13 tr:nth-of-type(odd){background-color:rgba(225,225,225,0.8);}.kb-table-container .kb-table3943_9b5d9d-13 td, .kb-table3943_9b5d9d-13 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-table-container .kb-table3943_9b5d9d-13 td, .kb-table3943_9b5d9d-13 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-table-container .kb-table3943_9b5d9d-13 td, .kb-table3943_9b5d9d-13 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-table-container kb-table-container3943_9b5d9d-13 wp-block-kadence-table\"><table class=\"kb-table kb-table3943_9b5d9d-13\">\n<tr class=\"kb-table-row kb-table-row3943_b0e070-20\">\n<th class=\"kb-table-data kb-table-data3943_45e22d-9f\">\n\n<p class=\"has-text-align-left\">Flow Rate Range :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data3943_da7f80-28\">\n\n<p>3.75m\u00b3\/h~850m\u00b3\/h<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row3943_86b2df-a3\">\n<th class=\"kb-table-data kb-table-data3943_a2ab67-8e\">\n\n<p class=\"has-text-align-left\">Head Range: <\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data3943_dfe8d9-a9\">\n\n<p>19m~816m<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row3943_f2ea6b-22\">\n<th class=\"kb-table-data kb-table-data3943_5b44ee-75\">\n\n<p class=\"has-text-align-left\">Motor Power :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data3943_ae4810-ad\">\n\n<p>3kw~1600kw<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row3943_b590e6-48\">\n<th class=\"kb-table-data kb-table-data3943_d35070-c4\">\n\n<p class=\"has-text-align-left\">Speed:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data3943_9d4a37-06\">\n\n<p class=\"has-text-align-left\">2980- 1480r\/min<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row3943_23a5c7-2b\">\n<th class=\"kb-table-data kb-table-data3943_442b1d-8b\">\n\n<p class=\"has-text-align-left\">Medium Temperature Range:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data3943_26d18c-44\">\n\n<p>\u226480\u2103<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row3943_32680f-3e\">\n<th class=\"kb-table-data kb-table-data3943_71b612-a8\">\n\n<p class=\"has-text-align-left\">Customizable Materials:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data3943_967be3-e3\">\n\n<p>316\/316L\/2205 Duplex Steel\/2507 Super Duplex Steel<\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n<!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Introduction<\/h2>\n\n\n\n<p>The DF Series Corrosion Resistant Horizontal Multistage Centrifugal Pump is a high-performance fluid handling solution specifically engineered for the most demanding environments, including sea water desalination, brine mining, and salt chemical processing. Designed with a robust segmental casing (drum-type) structure, this horizontal multistage pump features Changyu&#8217;s innovative four-stage axial force balancing system (comprising a balancing drum, pressure adjustment ring, throttle plate, and precision positioning). This advanced technology achieves complete axial force neutralization, ensuring exceptional stability and a 15% increase in energy efficiency throughout its lifecycle, especially under fluctuating frequencies or abrasive conditions.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-3943_47b8bd-ab{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-3943_47b8bd-ab .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-3943_47b8bd-ab .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-3943_47b8bd-ab .kb-slide-item .kb-gal-image-radius img{border-radius:10px 10px 10px 10px;;}<\/style><div class=\"kb-gallery-wrap-id-3943_47b8bd-ab alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-3943_47b8bd-ab kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump.webp\" width=\"585\" height=\"771\" alt=\"Corrosion Resistant Horizontal Multistage Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump.webp\" data-id=\"3962\" class=\"wp-image-3962\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump.webp 585w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump-228x300.webp 228w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump-114x150.webp 114w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Corrosion-Resistant-Horizontal-Multistage-Centrifugal-Pump-9x12.webp 9w\" sizes=\"auto, (max-width: 585px) 100vw, 585px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-1024x511.webp\" width=\"1024\" height=\"511\" alt=\"horizontal multistage centrifugal pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump.webp\" data-id=\"3963\" class=\"wp-image-3963\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-1024x511.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-300x150.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-150x75.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-768x384.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-1536x767.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump-18x9.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/horizontal-multistage-centrifugal-pump.webp 1640w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump-1024x707.webp\" width=\"1024\" height=\"707\" alt=\"multistage centrifugal pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump.webp\" data-id=\"3964\" class=\"wp-image-3964\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump-1024x707.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump-300x207.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump-150x104.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump-768x530.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump-18x12.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/multistage-centrifugal-pump.webp 1237w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<p>Built to withstand extreme salinity and chemical aggression, the Changyu DF series offers superior resistance to pitting and chloride-induced stress corrosion. With versatile material selections\u2014including various grades of Stainless Steel, High-Chromium Alloys, and Duplex Steel\u2014it ensures the safe and continuous transportation of corrosive fluids. The rotor and stator feature a differential hardness friction pair design, reducing clearance and increasing overall efficiency by over 3%. Whether applied in high-pressure reverse osmosis (RO), salt extraction, or aggressive chemical transfer, the Changyu DF series corrosion-resistant horizontal multistage centrifugal pump delivers reliable performance with flow rates ranging from 3.75 to 850 m\u00b3\/h and heads from 19 to 816 m. Trust <a href=\"https:\/\/changyupump.com\/about-us\/\" data-type=\"page\" data-id=\"16\">Changyu Pump<\/a> ISO-certified technology to minimize operational downtime and extend the service life of your critical industrial systems.<\/p>\n\n\n<style>.kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list{margin-right:-10px;}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list li .kt-tab-title{margin-right:10px;}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #eeeeee);}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #EDF2F7);}.wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:#ffffff;background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}@media all and (max-width: 767px){.kt-tabs-id3943_971a58-e6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id3943_971a58-e6 kt-tabs-has-2-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list kb-tabs-list-columns kb-tab-title-columns-6\"><li id=\"tab-strongpartsstrong\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-strongpartsstrong\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\"><strong>Parts<\/strong><\/span><\/a><\/li><li id=\"tab-strongspecificationsstrong\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-strongspecificationsstrong\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\"><strong>Specifications<\/strong><\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab3943_54c53b-46\"><div class=\"kt-tab-inner-content-inner\">\n<h3 class=\"wp-block-heading\">Parts of Horizontal Multistage Centrifugal Pump<\/h3>\n\n\n\n<p>Changyu Pump\u2019s DF Series Corrosion Resistant Horizontal Multistage Centrifugal Pump is a high-performance fluid handling solution specifically engineered for the most demanding environments, including seawater desalination, brine mining, and salt chemical processing. Designed with a robust segmental casing (drum-type) structure, this pump features an innovative four-stage axial force balancing system that achieves complete axial force neutralization. This advanced technology ensures exceptional stability and a 15% increase in energy efficiency throughout its lifecycle, even under fluctuating frequencies or abrasive conditions.<\/p>\n\n\n<style>.kb-image3943_193252-4a.kb-image-is-ratio-size, .kb-image3943_193252-4a .kb-image-is-ratio-size{max-width:1000px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image3943_193252-4a.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image3943_193252-4a .kb-image-is-ratio-size{align-self:unset;}.kb-image3943_193252-4a figure{max-width:1000px;}.kb-image3943_193252-4a .image-is-svg, .kb-image3943_193252-4a .image-is-svg img{width:100%;}.kb-image3943_193252-4a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image3943_193252-4a\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"959\" height=\"855\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Parts-of-Horizontal-Multistage-Centrifugal-Pump.webp\" alt=\"Parts of Horizontal Multistage Centrifugal Pump\" class=\"kb-img wp-image-3965\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Parts-of-Horizontal-Multistage-Centrifugal-Pump.webp 959w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Parts-of-Horizontal-Multistage-Centrifugal-Pump-300x267.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Parts-of-Horizontal-Multistage-Centrifugal-Pump-150x134.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Parts-of-Horizontal-Multistage-Centrifugal-Pump-768x685.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Parts-of-Horizontal-Multistage-Centrifugal-Pump-13x12.webp 13w\" sizes=\"auto, (max-width: 959px) 100vw, 959px\" \/><figcaption>Parts of Horizontal Multistage Centrifugal Pump<\/figcaption><\/figure><\/div>\n\n\n<style>.kb-row-layout-id3943_29c07b-3b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_29c07b-3b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_29c07b-3b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3943_29c07b-3b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_29c07b-3b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_29c07b-3b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_29c07b-3b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_b29be0-ce > .kt-inside-inner-col,.kadence-column3943_b29be0-ce > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_b29be0-ce > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_b29be0-ce > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_b29be0-ce > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_b29be0-ce > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_b29be0-ce{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_b29be0-ce > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_b29be0-ce > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_b29be0-ce\"><div class=\"kt-inside-inner-col\">\n<h4 class=\"wp-block-heading\">Casing &amp; Structural Components<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Suction Casing: Located at the pump&#8217;s inlet (typically on the left), it smoothly guides seawater or brine into the first-stage impeller.<\/li>\n\n\n\n<li>Stage Casing \/ Middle Section: Positioned between the suction and discharge sections with a &#8220;drum-type&#8221; design. Each section houses an impeller and diffuser, forming the core pressure-boosting zone.<\/li>\n\n\n\n<li>Discharge Casing: Located at the outlet (right side), it collects the pressurized liquid and directs it to the discharge piping.<\/li>\n\n\n\n<li>Tightening Bolts \/ Tension Rods: High-strength bolts that traverse the entire pump body, tightly securing the suction, stage, and discharge sections into a single pressure-resistant unit.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Rotor System &#8211; The Operational Heart<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Shaft: <\/strong>The central transmission component made of high-strength stainless steel or duplex steel, transmitting motor power to each impeller.<\/li>\n\n\n\n<li><strong>Impellers:<\/strong> Arranged in series. Changyu Pump&#8217;s DF series utilizes precision-cast SS316L or duplex steel impellers to resist pitting in high-salinity media.<\/li>\n\n\n\n<li><strong>Diffusers:<\/strong> Fixed within the stage casings to convert kinetic energy into pressure energy. Combined with differential hardness friction pairs, it boosts overall efficiency by over 3%.<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Advanced Four-Stage Balancing System<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Stage 1: <\/strong>Balancing Drum\n<ul class=\"wp-block-list\">\n<li>Works with the balancing sleeve to offset approximately <strong>70%<\/strong> of the axial thrust.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Stage 2: <\/strong>Pressure Adjustment Ring\n<ul class=\"wp-block-list\">\n<li>Operates in tandem with the drum to neutralize another <strong>20%<\/strong> of the force.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Stage 3: <\/strong>Throttle Plate\n<ul class=\"wp-block-list\">\n<li>Precisely balances the remaining <strong>10%<\/strong> of the axial thrust.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Stage 4: <\/strong>Precision Positioning System\n<ul class=\"wp-block-list\">\n<li>Handles instantaneous thrust changes during frequency conversions or harsh startup conditions.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<h4 class=\"wp-block-heading\">Sealing &amp; Bearing Units<\/h4>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Mechanical Seal:<\/strong> Positioned where the shaft exits the casing. High-performance corrosion-resistant seals are used for salt chemical processes to ensure zero leakage.<\/li>\n\n\n\n<li><strong>Bearing Housing:<\/strong> Supports the high-speed rotation of the rotor. Thanks to the four-stage balancing system, bearing load is minimized, significantly extending service life.<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{display:flex;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col,.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3943_4ba3d4-05{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_4ba3d4-05{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_4ba3d4-05{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3943_4ba3d4-05{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_4ba3d4-05{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3943_4ba3d4-05{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_4ba3d4-05{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_4ba3d4-05 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_4ba3d4-05\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-3943_3612d3-8f{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-3943_3612d3-8f .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-3943_3612d3-8f .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-3943_3612d3-8f .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-id-3943_3612d3-8f .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:var(--global-kb-font-size-sm, 0.9rem);}.kb-gallery-caption-style-bottom.kb-gallery-id-3943_3612d3-8f .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-bottom-hover.kb-gallery-id-3943_3612d3-8f .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:linear-gradient(0deg, rgba(0, 0, 0, 0.5) 0, rgba(0, 0, 0, 0) 100%);}<\/style><div class=\"kb-gallery-wrap-id-3943_3612d3-8f alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-3943_3612d3-8f kb-gallery-caption-style-bottom kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"6\" data-columns-xl=\"6\" data-columns-md=\"6\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371.webp\" data-description=\"horizontal multistage centrifugal pump\" data-alt=\"horizontal multistage centrifugal pump\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371-1024x616.webp\" width=\"1024\" height=\"616\" alt=\"horizontal multistage centrifugal pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371.webp\" data-id=\"3966\" class=\"wp-image-3966\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371-1024x616.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371-300x180.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371-150x90.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371-768x462.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371-18x12.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/ScreenShot_2026-03-20_152559_371.webp 1417w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">horizontal multistage centrifugal pump<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1.webp\" data-description=\"Pump Shaft\" data-alt=\"Pump shaft\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1-1024x1024.webp\" width=\"1024\" height=\"1024\" alt=\"Pump shaft\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1.webp\" data-id=\"2944\" class=\"wp-image-2944\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1-1024x1024.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1-300x300.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1-150x150.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1-768x768.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Pump-shaft-1.webp 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Pump Shaft<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1.webp\" data-id=\"3521\" class=\"wp-image-3521\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-4-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3.webp\" data-id=\"3520\" class=\"wp-image-3520\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-3.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5.webp\" data-id=\"3522\" class=\"wp-image-3522\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-5.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1.webp\" data-id=\"3526\" class=\"wp-image-3526\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Parts-of-a-High-Pressure-Multistage-Pump-9-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><em><strong>Notice:<\/strong> Trust <a href=\"https:\/\/changyupump.com\/about-us\/\" data-type=\"page\" data-id=\"16\">Changyu Pump\u2019s<\/a> <a href=\"https:\/\/www.iso.org\/standard\/62085.html\" data-type=\"link\" data-id=\"https:\/\/www.iso.org\/standard\/62085.html\" target=\"_blank\" rel=\"noopener\">ISO<\/a>-certified DF Series Corrosion Resistant Horizontal Multistage Centrifugal Pump to minimize operational downtime and lower your total cost of ownership in high-salinity industrial applications.<\/em><\/p>\n\n\n<style>.kb-row-layout-id3943_e77ce1-34 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_e77ce1-34 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_e77ce1-34 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id3943_e77ce1-34 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_e77ce1-34 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3943_e77ce1-34 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_e77ce1-34 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_e7c820-25 > .kt-inside-inner-col{display:flex;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col,.kadence-column3943_e7c820-25 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_e7c820-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3943_e7c820-25{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_e7c820-25{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_e7c820-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_e7c820-25{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3943_e7c820-25{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_e7c820-25{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_e7c820-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3943_e7c820-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3943_e7c820-25{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_e7c820-25{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_e7c820-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_e7c820-25 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_e7c820-25\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +86-13651913727<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_13b66e-48 > .kt-inside-inner-col{display:flex;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col,.kadence-column3943_13b66e-48 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_13b66e-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3943_13b66e-48{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_13b66e-48{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_13b66e-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_13b66e-48{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3943_13b66e-48{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_13b66e-48{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_13b66e-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3943_13b66e-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3943_13b66e-48{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_13b66e-48{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_13b66e-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_13b66e-48 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_13b66e-48\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab3943_fb651e-d5\"><div class=\"kt-tab-inner-content-inner\">\n<h2 class=\"wp-block-heading\">Specifications<\/h2>\n\n\n\n<h2 class=\"wp-block-heading\">Technical Specifications: DF Series Horizontal Multistage Centrifugal Pump<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><td><strong>Parameter<\/strong><\/td><td><strong>Range &amp; Specifications <\/strong><\/td><\/tr><\/thead><tbody><tr><td><strong>Flow Rate <\/strong><\/td><td>3.75 m\u00b3\/h \u2013 850 m\u00b3\/h<\/td><\/tr><tr><td><strong>Head <\/strong><\/td><td>19 m \u2013 816 m<\/td><\/tr><tr><td><strong>Power Output<\/strong><\/td><td>3 kW \u2013 1600 kW<\/td><\/tr><tr><td><strong>Max. Working Temperature<\/strong><\/td><td>\u2264 80\u00b0C<\/td><\/tr><tr><td><strong>Balancing System <\/strong><\/td><td>Innovative Four-stage Axial Force Balancing (15% Energy Saving)<\/td><\/tr><tr><td><strong>Efficiency Boost<\/strong><\/td><td><strong>&gt;3%<\/strong> (via Differential Hardness Friction Pairs)<\/td><\/tr><tr><td><strong>Max. Inlet Pressure <\/strong><\/td><td><strong>Customizable<\/strong> (Please specify during inquiry)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Detailed Material Configuration<\/h3>\n\n\n\n<p>To ensure maximum durability in aggressive environments like seawater desalination and brine mining, the Changyu DF Series offers specialized material selections:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Casing &amp; Impeller:<\/strong> Stainless Steel (SS304, SS316, SS316L), Duplex Stainless Steel (2205\/2507), High-Chromium Alloy.<\/li>\n\n\n\n<li><strong>Pump Shaft:<\/strong> High-strength Stainless Steel (2Cr13), SS304, or Duplex Steel for extreme torque and corrosion resistance.<\/li>\n\n\n\n<li><strong>Static Sealing:<\/strong> Fluorine Rubber (Viton) \/ PTFE.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Standard Sealing Options<\/h3>\n\n\n\n<p>Mechanical Seal (Single\/Double): Engineered for zero leakage in chemical processing and high-pressure salt chemical transfer.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Model Identification Code (Example)<\/h3>\n\n\n\n<p>To help our engineers select the right DF Series Corrosion-Resistant Horizontal Multistage Centrifugal Pump for your project, please refer to the following naming convention:<\/p>\n\n\n\n<p> The example <strong>DF 280 \u2013 43 x 5<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>DF:<\/strong> Series Name (Single-suction, Multistage, Segmental Corrosion-resistant Centrifugal Pump)<\/li>\n\n\n\n<li><strong>280:<\/strong> Design Flow Rate (m\u00b3\/h)<\/li>\n\n\n\n<li><strong>43:<\/strong> Single-stage Head (m)<\/li>\n\n\n\n<li><strong>5:<\/strong> Number of Stages (Total Head = Single-stage Head \u00d7 Number of Stages)<\/li>\n<\/ul>\n\n\n\n<p><em>Due to the complexity of chemical media and the high-pressure requirements in desalination and brine mining, please contact our technical team with your specific liquid concentration and inlet pressure. We provide customized solutions to lower your total cost of ownership.<\/em><\/p>\n\n\n<style>.kb-row-layout-id3943_ee37ca-8e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_ee37ca-8e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_ee37ca-8e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id3943_ee37ca-8e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_ee37ca-8e > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3943_ee37ca-8e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_ee37ca-8e alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{display:flex;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col,.kadence-column3943_29d1cf-02 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3943_29d1cf-02{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_29d1cf-02{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_29d1cf-02{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3943_29d1cf-02{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_29d1cf-02{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3943_29d1cf-02{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_29d1cf-02{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_29d1cf-02 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_29d1cf-02\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +86-13651913727<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{display:flex;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col,.kadence-column3943_dde4bf-86 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column3943_dde4bf-86{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_dde4bf-86{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_dde4bf-86{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column3943_dde4bf-86{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_dde4bf-86{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column3943_dde4bf-86{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_dde4bf-86{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column3943_dde4bf-86 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_dde4bf-86\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/DF-Series-Horizontal-Multistage-Centrifugal-Pump.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Incrustado de DF Series Horizontal Multistage Centrifugal Pump.\"><\/object><a id=\"wp-block-file--media-7cb42138-02e2-45d3-8aed-cd6ff3cc6d6f\" href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/DF-Series-Horizontal-Multistage-Centrifugal-Pump.pdf\">DF Series Horizontal Multistage Centrifugal Pump<\/a><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/DF-Series-Horizontal-Multistage-Centrifugal-Pump.pdf\" class=\"wp-block-file__button wp-element-button\" aria-describedby=\"wp-block-file--media-7cb42138-02e2-45d3-8aed-cd6ff3cc6d6f\" download>Download<\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-id3943_6c3767-3d > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_6c3767-3d > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_6c3767-3d > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3943_6c3767-3d > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_6c3767-3d > .kt-row-column-wrap{padding-top:80px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_6c3767-3d > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_6c3767-3d alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_4300c4-24 > .kt-inside-inner-col,.kadence-column3943_4300c4-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_4300c4-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_4300c4-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_4300c4-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_4300c4-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_4300c4-24{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_4300c4-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_4300c4-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_4300c4-24 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3943_60e7c2-d3, .wp-block-kadence-advancedheading.kt-adv-heading3943_60e7c2-d3[data-kb-block=\"kb-adv-heading3943_60e7c2-d3\"]{text-align:center;font-size:20px;font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3943_60e7c2-d3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3943_60e7c2-d3[data-kb-block=\"kb-adv-heading3943_60e7c2-d3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3943_60e7c2-d3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3943_60e7c2-d3[data-kb-block=\"kb-adv-heading3943_60e7c2-d3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading3943_60e7c2-d3 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading3943_60e7c2-d3\">Why Choose It?<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading3943_26cca7-86, .wp-block-kadence-advancedheading.kt-adv-heading3943_26cca7-86[data-kb-block=\"kb-adv-heading3943_26cca7-86\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading3943_26cca7-86 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3943_26cca7-86[data-kb-block=\"kb-adv-heading3943_26cca7-86\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3943_26cca7-86 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3943_26cca7-86[data-kb-block=\"kb-adv-heading3943_26cca7-86\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3943_26cca7-86 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading3943_26cca7-86\">Advantages of Horizontal Multistage Centrifugal Pump<\/h2>\n\n\n<style>.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id3943_c2f9e9-18 > .kt-row-layout-overlay{opacity:0.00;}@media all and (max-width: 1024px){.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3943_c2f9e9-18 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_c2f9e9-18 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column3943_75a729-1d > .kt-inside-inner-col{display:flex;}.kadence-column3943_75a729-1d > .kt-inside-inner-col,.kadence-column3943_75a729-1d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_75a729-1d > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_75a729-1d > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_75a729-1d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_75a729-1d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_75a729-1d{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_75a729-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_75a729-1d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_75a729-1d inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box3943_d5db94-7a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_d5db94-7a .kt-info-svg-icon-flip, .kt-info-box3943_d5db94-7a .kt-blocks-info-box-number{font-size:25px;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box3943_d5db94-7a .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_d5db94-7a .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box3943_d5db94-7a .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box3943_d5db94-7a .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_d5db94-7a\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_aperture kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"14.31\" y1=\"8\" x2=\"20.05\" y2=\"17.94\"\/><line x1=\"9.69\" y1=\"8\" x2=\"21.17\" y2=\"8\"\/><line x1=\"7.38\" y1=\"12\" x2=\"13.12\" y2=\"2.06\"\/><line x1=\"9.69\" y1=\"16\" x2=\"3.95\" y2=\"6.06\"\/><line x1=\"14.31\" y1=\"16\" x2=\"2.83\" y2=\"16\"\/><line x1=\"16.62\" y1=\"12\" x2=\"10.88\" y2=\"21.94\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Innovative Four-Stage Balancing System<\/h3><p class=\"kt-blocks-info-box-text\">Featuring an exclusive four-stage axial force balancing technology (balancing drum + pressure ring + throttle plate + precision positioning), the DF series achieves 100% axial force neutralization. This ensures exceptional stability and reliability even under harsh conditions like variable frequency operation or fluids with impurities.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box3943_9ba1f3-91 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_9ba1f3-91 .kt-info-svg-icon-flip, .kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box3943_9ba1f3-91 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_9ba1f3-91 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box3943_9ba1f3-91 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_9ba1f3-91\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_archive kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"21 8 21 21 3 21 3 8\"\/><rect x=\"1\" y=\"3\" width=\"22\" height=\"5\"\/><line x1=\"10\" y1=\"12\" x2=\"14\" y2=\"12\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Superior Corrosion Resistance<\/h3><p class=\"kt-blocks-info-box-text\">Specifically engineered for seawater desalination, brine mining, and salt chemicals, the pump components are precision-cast from high-grade materials such as SS316L or Duplex Stainless Steel. This provides ultimate protection against pitting and chloride-induced stress corrosion.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_a2167c-87 > .kt-inside-inner-col,.kadence-column3943_a2167c-87 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_a2167c-87 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_a2167c-87 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_a2167c-87 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_a2167c-87 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_a2167c-87{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_a2167c-87 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_a2167c-87 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_a2167c-87 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image3943_1f1f4e-10 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image3943_1f1f4e-10 img.kb-img, .kb-image3943_1f1f4e-10 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;box-shadow:inset 0px 0px 60px -15px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image3943_1f1f4e-10\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump1.webp\" alt=\"Horizontal Multistage Centrifugal Pump\" class=\"kb-img wp-image-3968\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump1.webp 600w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump1-225x300.webp 225w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump1-113x150.webp 113w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump1-9x12.webp 9w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div><figcaption>Horizontal Multistage Centrifugal Pump<\/figcaption><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col{display:flex;}.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col,.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_54b6e4-c6{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_54b6e4-c6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_54b6e4-c6 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box3943_d33860-8b .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_d33860-8b .kt-info-svg-icon-flip, .kt-info-box3943_d33860-8b .kt-blocks-info-box-number{font-size:25px;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box3943_d33860-8b .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_d33860-8b .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box3943_d33860-8b .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box3943_d33860-8b .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_d33860-8b\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">High-Efficiency &amp; Energy Saving<\/h3><p class=\"kt-blocks-info-box-text\">Utilizing a state-recommended hydraulic model and multi-streamline transition technology, the Changyu DF series reduces energy loss and boosts overall efficiency by over 3%. This advanced design delivers a 15% increase in energy saving across the entire equipment lifecycle.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box3943_532463-77 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_532463-77 .kt-info-svg-icon-flip, .kt-info-box3943_532463-77 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box3943_532463-77 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box3943_532463-77 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box3943_532463-77 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_532463-77 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box3943_532463-77 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box3943_532463-77 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box3943_532463-77 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_532463-77\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_cpu kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"4\" y=\"4\" width=\"16\" height=\"16\" rx=\"2\" ry=\"2\"\/><rect x=\"9\" y=\"9\" width=\"6\" height=\"6\"\/><line x1=\"9\" y1=\"1\" x2=\"9\" y2=\"4\"\/><line x1=\"15\" y1=\"1\" x2=\"15\" y2=\"4\"\/><line x1=\"9\" y1=\"20\" x2=\"9\" y2=\"23\"\/><line x1=\"15\" y1=\"20\" x2=\"15\" y2=\"23\"\/><line x1=\"20\" y1=\"9\" x2=\"23\" y2=\"9\"\/><line x1=\"20\" y1=\"14\" x2=\"23\" y2=\"14\"\/><line x1=\"1\" y1=\"9\" x2=\"4\" y2=\"9\"\/><line x1=\"1\" y1=\"14\" x2=\"4\" y2=\"14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Simplified Maintenance &amp; Durability<\/h3><p class=\"kt-blocks-info-box-text\">The modular design is compatible with traditional balancing disk installation dimensions, allowing for quick replacements and minimal downtime. With a differential hardness friction pair design for the rotor and stator, the DF series significantly extends service life and reduces labor costs.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3943_074713-2f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_074713-2f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_074713-2f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3943_074713-2f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_074713-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_074713-2f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_074713-2f alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3943_4229c2-16 > .kt-inside-inner-col,.kadence-column3943_4229c2-16 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_4229c2-16 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_4229c2-16 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_4229c2-16 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_4229c2-16 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_4229c2-16{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_4229c2-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_4229c2-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_4229c2-16\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id3943_271134-70 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_271134-70 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_271134-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3943_271134-70 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_271134-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_271134-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_271134-70 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3943_75f81e-13 > .kt-inside-inner-col,.kadence-column3943_75f81e-13 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_75f81e-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_75f81e-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_75f81e-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_75f81e-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_75f81e-13{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_75f81e-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_75f81e-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_75f81e-13\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading3943_c4fabe-75, .wp-block-kadence-advancedheading.kt-adv-heading3943_c4fabe-75[data-kb-block=\"kb-adv-heading3943_c4fabe-75\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:36px;line-height:1.4;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading3943_c4fabe-75 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading3943_c4fabe-75[data-kb-block=\"kb-adv-heading3943_c4fabe-75\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading3943_c4fabe-75 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading3943_c4fabe-75[data-kb-block=\"kb-adv-heading3943_c4fabe-75\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading3943_c4fabe-75 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading3943_c4fabe-75\">Applications: Horizontal Multistage Centrifugal Pump<\/h2>\n\n\n\n<p class=\"has-text-align-center\" style=\"padding-right:3rem;padding-left:3rem\">Changyu Pump\u2019s DF series horizontal multistage centrifugal pumps provide high-efficiency, high-pressure fluid handling solutions. Specifically engineered for extreme corrosion resistance and durability, they are widely used across multiple high-salinity sectors to ensure the safe and stable transportation of aggressive media.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id3943_8016ef-15 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id3943_8016ef-15 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_8016ef-15 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_502e7e-10 > .kt-inside-inner-col,.kadence-column3943_502e7e-10 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_502e7e-10 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_502e7e-10 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_502e7e-10 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_502e7e-10 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_502e7e-10{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_502e7e-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_502e7e-10 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_502e7e-10\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_432039-1a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_432039-1a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_432039-1a.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3943_432039-1a .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box3943_432039-1a .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1200px;height:0px;max-width:100%;}.kt-info-box3943_432039-1a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_432039-1a .kt-info-svg-icon-flip, .kt-info-box3943_432039-1a .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3943_432039-1a .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_432039-1a .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3943_432039-1a .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box3943_432039-1a .kt-blocks-info-box-text{font-size:16px;}.kt-info-box3943_432039-1a .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box3943_432039-1a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box3943_432039-1a .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_432039-1a\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination.webp\" alt=\"Seawater Desalination\" width=\"1200\" height=\"818\" class=\"kt-info-box-image wp-image-3537\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination-300x205.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination-1024x698.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination-150x102.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination-768x524.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Seawater-Desalination-18x12.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Sea Water Desalination<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">High-pressure Reverse Osmosis (RO) feed pumps and concentrated brine transportation.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_338034-ed > .kt-inside-inner-col,.kadence-column3943_338034-ed > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_338034-ed > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_338034-ed > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_338034-ed > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_338034-ed > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_338034-ed{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_338034-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_338034-ed > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_338034-ed\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_e0d1ae-91.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3943_e0d1ae-91 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box3943_e0d1ae-91 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:800px;height:0px;max-width:100%;}.kt-info-box3943_e0d1ae-91 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_e0d1ae-91 .kt-info-svg-icon-flip, .kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3943_e0d1ae-91 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box3943_e0d1ae-91 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_e0d1ae-91\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Salt-Chemical-Processing.webp\" alt=\"Salt Chemical Processing\" width=\"800\" height=\"534\" class=\"kt-info-box-image wp-image-3535\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Salt-Chemical-Processing.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Salt-Chemical-Processing-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Salt-Chemical-Processing-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Salt-Chemical-Processing-768x513.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Salt-Chemical-Processing-18x12.webp 18w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Brine Mining &amp; Salt Chemicals<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Extraction and circulation of high-concentration salt solutions and aggressive chemical fluids.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_48c496-ab > .kt-inside-inner-col,.kadence-column3943_48c496-ab > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_48c496-ab > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_48c496-ab > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_48c496-ab > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_48c496-ab > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_48c496-ab{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_48c496-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_48c496-ab > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_48c496-ab\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_22cbe5-c8.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3943_22cbe5-c8 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box3943_22cbe5-c8 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1080px;height:0px;max-width:100%;}.kt-info-box3943_22cbe5-c8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_22cbe5-c8 .kt-info-svg-icon-flip, .kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3943_22cbe5-c8 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box3943_22cbe5-c8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_22cbe5-c8\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage.webp\" alt=\"Mining and Mine Drainage\" width=\"1080\" height=\"629\" class=\"kt-info-box-image wp-image-3421\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage.webp 1080w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage-300x175.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage-1024x596.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage-150x87.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage-768x447.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Mining-and-Mine-Drainage-18x10.webp 18w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Metallurgy &amp; Mining<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Drainage of corrosive mine water and acidic liquid transfer in smelting processes.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_17f4dc-99 > .kt-inside-inner-col,.kadence-column3943_17f4dc-99 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_17f4dc-99 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_17f4dc-99 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_17f4dc-99 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_17f4dc-99 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_17f4dc-99{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_17f4dc-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_17f4dc-99 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_17f4dc-99\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box3943_ae50f0-29 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_ae50f0-29.wp-block-kadence-infobox{max-width:100%;}.kt-info-box3943_ae50f0-29 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box3943_ae50f0-29 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1800px;height:0px;max-width:100%;}.kt-info-box3943_ae50f0-29 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box3943_ae50f0-29 .kt-info-svg-icon-flip, .kt-info-box3943_ae50f0-29 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box3943_ae50f0-29 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box3943_ae50f0-29 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box3943_ae50f0-29\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Environmental-protection-and-wastewater-treatment.webp\" alt=\"Environmental protection and wastewater treatment\" width=\"1800\" height=\"1000\" class=\"kt-info-box-image wp-image-2771\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Environmental-protection-and-wastewater-treatment.webp 1800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Environmental-protection-and-wastewater-treatment-300x167.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Environmental-protection-and-wastewater-treatment-1024x569.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Environmental-protection-and-wastewater-treatment-768x427.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Environmental-protection-and-wastewater-treatment-1536x853.webp 1536w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Industrial Wastewater Treatment<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Handling of high-salinity wastewater and chemical-heavy industrial discharge.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Leading Manufacturer of High-Performance Horizontal Single stage Centrifugal Pumps<\/h2>\n\n\n<style>.kb-row-layout-id3943_97b2ab-66 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_97b2ab-66 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_97b2ab-66 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3943_97b2ab-66 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_97b2ab-66 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3943_97b2ab-66 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_97b2ab-66 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_0df961-29 > .kt-inside-inner-col,.kadence-column3943_0df961-29 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_0df961-29 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_0df961-29 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_0df961-29 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_0df961-29 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_0df961-29{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_0df961-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_0df961-29 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_0df961-29\"><div class=\"kt-inside-inner-col\">\n<p>Founded in 2006, <a href=\"https:\/\/changyupump.com\/about-us\/\" data-type=\"page\" data-id=\"16\">Anhui Changyu Pump and Valve Manufacturing Co., Ltd<\/a> is a premier national high-tech enterprise dedicated to the R&amp;D and precision manufacturing of industrial pumps. With over two decades of deep-rooted expertise, we operate a 20,000 m\u00b2 state-of-the-art facility, delivering more than 20,000 units annually to global markets. We are recognized as a pioneer in the industry, particularly for our breakthroughs in high-pressure multistage pump technology.<\/p>\n\n\n\n<p>Our DF series of corrosion-resistant horizontal multistage centrifugal pumps are our classic bestsellers. Supported by ISO 9001, <a href=\"https:\/\/www.trade.gov\/ce-marking\" data-type=\"link\" data-id=\"https:\/\/www.trade.gov\/ce-marking\" target=\"_blank\" rel=\"noopener\">CE<\/a>, and over 50 independent patents, Changyu Pump provides reliable solutions for the most challenging fluid environments. From seawater desalination to complex brine mining, our mission is to ensure safe, energy-efficient, and leak-free transportation of aggressive media.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_e1358b-a6 > .kt-inside-inner-col,.kadence-column3943_e1358b-a6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_e1358b-a6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_e1358b-a6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_e1358b-a6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_e1358b-a6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_e1358b-a6{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_e1358b-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_e1358b-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_e1358b-a6\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CHANGYU company introduce\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/WEFwgg-Bu8U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Factory Show<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-3943_b61f28-8b{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-3943_b61f28-8b .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-3943_b61f28-8b .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-3943_b61f28-8b .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-3943_b61f28-8b alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-3943_b61f28-8b kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"5\" data-columns-xl=\"5\" data-columns-md=\"5\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-id=\"954\" class=\"wp-image-954\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"529\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-id=\"959\" class=\"wp-image-959\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-300x176.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-768x451.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-id=\"927\" class=\"wp-image-927\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-id=\"921\" class=\"wp-image-921\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-id=\"930\" class=\"wp-image-930\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-id=\"940\" class=\"wp-image-940\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-id=\"945\" class=\"wp-image-945\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-id=\"926\" class=\"wp-image-926\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-id=\"944\" class=\"wp-image-944\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"504\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-id=\"949\" class=\"wp-image-949\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-768x430.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"838\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4.webp\" alt=\"\" class=\"wp-image-1134\" title=\"Centrifugal Chemical Pump Certificate\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4-1024x572.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4-768x429.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"703\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3.webp\" alt=\"Custom Visit\" class=\"wp-image-1135\" style=\"object-fit:cover\" title=\"Custom Visit\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-300x141.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-1024x480.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-768x360.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">FAQs<\/h2>\n\n\n<style>.kb-row-layout-id3943_f1f90a-77 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_f1f90a-77 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_f1f90a-77 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id3943_f1f90a-77 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_f1f90a-77 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id3943_f1f90a-77 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_f1f90a-77 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col,.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_4cbe6e-c5{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_4cbe6e-c5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_4cbe6e-c5\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3943_99884d-23 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id3943_99884d-23 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:9px;padding-right:13px;padding-bottom:9px;padding-left:13px;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id3943_99884d-23 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_99884d-23:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id3943_99884d-23 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}}@media all and (max-width: 1024px){.kt-accordion-id3943_99884d-23 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}@media all and (max-width: 767px){.kt-accordion-id3943_99884d-23 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3943_99884d-23 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id3943_99884d-23 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3943_99884d-23 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id3943_99884d-23 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3943_99884d-23 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3943_99884d-23 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane3943_da2c9e-c3\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q1: What are the primary applications of the DF Series Corrosion Resistant Horizontal Multistage Centrifugal Pump?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q1: What are the primary applications of the DF Series Corrosion Resistant Horizontal Multistage Centrifugal Pump?<\/h3>\n\n\n\n<p><strong>A:<\/strong> The Changyu DF series is specifically designed for high-pressure and highly corrosive environments. It is ideal for sea water desalination (RO feed pumps), <strong>brine mining<\/strong>, salt chemical processing, and acidic wastewater treatment in mining and metallurgy.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane3943_f8f1a4-15\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q3: What materials are available for handling high-salinity brine or corrosive fluids?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q3: What materials are available for handling high-salinity brine or corrosive fluids?<\/h3>\n\n\n\n<p><strong>A:<\/strong> To prevent pitting and chloride-induced stress corrosion, the Changyu DF series offers precision-cast components in SS316L, Duplex Stainless Steel (2205\/2507), and high-chromium alloys. We customize the material configuration based on your specific media concentration.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane3943_06ef12-3f\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q5: How does Changyu Pump improve the overall efficiency of the DF series?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q5: How does Changyu Pump improve the overall efficiency of the DF series?<\/h3>\n\n\n\n<p><strong>A:<\/strong> By utilizing state-recommended hydraulic models and differential hardness friction pairs between the rotor and stator, we reduce internal friction and leakage, boosting the pump&#8217;s overall efficiency by more than 3%.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_0341db-a8 > .kt-inside-inner-col,.kadence-column3943_0341db-a8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_0341db-a8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_0341db-a8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_0341db-a8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_0341db-a8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_0341db-a8{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_0341db-a8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_0341db-a8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_0341db-a8\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id3943_a2c238-b7 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id3943_a2c238-b7 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:9px;padding-right:13px;padding-bottom:9px;padding-left:13px;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id3943_a2c238-b7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id3943_a2c238-b7:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id3943_a2c238-b7 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}}@media all and (max-width: 1024px){.kt-accordion-id3943_a2c238-b7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}@media all and (max-width: 767px){.kt-accordion-id3943_a2c238-b7 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id3943_a2c238-b7 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id3943_a2c238-b7 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id3943_a2c238-b7 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id3943_a2c238-b7 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id3943_a2c238-b7 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id3943_a2c238-b7 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane3943_92348d-43\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q2: How does the &#8220;Four-stage Axial Force Balancing System&#8221; benefit my operation?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q2: How does the &#8220;Four-stage Axial Force Balancing System&#8221; benefit my operation?<\/h3>\n\n\n\n<p><strong>A:<\/strong> Unlike traditional pumps, our innovative four-stage system (balancing drum + pressure ring + throttle plate + positioning) neutralizes 100% of axial thrust. This significantly reduces bearing load, enhances stability during frequency conversion, and delivers over 15% energy savings throughout the pump&#8217;s lifecycle.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane3943_3dd854-51\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q4: What is the maximum performance range (Flow and Head) of the DF series?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q4: What is the maximum performance range (Flow and Head) of the DF series?<\/h3>\n\n\n\n<p><strong>A:<\/strong> Based on our technical specifications, the DF series covers a flow rate of 3.75 to 850 m\u00b3\/h and a head range of 19 to 816 meters, with power options up to 1600 kW.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane3943_9db0f0-0a\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q6: Is the DF series compatible with existing industrial piping systems?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q6: Is the DF series compatible with existing industrial piping systems?<\/h3>\n\n\n\n<p><strong>A:<\/strong> Yes. The DF series corrosion resistant horizontal multistage centrifugal pump uses a modular design with dimensions compatible with traditional multistage pump standards, making it easy to upgrade your existing system with minimal downtime.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3943_4505ad-f4 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_4505ad-f4 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_4505ad-f4 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3943_4505ad-f4 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_4505ad-f4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_4505ad-f4 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_4505ad-f4 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3943_513bf0-cb > .kt-inside-inner-col,.kadence-column3943_513bf0-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_513bf0-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_513bf0-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_513bf0-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_513bf0-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_513bf0-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_513bf0-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_513bf0-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_513bf0-cb\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Project Showcases<\/h2>\n\n\n\n<p class=\"has-text-align-center\">From large-scale seawater desalination plants to complex brine mining and salt chemical processing, our extensive library of real-world applications demonstrates the exceptional reliability, efficiency, and long-term durability of the Changyu DF series. Our fluid solutions are engineered to thrive in diverse and high-pressure environments where standard pumps fail.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_d7a22e-63 > .kt-inside-inner-col,.kadence-column3943_d7a22e-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_d7a22e-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_d7a22e-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_d7a22e-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_d7a22e-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_d7a22e-63{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_d7a22e-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_d7a22e-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_d7a22e-63\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop3943_c43b6e-a9 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop3943_c43b6e-a9 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop3943_c43b6e-a9 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop3943_c43b6e-a9 .entry-content:after{height:0px;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop3943_c43b6e-a9 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop3943_c43b6e-a9 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3943_c43b6e-a9.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop3943_c43b6e-a9 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-3648 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/project\/corrosion-resistant-centrifugal-pump-alumina-solution-project-australia\/\" aria-label=\"Corrosion Resistant Centrifugal Pump Project for Alumina Solution Transfer in Australia\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"corrosion resistant centrifugal pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/project\/corrosion-resistant-centrifugal-pump-alumina-solution-project-australia\/\">Corrosion Resistant Centrifugal Pump Project for Alumina Solution Transfer in Australia<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3357 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/project\/industrial-process-pump-pac-production-india\/\" aria-label=\"Industrial Process Pump Application for PAC Production in India Case\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"397\" height=\"280\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Industrial process pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1.webp 397w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1-300x212.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1-150x106.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1-18x12.webp 18w\" sizes=\"auto, (max-width: 397px) 100vw, 397px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/project\/industrial-process-pump-pac-production-india\/\">Industrial Process Pump Application for PAC Production in India Case<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3297 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/project\/vietnam-zinc-sulfate-slurry-pump\/\" aria-label=\"Vietnam Zinc Smelter Wet Zinc Sulfate Slurry Pumping Case\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-1024x769.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"zinc sulfate slurry pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-1024x769.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2.webp 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/project\/vietnam-zinc-sulfate-slurry-pump\/\">Vietnam Zinc Smelter Wet Zinc Sulfate Slurry Pumping Case<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3205 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/project\/uhb-slurry-pump-for-sulfuric-acid\/\" aria-label=\"UHB Slurry Pump for Sulfuric Acid in Salt Crystal Separation\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"slurry pump for sulfuric acid\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/project\/uhb-slurry-pump-for-sulfuric-acid\/\">UHB Slurry Pump for Sulfuric Acid in Salt Crystal Separation<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-2841 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/project\/slurry-pump-case-for-sulfuric-acid-waste-gas-scrubber\/\" aria-label=\"Application Case of Slurry Pump for Scrubber in Sulfuric Acid Production Waste Gas Treatment\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"596\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-1024x596.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Case of Slurry Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-1024x596.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-300x175.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-150x87.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-768x447.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/project\/slurry-pump-case-for-sulfuric-acid-waste-gas-scrubber\/\">Application Case of Slurry Pump for Scrubber in Sulfuric Acid Production Waste Gas Treatment<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-878 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/project\/stainless-steel-magnetic-pump-brazil\/\" aria-label=\"Customized Stainless Steel Insulated Magnetic Pump for a Petrochemical Plant in Brazil\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-1024x683.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Custom Stainless Steel Insulated Magnetic Pump for Brazilian Client\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-1024x683.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-768x512.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-1536x1024.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-2048x1366.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/project\/stainless-steel-magnetic-pump-brazil\/\">Customized Stainless Steel Insulated Magnetic Pump for a Petrochemical Plant in Brazil<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id3943_246eec-bb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id3943_246eec-bb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id3943_246eec-bb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id3943_246eec-bb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id3943_246eec-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id3943_246eec-bb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id3943_246eec-bb alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col,.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_f7f4cd-92{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_f7f4cd-92 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_f7f4cd-92\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Blogs<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column3943_d8bf85-cf > .kt-inside-inner-col,.kadence-column3943_d8bf85-cf > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column3943_d8bf85-cf > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column3943_d8bf85-cf > .kt-inside-inner-col{flex-direction:column;}.kadence-column3943_d8bf85-cf > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column3943_d8bf85-cf > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column3943_d8bf85-cf{position:relative;}@media all and (max-width: 1024px){.kadence-column3943_d8bf85-cf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column3943_d8bf85-cf > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column3943_d8bf85-cf\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop3943_5a21c6-48 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop3943_5a21c6-48 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop3943_5a21c6-48 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop3943_5a21c6-48 .entry-content:after{height:0px;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop3943_5a21c6-48 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop3943_5a21c6-48 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop3943_5a21c6-48.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop3943_5a21c6-48 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-3804 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-centrifugal-slurry-pump tag-horizontal-centrifugal-pump tag-horizontal-slurry-pumps\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/ultimate-guide-to-horizontal-slurry-pumps-industrial-chemical-solutions\/\" aria-label=\"Ultimate Guide to Horizontal Slurry Pumps: Industrial &amp; Chemical Solutions\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/factory-3-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Horizontal slurry pumps factory\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/factory-3-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/factory-3-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/factory-3-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/factory-3-1536x864.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/factory-3.webp 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/ultimate-guide-to-horizontal-slurry-pumps-industrial-chemical-solutions\/\">Ultimate Guide to Horizontal Slurry Pumps: Industrial &amp; Chemical Solutions<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Etiquetas<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/es\/tag\/centrifugal-slurry-pump\/\" rel=\"tag\">centrifugal slurry pump<\/a>, <a href=\"https:\/\/changyupump.com\/es\/tag\/horizontal-centrifugal-pump\/\" rel=\"tag\">horizontal centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/es\/tag\/horizontal-slurry-pumps\/\" rel=\"tag\">Horizontal Slurry Pumps<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-814 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/horizontal-vs-vertical-centrifugal-pumps-and-how-to-choose\/\" aria-label=\"Horizontal Centrifugal Pumps vs Vertical Centrifugal Pumps and How to Choose\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-vs-Vertical-Centrifugal-Pumps-and-How-to-Choose-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Horizontal Centrifugal Pumps vs Vertical Centrifugal Pumps\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-vs-Vertical-Centrifugal-Pumps-and-How-to-Choose-1.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-vs-Vertical-Centrifugal-Pumps-and-How-to-Choose-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-vs-Vertical-Centrifugal-Pumps-and-How-to-Choose-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/horizontal-vs-vertical-centrifugal-pumps-and-how-to-choose\/\">Horizontal Centrifugal Pumps vs Vertical Centrifugal Pumps and How to Choose<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-822 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/how-does-a-horizontal-centrifugal-pump-work\/\" aria-label=\"How Does a Horizontal Centrifugal Pump Work\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYL-Type-Vertical-Inline-Centrifugal-Pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"CYL Type Vertical Inline Centrifugal Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYL-Type-Vertical-Inline-Centrifugal-Pump.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYL-Type-Vertical-Inline-Centrifugal-Pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYL-Type-Vertical-Inline-Centrifugal-Pump-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/how-does-a-horizontal-centrifugal-pump-work\/\">How Does a Horizontal Centrifugal Pump Work<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3786 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/self-priming-chemical-pump-vs-centrifugal-pump\/\" aria-label=\"Self Priming Chemical Pump vs Chemical Centrifugal Pump Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Self-priming-pumps.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Self Priming Chemical Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Self-priming-pumps.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Self-priming-pumps-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Self-priming-pumps-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Self-priming-pumps-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Self-priming-pumps-16x12.webp 16w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/self-priming-chemical-pump-vs-centrifugal-pump\/\">Self Priming Chemical Pump vs Chemical Centrifugal Pump Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-808 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/the-centrifugal-pump-parts-and-working\/\" aria-label=\"Understand The Centrifugal Pump Parts And Working\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"724\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Understand-The-Centrifugal-Pump-Parts-And-Working.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Understand-The-Centrifugal-Pump-Parts-And-Working.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Understand-The-Centrifugal-Pump-Parts-And-Working-300x212.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Understand-The-Centrifugal-Pump-Parts-And-Working-768x543.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/the-centrifugal-pump-parts-and-working\/\">Understand The Centrifugal Pump Parts And Working<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3682 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/how-cavitation-occurs-in-centrifugal-pump\/\" aria-label=\"How Cavitation Occurs in Centrifugal Pump\uff1f\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"how cavitation occurs in centrifugal pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-1536x1152.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/how-cavitation-occurs-in-centrifugal-pump.webp 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/how-cavitation-occurs-in-centrifugal-pump\/\">How Cavitation Occurs in Centrifugal Pump\uff1f<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3670 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/is-a-centrifugal-pump-a-positive-displacement-pump\/\" aria-label=\"Is a Centrifugal Pump a Positive Displacement Pump?\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Is a Centrifugal Pump a Positive Displacement Pump 1\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Is-a-Centrifugal-Pump-a-Positive-Displacement-Pump-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/is-a-centrifugal-pump-a-positive-displacement-pump\/\">Is a Centrifugal Pump a Positive Displacement Pump?<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3658 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/how-to-prime-a-centrifugal-pump\/\" aria-label=\"How to Prime a Centrifugal Pump\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"How to Prime a Centrifugal Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/How-to-Prime-a-Centrifugal-Pump.webp 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/how-to-prime-a-centrifugal-pump\/\">How to Prime a Centrifugal Pump<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-810 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/magnetic-drive-pump-vs-centrifugal-pump\/\" aria-label=\"What is The Difference Between Magnetic Drive Pump And Centrifugal Pump\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/What-Is-The-Difference-Between-Magnetic-Drive-Pump-Vs-Centrifugal-Pump-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"What Is The Difference Between Magnetic Drive Pump Vs Centrifugal Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/What-Is-The-Difference-Between-Magnetic-Drive-Pump-Vs-Centrifugal-Pump-1.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/What-Is-The-Difference-Between-Magnetic-Drive-Pump-Vs-Centrifugal-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/What-Is-The-Difference-Between-Magnetic-Drive-Pump-Vs-Centrifugal-Pump-1-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/magnetic-drive-pump-vs-centrifugal-pump\/\">What is The Difference Between Magnetic Drive Pump And Centrifugal Pump<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-820 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/how-to-calculate-centrifugal-pump-efficiency\/\" aria-label=\"How to Calculate Centrifugal Pump Efficiency\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"410\" height=\"287\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/How-to-Calculate-Centrifugal-Pump-Efficiency-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"How to Calculate Centrifugal Pump Efficiency\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/How-to-Calculate-Centrifugal-Pump-Efficiency-1.webp 410w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/How-to-Calculate-Centrifugal-Pump-Efficiency-1-300x210.webp 300w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/how-to-calculate-centrifugal-pump-efficiency\/\">How to Calculate Centrifugal Pump Efficiency<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3151 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/es\/blog\/industrial-centrifugal-pump-power-and-head\/\" aria-label=\"What Are Rated Power, Shaft Power, Suction Head and Discharge Head of Industrial Centrifugal Pumps?\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"industrial centrifugal pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/industrial-centrifugal-pump-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/es\/blog\/industrial-centrifugal-pump-power-and-head\/\">What Are Rated Power, Shaft Power, Suction Head and Discharge Head of Industrial Centrifugal Pumps?<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/es\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/es\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-1114] --><style>.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id1114_136e69-11 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1114_136e69-11 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{display:flex;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col,.kadence-column1114_03d1b0-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_03d1b0-0d{text-align:left;}.kadence-column1114_03d1b0-0d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_03d1b0-0d kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading1114_6c6840-24 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1114_6c6840-24\">Request a free quote<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1114_7bff25-4d wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1114_7bff25-4d\">Please fill in the details of your pumped liquid, including flow, head, specific gravity, and temperature, so we can recommend the best pump and provide a precise quote.<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1114_923d6b-76 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1114_3d05c4-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_3d05c4-55\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Customized Pump Solutions<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_a819a4-1b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_a819a4-1b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_users kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M17 21v-2a4 4 0 0 0-4-4H5a4 4 0 0 0-4 4v2\"\/><circle cx=\"9\" cy=\"7\" r=\"4\"\/><path d=\"M23 21v-2a4 4 0 0 0-3-3.87\"\/><path d=\"M16 3.13a4 4 0 0 1 0 7.75\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fast Quotation within 24 hours<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_05ee61-11 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_05ee61-11\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_feather kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20.24 12.24a6 6 0 0 0-8.49-8.49L5 10.5V19h8.5z\"\/><line x1=\"16\" y1=\"8\" x2=\"2\" y2=\"22\"\/><line x1=\"17\" y1=\"15\" x2=\"9\" y2=\"15\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Factory Direct with Competitive Price<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_5f1d2f-38 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_5f1d2f-38\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_settings kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"3\"\/><path d=\"M19.4 15a1.65 1.65 0 0 0 .33 1.82l.06.06a2 2 0 0 1 0 2.83 2 2 0 0 1-2.83 0l-.06-.06a1.65 1.65 0 0 0-1.82-.33 1.65 1.65 0 0 0-1 1.51V21a2 2 0 0 1-2 2 2 2 0 0 1-2-2v-.09A1.65 1.65 0 0 0 9 19.4a1.65 1.65 0 0 0-1.82.33l-.06.06a2 2 0 0 1-2.83 0 2 2 0 0 1 0-2.83l.06-.06a1.65 1.65 0 0 0 .33-1.82 1.65 1.65 0 0 0-1.51-1H3a2 2 0 0 1-2-2 2 2 0 0 1 2-2h.09A1.65 1.65 0 0 0 4.6 9a1.65 1.65 0 0 0-.33-1.82l-.06-.06a2 2 0 0 1 0-2.83 2 2 0 0 1 2.83 0l.06.06a1.65 1.65 0 0 0 1.82.33H9a1.65 1.65 0 0 0 1-1.51V3a2 2 0 0 1 2-2 2 2 0 0 1 2 2v.09a1.65 1.65 0 0 0 1 1.51 1.65 1.65 0 0 0 1.82-.33l.06-.06a2 2 0 0 1 2.83 0 2 2 0 0 1 0 2.83l-.06.06a1.65 1.65 0 0 0-.33 1.82V9a1.65 1.65 0 0 0 1.51 1H21a2 2 0 0 1 2 2 2 2 0 0 1-2 2h-.09a1.65 1.65 0 0 0-1.51 1z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Professional engineers, one-on-one technical consultation<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_a211a7-13 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_a211a7-13\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_award kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"8\" r=\"7\"\/><polyline points=\"8.21 13.89 7 23 12 20 17 23 15.79 13.88\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">CE\/ISO certified pumps with strict testing before shipment<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.kadence-column1114_77e08c-18 > .kt-inside-inner-col{display:flex;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col,.kadence-column1114_77e08c-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_77e08c-18{position:relative;}.kadence-column1114_77e08c-18, .kt-inside-inner-col > .kadence-column1114_77e08c-18:not(.specificity){margin-top:var(--global-kb-spacing-lg, 3rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);}@media all and (max-width: 1024px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_77e08c-18 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading1114_b234f2-d2 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1114_b234f2-d2\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons1114_296db3-9a .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons1114_296db3-9a{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons1114_296db3-9a{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons1114_296db3-9a alignnone\"><style>.kt-svg-item-1114_b484c3-db .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_b484c3-db .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:20px;}.kt-svg-item-1114_b484c3-db:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_b484c3-db\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=61564021046258\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_3f5c48-35 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_3f5c48-35 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_3f5c48-35\"><a href=\"https:\/\/www.linkedin.com\/company\/anhui-changyu-pump-valve-co-ltd\/?viewAsMember=true\" class=\"kt-svg-icon-link\" aria-label=\"Linkedin\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_linkedin\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_7e9ec1-58 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_7e9ec1-58 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:17px;}.kt-svg-item-1114_7e9ec1-58:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_7e9ec1-58\"><a href=\"https:\/\/www.instagram.com\/changyupump\/\" class=\"kt-svg-icon-link\" aria-label=\"Ins\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_instagram\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"2\" y=\"2\" width=\"20\" height=\"20\" rx=\"5\" ry=\"5\"\/><path d=\"M16 11.37A4 4 0 1 1 12.63 8 4 4 0 0 1 16 11.37z\"\/><line x1=\"17.5\" y1=\"6.5\" x2=\"17.5\" y2=\"6.5\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_177ba8-54 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_177ba8-54 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}.kt-svg-item-1114_177ba8-54:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_177ba8-54\"><a href=\"https:\/\/www.youtube.com\/@Changyu-CY\" class=\"kt-svg-icon-link\" aria-label=\"Youtube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col,.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{column-gap:0px;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_ac3a5c-85{text-align:left;}.kadence-column1114_ac3a5c-85{position:relative;}@media all and (max-width: 1024px){.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_ac3a5c-85 kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;background:var(--global-palette2, #2B6CB0);}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit:hover, .kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit:focus {background:#019141;}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-1114_7d9556-ee kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_1114_7d9556-ee_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_1114_7d9556-ee_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Address\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_1114_7d9556-ee_2\" data-label=\"Phone\/WA\" type=\"text\" placeholder=\"Phone\/WA\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_3\" id=\"kb_field_1114_7d9556-ee_3\" data-label=\"Country\" type=\"text\" placeholder=\"Country\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-3\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-4 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_4\" id=\"kb_field_1114_7d9556-ee_4\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-4\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"1114_7d9556-ee\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"1114\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\"><strong>Send Your Inquiry Now<\/strong><\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-1114_7d9556-ee .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-1114] -->\n","protected":false},"excerpt":{"rendered":"<p>La bomba centr\u00edfuga multietapa horizontal resistente a la corrosi\u00f3n de la serie DF de Changyu Pump ofrece un ahorro energ\u00e9tico de 151 TP3T y una altura manom\u00e9trica de 816 m para la desalinizaci\u00f3n y la extracci\u00f3n de salmuera, fabricada en acero inoxidable 316L\/duplex de gran durabilidad.<\/p>","protected":false},"featured_media":3955,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"show","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"class_list":["post-3943","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Horizontal-Multistage-Centrifugal-Pump-1-1024x768.jpg",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/changyupump.com\/es\/wp-json\/wp\/v2\/product\/3943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/changyupump.com\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/changyupump.com\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/changyupump.com\/es\/wp-json\/wp\/v2\/media\/3955"}],"wp:attachment":[{"href":"https:\/\/changyupump.com\/es\/wp-json\/wp\/v2\/media?parent=3943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}