{"id":1133,"date":"2026-04-15T14:47:02","date_gmt":"2026-04-15T14:47:02","guid":{"rendered":"https:\/\/changyupump.com\/?post_type=product&#038;p=1133"},"modified":"2026-04-24T03:07:48","modified_gmt":"2026-04-24T03:07:48","slug":"cyw-horizontal-centrifugal-water-pump","status":"publish","type":"product","link":"https:\/\/changyupump.com\/fr\/product\/cyw-horizontal-centrifugal-water-pump\/","title":{"rendered":"Pompe \u00e0 eau centrifuge horizontale | S\u00e9rie CYW"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1133_82de94-96{margin-top:-20px;}.kb-row-layout-id1133_82de94-96 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_82de94-96 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_82de94-96 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1133_82de94-96 > .kt-row-layout-overlay{opacity:0.95;background-color:#f0f2f4;}@media all and (max-width: 1024px){.kb-row-layout-id1133_82de94-96 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1133_82de94-96 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_82de94-96 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_f04892-f5 > .kt-inside-inner-col,.kadence-column1133_f04892-f5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_f04892-f5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_f04892-f5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_f04892-f5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_f04892-f5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_f04892-f5{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_f04892-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_f04892-f5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_f04892-f5\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-type-thumbslider.kb-gallery-id-1133_49b8e4-40 .kt-blocks-carousel-init {margin-bottom:10px;}.kb-gallery-id-1133_49b8e4-40 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1133_49b8e4-40 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1133_49b8e4-40 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-thumbslider kb-gallery-id-1133_49b8e4-40 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div id=\"kb-slider-1133_49b8e4-40\" class=\"kt-blocks-carousel-init splide kb-blocks-slider kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"4\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-thumb-slider-1133_49b8e4-40\"  data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp\" data-id=\"4468\" class=\"wp-image-4468 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp\" data-id=\"4470\" class=\"wp-image-4470 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump CYW Series\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp\" data-id=\"4467\" class=\"wp-image-4467 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp\" data-id=\"4469\" class=\"wp-image-4469 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><div id=\"kb-thumb-slider-1133_49b8e4-40\" class=\"kb-blocks-slider splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-speed=\"7000\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-slider-1133_49b8e4-40\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump \" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp\" data-id=\"4468\" class=\"wp-image-4468 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump \" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp\" data-id=\"4470\" class=\"wp-image-4470 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-3-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump CYW Series\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp\" data-id=\"4467\" class=\"wp-image-4467 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-2-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp\" width=\"1024\" height=\"768\" alt=\"Horizontal Centrifugal Water Pump \" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp\" data-id=\"4469\" class=\"wp-image-4469 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-2-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column1133_8963c5-9c > .kt-inside-inner-col,.kadence-column1133_8963c5-9c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_8963c5-9c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_8963c5-9c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_8963c5-9c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_8963c5-9c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_8963c5-9c{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_8963c5-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_8963c5-9c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_8963c5-9c\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading has-large-font-size\">Horizontal Centrifugal Water Pump | CYW Series<\/h1>\n\n\n\n<p style=\"font-size:18px\">The <strong><a href=\"https:\/\/changyupump.com\/about-us\/\" data-type=\"page\" data-id=\"16\">ChangyuPump<\/a> CYW Series Horizontal Centrifugal Water Pump<\/strong> is a high-efficiency, single-stage, single-suction pump designed in compliance with <strong><a href=\"https:\/\/www.iso.org\/standard\/7862.html?utm_source=chatgpt.com\" data-type=\"link\" data-id=\"https:\/\/www.iso.org\/standard\/7862.html?utm_source=chatgpt.com\" target=\"_blank\" rel=\"noopener\">ISO 2858<\/a><\/strong> and <strong>JB\/T53058-93<\/strong> standards.<\/p>\n\n\n\n<p style=\"font-size:18px\">Engineered with optimized hydraulic models and a compact structure, this pump delivers <strong>stable performance, low energy consumption, and long service life<\/strong>, making it ideal for industrial, municipal, and HVAC systems.<\/p>\n\n\n<style>.kb-table-container1133_b87b37-76{overflow-x:auto;}.kb-table1133_b87b37-76 td:nth-of-type(1), .kb-table1133_b87b37-76 th:nth-of-type(1){width:30%;}.kb-table1133_b87b37-76{table-layout:fixed;width:100%;}.kb-table-container .kb-table1133_b87b37-76 th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table1133_b87b37-76 caption{text-align:center;}.kb-table-container .kb-table1133_b87b37-76 td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}.kb-table-container .kb-table1133_b87b37-76 tr:nth-of-type(odd){background-color:rgba(225,225,225,0.8);}.kb-table-container .kb-table1133_b87b37-76 td, .kb-table1133_b87b37-76 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-table-container .kb-table1133_b87b37-76 td, .kb-table1133_b87b37-76 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-table-container .kb-table1133_b87b37-76 td, .kb-table1133_b87b37-76 th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-table-container kb-table-container1133_b87b37-76 wp-block-kadence-table\"><table class=\"kb-table kb-table1133_b87b37-76\">\n<tr class=\"kb-table-row kb-table-row1133_775a65-a3\">\n<th class=\"kb-table-data kb-table-data1133_196570-0c\">\n\n<p class=\"has-text-align-left\">Flow Rate Range :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1133_2cfa30-35\">\n\n<p>4.5m\u00b3\/h~1660m\u00b3\/h<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1133_cf1595-7c\">\n<th class=\"kb-table-data kb-table-data1133_019ac1-f7\">\n\n<p class=\"has-text-align-left\">Head Range: <\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1133_3f7e9b-c3\">\n\n<p>5.2m~150m<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1133_612827-87\">\n<th class=\"kb-table-data kb-table-data1133_8813fd-30\">\n\n<p class=\"has-text-align-left\">Motor Power :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1133_f8582e-c7\">\n\n<p>0.75 kw~160 kw<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1133_32f1ec-dc\">\n<th class=\"kb-table-data kb-table-data1133_f11a3d-96\">\n\n<p class=\"has-text-align-left\">Speed:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1133_9bdd9b-50\">\n\n<p class=\"has-text-align-left\">1450~2900r\/min<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1133_cf07cf-03\">\n<th class=\"kb-table-data kb-table-data1133_03857b-32\">\n\n<p class=\"has-text-align-left\">Medium Temperature Range:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1133_4f7cd4-9f\">\n\n<p>-10\u2103~85\u2103<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1133_e81646-44\">\n<th class=\"kb-table-data kb-table-data1133_b10f12-92\">\n\n<p class=\"has-text-align-left\">Customizable Materials:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1133_328726-1f\">\n\n<p>HT250, QT450-12, Bronze C95200 or SS304, SS316, HT250, QT450-12, Bronze C95200 or SS304, SS316<\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n<!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Veuillez activer JavaScript dans votre navigateur pour envoyer le formulaire.<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Introduction<\/h2>\n\n\n\n<p>The ChangyuPump horizontal centrifugal water pump is built based on ISO 2858 dimensional standards and JB\/T53058-93 pipeline pump specifications, ensuring full compatibility with international piping systems and easy equipment replacement. Its back pull-out structure allows maintenance without dismantling pipelines, significantly reducing downtime in continuous operation environments such as factories and municipal systems. The three-direction outlet configuration further improves installation flexibility in space-limited projects.<\/p>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-1133_de616a-45{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1133_de616a-45{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1133_de616a-45 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1133_de616a-45 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1133_de616a-45 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1133_de616a-45 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1133_de616a-45 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1-1024x576.webp\" width=\"1024\" height=\"576\" alt=\"Horizontal Centrifugal Water Pump CYW Series\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1.webp\" data-id=\"4466\" class=\"wp-image-4466\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-1024x576.webp\" width=\"1024\" height=\"576\" alt=\"Centrifugal Water Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1.webp\" data-id=\"4464\" class=\"wp-image-4464\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2-1024x576.webp\" width=\"1024\" height=\"576\" alt=\"Centrifugal Water Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2.webp\" data-id=\"4465\" class=\"wp-image-4465\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<p>This horizontal centrifugal pump is engineered for clearly defined fluid conditions, including clean water, \u2264120\u00b0C hot water systems, and non-solid corrosive media. It is widely deployed in HVAC circulation loops, industrial cooling systems, building pressure boosting, and long-distance water transfer. With standardized design and application-specific variants, it serves as a practical and reliable solution for engineers requiring stable performance under controlled operating parameters.<\/p>\n\n\n<style>.kb-row-layout-id1133_e71391-6f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_e71391-6f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_e71391-6f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_e71391-6f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_e71391-6f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_e71391-6f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_e71391-6f alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_995d0b-ef > .kt-inside-inner-col,.kadence-column1133_995d0b-ef > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_995d0b-ef > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_995d0b-ef > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_995d0b-ef > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_995d0b-ef > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_995d0b-ef{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_995d0b-ef > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_995d0b-ef > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_995d0b-ef\"><div class=\"kt-inside-inner-col\"><style>.kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list{margin-right:-10px;}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list li .kt-tab-title{margin-right:10px;}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #eeeeee);}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #EDF2F7);}.wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:#ffffff;background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}@media all and (max-width: 767px){.kt-tabs-id1133_ecd818-06 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id1133_ecd818-06 kt-tabs-has-2-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list kb-tabs-list-columns kb-tab-title-columns-6\"><li id=\"tab-strongpartsstrong\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-strongpartsstrong\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\"><strong>Parts<\/strong><\/span><\/a><\/li><li id=\"tab-strongspecificationsstrong\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-strongspecificationsstrong\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\"><strong>Specifications<\/strong><\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab1133_19ffa0-76\"><div class=\"kt-tab-inner-content-inner\">\n<h2 class=\"wp-block-heading\">Components and Functions of Horizontal Centrifugal Water Pump<\/h2>\n\n\n\n<p>Horizontal centrifugal water pump parts primarily include the impeller, casing, shaft, bearings, and sealing assembly. Please see the following diagram of the Horizontal Centrifugal Water Pump for details:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Outlet Configuration (Multi-Directional)<\/strong><br>The discharge outlet can be installed in left, right, or upward directions, providing flexible installation options for different pipeline layouts.<\/li>\n\n\n\n<li><strong>Impeller (Closed-Type Design)<\/strong><br>The impeller is the core hydraulic component, responsible for generating centrifugal force to achieve the required flow rate and head. Precision dynamic balancing ensures stable operation and reduces vibration.<\/li>\n\n\n\n<li><strong>Pump Casing (Volute Type)<\/strong><br>Designed according to ISO 2858 standards, the casing converts fluid velocity into pressure while providing strong structural support under system pressure up to 1.6 MPa.<\/li>\n\n\n\n<li><strong>Pump Shaft<\/strong><br>High-precision machined shaft ensures excellent concentricity, minimizing mechanical loss and maintaining stable transmission between motor and impeller.<\/li>\n\n\n\n<li><strong>Mechanical Seal System<\/strong><br>Equipped with hard alloy mechanical seals (optional silicon carbide or titanium alloy), enabling leak-free operation under temperatures up to 120\u00b0C and various liquid conditions.<\/li>\n\n\n\n<li><strong>Bearings (Heavy-Duty Support)<\/strong><br>High-quality bearings reduce friction and support continuous operation, ensuring low noise (&lt;40 dB) and extended service life.<\/li>\n\n\n\n<li><strong>Motor (B35 Standard Direct-Coupled Motor)<\/strong><br>The pump adopts a direct-coupled motor structure, eliminating the need for alignment adjustment after installation and improving overall transmission efficiency.<\/li>\n\n\n\n<li><strong>Base Frame<\/strong><br>Integrated base ensures structural stability, reduces vibration transmission, and simplifies installation in industrial and municipal systems.<\/li>\n\n\n\n<li><strong>Outlet Configuration (Multi-Directional)<\/strong><br>The discharge outlet can be installed in left, right, or upward directions, providing flexible installation options for different pipeline layouts.<\/li>\n<\/ul>\n\n\n<style>.kb-image1133_adc8b1-a9 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1133_adc8b1-a9\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"382\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-Diagram.webp\" alt=\"\" class=\"kb-img wp-image-1145\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-Diagram.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-Diagram-300x112.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-Diagram-768x287.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Working Principle<\/strong><\/h2>\n\n\n\n<p><a href=\"https:\/\/changyupump.com\/centrifugal-pump-for-sale\/\" data-type=\"link\" data-id=\"https:\/\/changyupump.com\/centrifugal-pump-for-sale\/\">Centrifugal pumps<\/a> function by transforming mechanical rotation into fluid pressure and flow. As the impeller spins rapidly within its casing, it creates centrifugal force that accelerates the water radially outward. This high-velocity flow is then directed through a gradually expanding volute casing, where its speed is converted into stable pressure, efficiently discharging the liquid through the outlet pipeline.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Motor Drive (Mechanical Energy Input)<\/strong><br>The B35 standard motor provides direct rotational power to the pump shaft, eliminating coupling misalignment and ensuring stable energy transmission under continuous operation conditions. <\/li>\n\n\n\n<li><strong>Impeller Rotation (Centrifugal Force Generation)<\/strong><br>As the impeller rotates at high speed, it accelerates the liquid outward from the center, creating centrifugal force that continuously draws fluid into the pump inlet. <\/li>\n\n\n\n<li><strong>Energy Conversion (Velocity to Pressure)<\/strong><br>The high-velocity liquid is guided into the volute pump casing, where kinetic energy is gradually converted into static pressure, ensuring stable and controlled flow output. <\/li>\n\n\n\n<li><strong>Flow Direction Control (Continuous Discharge)<\/strong><br>The pressurized liquid is smoothly discharged through the outlet pipeline, maintaining steady flow for systems such as water supply, HVAC circulation, and industrial transfer applications. <\/li>\n\n\n\n<li><strong>System Stability (Low Vibration Operation)<\/strong><br>Precision-balanced impeller design and high concentricity shaft structure ensure smooth hydraulic operation, reducing vibration and noise during long-term continuous working cycles.<\/li>\n<\/ul>\n\n\n<style>.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap .kt-video-svg-icon{color:#ffffff;}.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap .kt-video-svg-icon > svg{stroke-width:2;}.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap .kadence-video-overlay{opacity:0.3;;mix-blend-mode:none;;background:#000000;;}.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap:hover .kadence-video-overlay{opacity:0.5;;}.glightbox-kadence-dark.kadence-popup-1133_099876-28 .goverlay{background:#000000;opacity:0.8;}.glightbox-container.kadence-popup-1133_099876-28 .gclose path, .glightbox-container.kadence-popup-1133_099876-28 .gnext path, .glightbox-container.kadence-popup-1133_099876-28 .gprev path{fill:#ffffff;}.glightbox-container.kadence-popup-1133_099876-28 .gslide-video, .glightbox-container.kadence-popup-1133_099876-28 .gvideo-local{max-width:900px !important;}@media all and (max-width: 1024px){.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}@media all and (max-width: 767px){.kadence-video-popup1133_099876-28 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-videopopup kadence-video-popup1133_099876-28\"><div class=\"kadence-video-popup-wrap kadence-video-noshadow\"><div class=\"kadence-video-intrinsic \"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-.webp\" alt=\"Horizontal Centrifugal Water Pump CYW Series\" width=\"1200\" height=\"673\" class=\"kadence-video-poster wp-image-4472\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series-.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series--300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series--1024x574.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series--150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series--768x431.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-CYW-Series--18x10.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><div class=\"kadence-video-overlay\"><\/div><a class=\"kadence-video-popup-link kadence-video-type-external\" href=\"https:\/\/www.youtube.com\/watch?v=zSOLC1yjOEs\" role=\"button\" data-popup-class=\"kadence-popup-1133_099876-28\" data-effect=\"none\" data-popup-id=\"kadence-local-video-1133_099876-28\" data-popup-auto=\"true\" data-youtube-cookies=\"true\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_play kt-video-svg-icon kt-video-svg-icon-style-default kt-video-svg-icon-fas play kt-video-play-animation-none kt-video-svg-icon-size-auto\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Play<\/title><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"\/><\/svg><\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab1133_b4b557-28\"><div class=\"kt-tab-inner-content-inner\">\n<h2 class=\"wp-block-heading\"><strong>CYW Horizontal Centrifugal Water Pump Specifications<\/strong><\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Item<\/th><th class=\"has-text-align-center\" data-align=\"center\">Specification<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Pump Type<\/td><td class=\"has-text-align-center\" data-align=\"center\">Single-stage, single-suction horizontal centrifugal pump<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Design Standard<\/td><td class=\"has-text-align-center\" data-align=\"center\">ISO 2858 \/ JB\/T53058-93<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Flow Range<\/td><td class=\"has-text-align-center\" data-align=\"center\">1.5 \u2013 1660 m\u00b3\/h<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Head Range<\/td><td class=\"has-text-align-center\" data-align=\"center\">5.2 \u2013 160 m<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Power Range<\/td><td class=\"has-text-align-center\" data-align=\"center\">0.75 \u2013 90 kW<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">System Pressure<\/td><td class=\"has-text-align-center\" data-align=\"center\">\u2264 1.6 MPa (higher pressure customized)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Temperature Range<\/td><td class=\"has-text-align-center\" data-align=\"center\">-20\u00b0C \u2013 120\u00b0C (varies by model type)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Seal Type<\/td><td class=\"has-text-align-center\" data-align=\"center\">Mechanical seal (hard alloy \/ silicon carbide \/ titanium alloy optional)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Motor Type<\/td><td class=\"has-text-align-center\" data-align=\"center\">B35 direct-coupled three-phase asynchronous motor<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Noise Level<\/td><td class=\"has-text-align-center\" data-align=\"center\">&lt; 40 dB (optimized hydraulic + bearing system)<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">Installation Type<\/td><td class=\"has-text-align-center\" data-align=\"center\">Horizontal installation, three-direction outlet (left\/right\/top)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">CYW Series Model Code Interpretation (Pump Selection Guide)<\/h3>\n\n\n\n<p>The CYW series horizontal centrifugal water pump adopts a structured model coding system to clearly define pump size, hydraulic performance, and impeller trimming status. This coding method helps engineers quickly identify pump specifications and select the correct configuration based on system requirements.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Example Model: <strong>CYW100-160(I)AB<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>CYW<\/strong> \u2192 Horizontal single-stage single-suction centrifugal water pump<\/li>\n\n\n\n<li><strong>100<\/strong> \u2192 DN100 mm inlet\/outlet diameter<\/li>\n\n\n\n<li><strong>160<\/strong> \u2192 160 mm original impeller outer diameter<\/li>\n\n\n\n<li><strong>(I)<\/strong> \u2192 Flow classification group I<\/li>\n\n\n\n<li><strong>A<\/strong> \u2192 First impeller trimming applied (performance adjustment)<\/li>\n\n\n\n<li><strong>B<\/strong> \u2192 Second impeller trimming applied (fine adjustment)<\/li>\n<\/ul>\n\n\n\n<p><strong>Interpretation Result:<\/strong><\/p>\n\n\n\n<p><em>This model represents a <strong>DN100 horizontal centrifugal water pump<\/strong> with a 160 mm impeller, which has undergone <strong>two-stage impeller trimming<\/strong> to precisely match system flow and head requirements. It is suitable for applications requiring customized hydraulic performance such as HVAC circulation, industrial water transfer, and municipal boosting systems.<\/em><\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYW-Series-Specifications.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 CYW Series Specifications.pddf.\"><\/object><a id=\"wp-block-file--media-80c669f8-def8-486a-ae8a-3d215430e43b\" href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYW-Series-Specifications.pdf\">CYW Series Specifications.pddf<\/a><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYW-Series-Specifications.pdf\" class=\"wp-block-file__button wp-element-button\" aria-describedby=\"wp-block-file--media-80c669f8-def8-486a-ae8a-3d215430e43b\" download>Download<\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_97c128-ad > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_97c128-ad > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_97c128-ad > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_97c128-ad > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_97c128-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_97c128-ad > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_97c128-ad alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_40319a-74 > .kt-inside-inner-col,.kadence-column1133_40319a-74 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_40319a-74 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_40319a-74 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_40319a-74 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_40319a-74 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_40319a-74{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_40319a-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_40319a-74 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_40319a-74\"><div class=\"kt-inside-inner-col\">\n<p style=\"margin-top:var(--wp--preset--spacing--50)\"><strong>Note:<\/strong> <em>At Changyu, we provide one-on-one technical guidance and product recommendations tailored to your specific operating conditions. If you have any questions, please feel free to <a href=\"https:\/\/changyupump.com\/contacts\/\" data-type=\"page\" data-id=\"17\">contact us<\/a> right away, our team of experts will respond within <strong>24 hours<\/strong>.<\/em><\/p>\n\n\n<style>.kb-row-layout-id1133_cb2bfe-a9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_cb2bfe-a9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_cb2bfe-a9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1133_cb2bfe-a9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_cb2bfe-a9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1133_cb2bfe-a9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_cb2bfe-a9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{display:flex;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col,.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1133_4cc8c3-60{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_4cc8c3-60{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_4cc8c3-60{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1133_4cc8c3-60{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_4cc8c3-60{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1133_4cc8c3-60{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_4cc8c3-60{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_4cc8c3-60 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_4cc8c3-60\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +<a href=\"https:\/\/wa.me\/8613651913727\" data-type=\"link\" data-id=\"https:\/\/wa.me\/8613651913727\" target=\"_blank\" rel=\"noopener\">86-13651913727<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_7d823c-09 > .kt-inside-inner-col{display:flex;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col,.kadence-column1133_7d823c-09 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_7d823c-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1133_7d823c-09{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_7d823c-09{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_7d823c-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_7d823c-09{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1133_7d823c-09{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_7d823c-09{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_7d823c-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1133_7d823c-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1133_7d823c-09{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_7d823c-09{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_7d823c-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_7d823c-09 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_7d823c-09\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Veuillez activer JavaScript dans votre navigateur pour envoyer le formulaire.<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_fe3dbc-62 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_fe3dbc-62 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_fe3dbc-62 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_fe3dbc-62 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_fe3dbc-62 > .kt-row-column-wrap{padding-top:80px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_fe3dbc-62 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_fe3dbc-62 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_a006f8-95 > .kt-inside-inner-col,.kadence-column1133_a006f8-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_a006f8-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_a006f8-95 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_a006f8-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_a006f8-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_a006f8-95{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_a006f8-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_a006f8-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_a006f8-95 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1133_b9f057-03, .wp-block-kadence-advancedheading.kt-adv-heading1133_b9f057-03[data-kb-block=\"kb-adv-heading1133_b9f057-03\"]{text-align:center;font-size:20px;font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading1133_b9f057-03 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1133_b9f057-03[data-kb-block=\"kb-adv-heading1133_b9f057-03\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1133_b9f057-03 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1133_b9f057-03[data-kb-block=\"kb-adv-heading1133_b9f057-03\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1133_b9f057-03 wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading1133_b9f057-03\">Why Choose It?<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1133_c3900c-8c, .wp-block-kadence-advancedheading.kt-adv-heading1133_c3900c-8c[data-kb-block=\"kb-adv-heading1133_c3900c-8c\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading1133_c3900c-8c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1133_c3900c-8c[data-kb-block=\"kb-adv-heading1133_c3900c-8c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1133_c3900c-8c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1133_c3900c-8c[data-kb-block=\"kb-adv-heading1133_c3900c-8c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1133_c3900c-8c wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1133_c3900c-8c\">Advantages of the Horizontal Centrifugal Water Pump<\/h2>\n\n\n<style>.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1133_7f20bf-23 > .kt-row-layout-overlay{opacity:0.00;}@media all and (max-width: 1024px){.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1133_7f20bf-23 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_7f20bf-23 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1133_936741-c5 > .kt-inside-inner-col{display:flex;}.kadence-column1133_936741-c5 > .kt-inside-inner-col,.kadence-column1133_936741-c5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_936741-c5 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_936741-c5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_936741-c5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_936741-c5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_936741-c5{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_936741-c5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_936741-c5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_936741-c5 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1133_676cfb-18 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_676cfb-18 .kt-info-svg-icon-flip, .kt-info-box1133_676cfb-18 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1133_676cfb-18 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_676cfb-18 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1133_676cfb-18 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1133_676cfb-18 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_676cfb-18\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_aperture kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"14.31\" y1=\"8\" x2=\"20.05\" y2=\"17.94\"\/><line x1=\"9.69\" y1=\"8\" x2=\"21.17\" y2=\"8\"\/><line x1=\"7.38\" y1=\"12\" x2=\"13.12\" y2=\"2.06\"\/><line x1=\"9.69\" y1=\"16\" x2=\"3.95\" y2=\"6.06\"\/><line x1=\"14.31\" y1=\"16\" x2=\"2.83\" y2=\"16\"\/><line x1=\"16.62\" y1=\"12\" x2=\"10.88\" y2=\"21.94\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Standard Compliance<\/h3><p class=\"kt-blocks-info-box-text\">Ensures standardized installation dimensions and strong interchangeability, making system integration and pump replacement simple, reliable, and cost-efficient in industrial pipeline applications.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1133_43bf74-d2 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_43bf74-d2 .kt-info-svg-icon-flip, .kt-info-box1133_43bf74-d2 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1133_43bf74-d2 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_43bf74-d2 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1133_43bf74-d2 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_43bf74-d2\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_archive kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"21 8 21 21 3 21 3 8\"\/><rect x=\"1\" y=\"3\" width=\"22\" height=\"5\"\/><line x1=\"10\" y1=\"12\" x2=\"14\" y2=\"12\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Wide Performance Range<\/h3><p class=\"kt-blocks-info-box-text\">Covers flow from 1.5\u20131660 m\u00b3\/h, head from 5.2\u2013160 m, and temperature from -20\u00b0C to 120\u00b0C (depending on model), suitable for municipal, HVAC, and industrial water transfer systems.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col,.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_3fd4aa-e7{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_3fd4aa-e7 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_3fd4aa-e7 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image1133_01390d-37 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image1133_01390d-37 img.kb-img, .kb-image1133_01390d-37 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;box-shadow:inset 0px 0px 60px -15px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image1133_01390d-37\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-land43\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1.webp\" alt=\"Centrifugal Water Pump\" class=\"kb-img wp-image-4464\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Water-Pump-1-18x10.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><figcaption>Centrifugal Water Pump<\/figcaption><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_21be64-91 > .kt-inside-inner-col{display:flex;}.kadence-column1133_21be64-91 > .kt-inside-inner-col,.kadence-column1133_21be64-91 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_21be64-91 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_21be64-91 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_21be64-91 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_21be64-91 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_21be64-91{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_21be64-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_21be64-91 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_21be64-91 inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1133_e255b9-99 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_e255b9-99 .kt-info-svg-icon-flip, .kt-info-box1133_e255b9-99 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1133_e255b9-99 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_e255b9-99 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1133_e255b9-99 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1133_e255b9-99 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_e255b9-99\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Leak-Free Operation<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Uses high-strength mechanical seals (optional silicon carbide or titanium alloy), supporting system pressure up to 1.6 MPa for safe and stable long-term operation.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1133_113392-84 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_113392-84 .kt-info-svg-icon-flip, .kt-info-box1133_113392-84 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1133_113392-84 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1133_113392-84 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1133_113392-84 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_113392-84 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1133_113392-84 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1133_113392-84 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1133_113392-84 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_113392-84\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_cpu kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"4\" y=\"4\" width=\"16\" height=\"16\" rx=\"2\" ry=\"2\"\/><rect x=\"9\" y=\"9\" width=\"6\" height=\"6\"\/><line x1=\"9\" y1=\"1\" x2=\"9\" y2=\"4\"\/><line x1=\"15\" y1=\"1\" x2=\"15\" y2=\"4\"\/><line x1=\"9\" y1=\"20\" x2=\"9\" y2=\"23\"\/><line x1=\"15\" y1=\"20\" x2=\"15\" y2=\"23\"\/><line x1=\"20\" y1=\"9\" x2=\"23\" y2=\"9\"\/><line x1=\"20\" y1=\"14\" x2=\"23\" y2=\"14\"\/><line x1=\"1\" y1=\"9\" x2=\"4\" y2=\"9\"\/><line x1=\"1\" y1=\"14\" x2=\"4\" y2=\"14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Low Maintenance Design<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Back pull-out structure, three-direction outlet, and B35 direct-coupled motor design allow easy maintenance without pipeline removal, reducing downtime and service cost.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_08ea52-2e > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_08ea52-2e > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_08ea52-2e > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_08ea52-2e > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_08ea52-2e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_08ea52-2e > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_08ea52-2e alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_d7fc08-ac > .kt-inside-inner-col,.kadence-column1133_d7fc08-ac > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_d7fc08-ac > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_d7fc08-ac > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_d7fc08-ac > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_d7fc08-ac > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_d7fc08-ac{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_d7fc08-ac > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_d7fc08-ac > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_d7fc08-ac\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1133_48c222-93 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_48c222-93 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_48c222-93 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_48c222-93 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_48c222-93 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_48c222-93 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_48c222-93 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col,.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_9ccaaf-90{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_9ccaaf-90 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_9ccaaf-90\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1133_e2c52d-d9, .wp-block-kadence-advancedheading.kt-adv-heading1133_e2c52d-d9[data-kb-block=\"kb-adv-heading1133_e2c52d-d9\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:36px;line-height:1.4;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1133_e2c52d-d9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1133_e2c52d-d9[data-kb-block=\"kb-adv-heading1133_e2c52d-d9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1133_e2c52d-d9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1133_e2c52d-d9[data-kb-block=\"kb-adv-heading1133_e2c52d-d9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1133_e2c52d-d9 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1133_e2c52d-d9\">Applications: Horizontal Centrifugal Pump<\/h2>\n\n\n\n<p class=\"has-text-align-center\" style=\"padding-right:3rem;padding-left:3rem\">The CYW horizontal centrifugal pump is specifically designed for pumping clean water and liquids with physical and chemical properties similar to clean water. It is widely used in the following industries and applications:<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id1133_95272a-61 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1133_95272a-61 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_95272a-61 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_30ab56-d0 > .kt-inside-inner-col,.kadence-column1133_30ab56-d0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_30ab56-d0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_30ab56-d0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_30ab56-d0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_30ab56-d0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_30ab56-d0{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_30ab56-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_30ab56-d0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_30ab56-d0\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_4887cc-57 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_4887cc-57 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_4887cc-57.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1133_4887cc-57 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1133_4887cc-57 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1000px;height:0px;max-width:100%;}.kt-info-box1133_4887cc-57 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_4887cc-57 .kt-info-svg-icon-flip, .kt-info-box1133_4887cc-57 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1133_4887cc-57 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_4887cc-57 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1133_4887cc-57 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1133_4887cc-57 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1133_4887cc-57 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1133_4887cc-57 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1133_4887cc-57 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_4887cc-57\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Municipal-and-construction-sectors.webp\" alt=\"Municipal and construction sectors\" width=\"1000\" height=\"564\" class=\"kt-info-box-image wp-image-4475\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Municipal-and-construction-sectors.webp 1000w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Municipal-and-construction-sectors-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Municipal-and-construction-sectors-150x85.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Municipal-and-construction-sectors-768x433.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Municipal-and-construction-sectors-18x10.webp 18w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Municipal and construction sectors<\/h3><p class=\"kt-blocks-info-box-text\">urban water supply and drainage systems, pressure boosting for high-rise buildings, fire protection system pressure boosting, and landscape irrigation<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_b65880-95 > .kt-inside-inner-col,.kadence-column1133_b65880-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_b65880-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_b65880-95 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_b65880-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_b65880-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_b65880-95{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_b65880-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_b65880-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_b65880-95\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_672f1d-e6 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_672f1d-e6.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1133_672f1d-e6 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1133_672f1d-e6 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:600px;height:0px;max-width:100%;}.kt-info-box1133_672f1d-e6 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_672f1d-e6 .kt-info-svg-icon-flip, .kt-info-box1133_672f1d-e6 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1133_672f1d-e6 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1133_672f1d-e6 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_672f1d-e6\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Industrial-Applications.webp\" alt=\"Industrial Applications\" width=\"600\" height=\"400\" class=\"kt-info-box-image wp-image-4474\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Industrial-Applications.webp 600w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Industrial-Applications-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Industrial-Applications-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Industrial-Applications-18x12.webp 18w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Industrial Applications<\/h3><p class=\"kt-blocks-info-box-text\">Long-distance transportation of liquids with water-like quality, such as cooling water and washing water in industrial processes, as well as supply of circulating cooling water for air conditioning systems<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_cd0168-34 > .kt-inside-inner-col,.kadence-column1133_cd0168-34 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_cd0168-34 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_cd0168-34 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_cd0168-34 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_cd0168-34 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_cd0168-34{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_cd0168-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_cd0168-34 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_cd0168-34\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_566912-e8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_566912-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_566912-e8.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1133_566912-e8 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1133_566912-e8 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1080px;height:0px;max-width:100%;}.kt-info-box1133_566912-e8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_566912-e8 .kt-info-svg-icon-flip, .kt-info-box1133_566912-e8 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1133_566912-e8 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_566912-e8 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1133_566912-e8 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1133_566912-e8 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1133_566912-e8 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1133_566912-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1133_566912-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_566912-e8\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy.webp\" alt=\"HVAC and District Energy\" width=\"1080\" height=\"721\" class=\"kt-info-box-image wp-image-4473\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy.webp 1080w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-1024x684.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-768x513.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-18x12.webp 18w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">HVAC and District Energy<\/h3><p class=\"kt-blocks-info-box-text\">Circulation and transportation of water-based media in heating, ventilation, and district energy systems<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_2db2cc-28 > .kt-inside-inner-col,.kadence-column1133_2db2cc-28 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_2db2cc-28 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_2db2cc-28 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_2db2cc-28 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_2db2cc-28 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_2db2cc-28{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_2db2cc-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_2db2cc-28 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_2db2cc-28\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1133_a7e037-06 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1133_a7e037-06 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_a7e037-06.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1133_a7e037-06 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1133_a7e037-06 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:512px;height:0px;max-width:100%;}.kt-info-box1133_a7e037-06 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1133_a7e037-06 .kt-info-svg-icon-flip, .kt-info-box1133_a7e037-06 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1133_a7e037-06 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1133_a7e037-06 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1133_a7e037-06 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1133_a7e037-06 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1133_a7e037-06 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1133_a7e037-06 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1133_a7e037-06 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1133_a7e037-06\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Other-Applicable-Scenarios.webp\" alt=\"Other Applicable Scenarios\" width=\"512\" height=\"342\" class=\"kt-info-box-image wp-image-4476\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Other-Applicable-Scenarios.webp 512w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Other-Applicable-Scenarios-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Other-Applicable-Scenarios-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/Other-Applicable-Scenarios-18x12.webp 18w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Other Applicable Scenarios<\/h3><p class=\"kt-blocks-info-box-text\">Also suitable for agricultural irrigation, aquaculture water supply and drainage, and general industrial medium transfer<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_4e433a-e9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_4e433a-e9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_4e433a-e9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_4e433a-e9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_4e433a-e9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_4e433a-e9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_4e433a-e9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col,.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_a5dfea-b3{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_a5dfea-b3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_a5dfea-b3\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\"><strong>Custom Horizontal Centrifugal Water Pump<\/strong><\/h2>\n\n\n<style>.kb-row-layout-id1133_3e4120-70 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_3e4120-70 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_3e4120-70 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1133_3e4120-70 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_3e4120-70 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1133_3e4120-70 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_3e4120-70 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_5f4562-f6 > .kt-inside-inner-col,.kadence-column1133_5f4562-f6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_5f4562-f6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_5f4562-f6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_5f4562-f6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_5f4562-f6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_5f4562-f6{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_5f4562-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_5f4562-f6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_5f4562-f6\"><div class=\"kt-inside-inner-col\">\n<p>Changyu Pump specializes in the design and production of custom horizontal centrifugal water pumps, offering tailored solutions for a wide range of industrial, commercial, and municipal applications. We have advanced manufacturing capabilities and strict quality control systems, ensure every pump delivers high efficiency, reliability, and durability. Our product line includes various customizable models such as&nbsp;<a href=\"https:\/\/changyupump.com\/self-priming-pump\/\" data-type=\"link\" data-id=\"https:\/\/changyupump.com\/self-priming-pump\/\">self-priming centrifugal pumps<\/a>&nbsp;and&nbsp;<a href=\"https:\/\/changyupump.com\/magnetic-pump-supplier\/\" data-type=\"link\" data-id=\"https:\/\/changyupump.com\/magnetic-pump-supplier\/\">magnetic driven pump<\/a>s, capable of meeting diverse operational requirements and medium characteristics.<\/p>\n\n\n\n<p>If you want a best pump solution, please provide details regarding flow rate, head, medium properties, temperature, and intended application. Our technical team will gladly assist you with product selection and customized support. Feel free to contact us for a formal quotation or additional technical information.<\/p>\n\n\n<style>.kb-row-layout-id1133_82584b-b1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_82584b-b1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_82584b-b1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1133_82584b-b1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_82584b-b1 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1133_82584b-b1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_82584b-b1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_ee88b5-de > .kt-inside-inner-col{display:flex;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col,.kadence-column1133_ee88b5-de > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_ee88b5-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1133_ee88b5-de{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_ee88b5-de{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_ee88b5-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_ee88b5-de{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1133_ee88b5-de{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_ee88b5-de{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_ee88b5-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1133_ee88b5-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1133_ee88b5-de{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_ee88b5-de{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_ee88b5-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_ee88b5-de > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_ee88b5-de\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +<a href=\"https:\/\/wa.me\/8613651913727\" data-type=\"link\" data-id=\"https:\/\/wa.me\/8613651913727\" target=\"_blank\" rel=\"noopener\">86-13651913727<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{display:flex;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col,.kadence-column1133_3a38f9-50 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1133_3a38f9-50{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_3a38f9-50{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_3a38f9-50{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1133_3a38f9-50{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_3a38f9-50{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1133_3a38f9-50{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_3a38f9-50{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1133_3a38f9-50 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_3a38f9-50\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Veuillez activer JavaScript dans votre navigateur pour envoyer le formulaire.<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column1133_cd19dd-ec > .kt-inside-inner-col,.kadence-column1133_cd19dd-ec > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_cd19dd-ec > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_cd19dd-ec > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_cd19dd-ec > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_cd19dd-ec > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_cd19dd-ec{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_cd19dd-ec > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_cd19dd-ec > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_cd19dd-ec\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CHANGYU company introduce\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/WEFwgg-Bu8U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_c3ee25-6c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_c3ee25-6c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_c3ee25-6c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_c3ee25-6c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_c3ee25-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_c3ee25-6c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_c3ee25-6c alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_37c74b-46 > .kt-inside-inner-col,.kadence-column1133_37c74b-46 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_37c74b-46 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_37c74b-46 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_37c74b-46 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_37c74b-46 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_37c74b-46{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_37c74b-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_37c74b-46 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_37c74b-46\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Factory Show<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1133_0c5387-b9{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1133_0c5387-b9 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1133_0c5387-b9 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1133_0c5387-b9 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1133_0c5387-b9 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1133_0c5387-b9 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"5\" data-columns-xl=\"5\" data-columns-md=\"5\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-id=\"954\" class=\"wp-image-954\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" width=\"900\" height=\"529\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-id=\"959\" class=\"wp-image-959\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-300x176.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-768x451.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-id=\"927\" class=\"wp-image-927\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-id=\"921\" class=\"wp-image-921\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-id=\"930\" class=\"wp-image-930\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-id=\"940\" class=\"wp-image-940\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-id=\"945\" class=\"wp-image-945\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-id=\"926\" class=\"wp-image-926\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-id=\"944\" class=\"wp-image-944\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" width=\"900\" height=\"504\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-id=\"949\" class=\"wp-image-949\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-768x430.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"703\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3.webp\" alt=\"Custom Visit\" class=\"wp-image-1135\" style=\"object-fit:cover\" title=\"Custom Visit\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-300x141.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-1024x480.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-768x360.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_6dcd48-4a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_6dcd48-4a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_6dcd48-4a > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_6dcd48-4a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_6dcd48-4a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_6dcd48-4a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_6dcd48-4a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_c29170-c4 > .kt-inside-inner-col,.kadence-column1133_c29170-c4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_c29170-c4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_c29170-c4 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_c29170-c4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_c29170-c4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_c29170-c4{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_c29170-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_c29170-c4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_c29170-c4\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">FAQs<\/h2>\n\n\n<style>.kb-row-layout-id1133_42ccec-45 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_42ccec-45 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_42ccec-45 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1133_42ccec-45 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_42ccec-45 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1133_42ccec-45 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_42ccec-45 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1133_76e2c6-bb > .kt-inside-inner-col,.kadence-column1133_76e2c6-bb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_76e2c6-bb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_76e2c6-bb > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_76e2c6-bb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_76e2c6-bb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_76e2c6-bb{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_76e2c6-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_76e2c6-bb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_76e2c6-bb\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1133_c0f6d4-90 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id1133_c0f6d4-90 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:9px;padding-right:13px;padding-bottom:9px;padding-left:13px;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id1133_c0f6d4-90 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c0f6d4-90:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id1133_c0f6d4-90 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}}@media all and (max-width: 1024px){.kt-accordion-id1133_c0f6d4-90 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}@media all and (max-width: 767px){.kt-accordion-id1133_c0f6d4-90 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1133_c0f6d4-90 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id1133_c0f6d4-90 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1133_c0f6d4-90 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id1133_c0f6d4-90 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1133_c0f6d4-90 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1133_c0f6d4-90 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1133_89c702-20\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is a horizontal centrifugal water pump used for?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>It is used for transferring clean water or similar liquids in municipal water supply, HVAC circulation, industrial cooling systems, building pressure boosting, and agricultural irrigation applications.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1133_18244a-2d\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the operating temperature range of this centrifugal water pump?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Depending on the model, the CYW pump operates from -20\u00b0C to 120\u00b0C, covering clean water, hot water circulation, chemical liquids without solids, and oil transfer applications.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1133_0581ec-ad\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Can the pump handle corrosive or chemical liquids?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Yes. The CYWH chemical model is designed for non-solid corrosive liquids such as acids and alkalis, using corrosion-resistant materials and upgraded sealing systems.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_2788d6-63 > .kt-inside-inner-col,.kadence-column1133_2788d6-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_2788d6-63 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_2788d6-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_2788d6-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_2788d6-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_2788d6-63{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_2788d6-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_2788d6-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_2788d6-63\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id1133_c7a389-ad .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id1133_c7a389-ad .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:9px;padding-right:13px;padding-bottom:9px;padding-left:13px;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id1133_c7a389-ad .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1133_c7a389-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id1133_c7a389-ad .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}}@media all and (max-width: 1024px){.kt-accordion-id1133_c7a389-ad .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}@media all and (max-width: 767px){.kt-accordion-id1133_c7a389-ad .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1133_c7a389-ad .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id1133_c7a389-ad .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1133_c7a389-ad .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id1133_c7a389-ad .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1133_c7a389-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1133_c7a389-ad kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1133_17919f-39\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What standards does the CYW horizontal centrifugal water pump follow?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>A: The ChangyuPump CYW series is designed according to ISO 2858 and JB\/T53058-93 standards, ensuring standardized dimensions, easy installation, and reliable interchangeability in pipeline systems.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1133_81b584-bf\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">How do I choose the correct CYW pump model?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Selection is based on flow rate, head, medium type, temperature, and system pressure. Providing these parameters allows accurate matching of the correct Horizontal Centrifugal Water Pump model.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1133_580fef-7d\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Is maintenance difficult for this centrifugal water pump?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>No. The back pull-out structure allows internal components to be serviced without removing pipelines, significantly reducing downtime and maintenance cost in industrial operation.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1133_d0f75b-be > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1133_d0f75b-be > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1133_d0f75b-be > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1133_d0f75b-be > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1133_d0f75b-be > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1133_d0f75b-be > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1133_d0f75b-be alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col,.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_9cb6a4-dd{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_9cb6a4-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_9cb6a4-dd\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Blog<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column1133_58efe4-76 > .kt-inside-inner-col,.kadence-column1133_58efe4-76 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1133_58efe4-76 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1133_58efe4-76 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1133_58efe4-76 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1133_58efe4-76 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1133_58efe4-76{position:relative;}@media all and (max-width: 1024px){.kadence-column1133_58efe4-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1133_58efe4-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1133_58efe4-76\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop1133_6db1ca-ea .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop1133_6db1ca-ea .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop1133_6db1ca-ea .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop1133_6db1ca-ea .entry-content:after{height:0px;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-footer a{color:#777777;}.kt-post-loop1133_6db1ca-ea .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop1133_6db1ca-ea .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1133_6db1ca-ea.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop1133_6db1ca-ea kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"11880\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"3\" data-columns-xl=\"3\" data-columns-md=\"3\" data-columns-sm=\"2\" data-columns-xs=\"1\" data-columns-ss=\"1\"><li class=\"kt-post-slider-item post-4190 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-sump-pump tag-corrosive-wastewater-pump tag-industrial-sump-pump tag-industrial-wastewater-pump tag-magnetic-drive-sump-pump tag-self-priming-sump-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/how-to-select-an-industrial-sump-pump-for-chemical-wastewater\/\" aria-label=\"How to Select an Industrial Sump Pump for Chemical Wastewater\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Industrial Process Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-Process-Pump-8.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/how-to-select-an-industrial-sump-pump-for-chemical-wastewater\/\">How to Select an Industrial Sump Pump for Chemical Wastewater<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/chemical-sump-pump\/\" rel=\"tag\">chemical sump pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/corrosive-wastewater-pump\/\" rel=\"tag\">corrosive wastewater pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/industrial-sump-pump\/\" rel=\"tag\">Industrial sump pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/industrial-wastewater-pump\/\" rel=\"tag\">industrial wastewater pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/magnetic-drive-sump-pump\/\" rel=\"tag\">magnetic drive sump pump.<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/self-priming-sump-pump\/\" rel=\"tag\">self priming sump pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4236 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-abrasive-slurry-pump tag-centrifugal-slurry-pump tag-corrosive-slurry-pump tag-slurry-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/centrifugal-slurry-pump-working-principle-applications-selection-guide\/\" aria-label=\"Centrifugal Slurry Pump: Working Principle, Applications &amp; Selection Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"UHB Series Horizontal Chemical Slurry Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/UHB-Series-Horizontal-Chemical-Slurry-Pump-4.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/centrifugal-slurry-pump-working-principle-applications-selection-guide\/\">Centrifugal Slurry Pump: Working Principle, Applications &amp; Selection Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/abrasive-slurry-pump\/\" rel=\"tag\">abrasive slurry pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/centrifugal-slurry-pump\/\" rel=\"tag\">centrifugal slurry pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/corrosive-slurry-pump\/\" rel=\"tag\">corrosive slurry pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/slurry-pump\/\" rel=\"tag\">slurry pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4232 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-pump tag-acid-transfer-pump tag-fluoroplastic-pump tag-magnetic-drive-acid-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/acid-pump-selection-guide\/\" aria-label=\"Acid Pump: Types, Materials, Applications &amp; Selection Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Concentrated-sulfuric-acid-transfer-magnetic-pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"CYQ Concentrated sulfuric acid transfer magnetic pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Concentrated-sulfuric-acid-transfer-magnetic-pump.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Concentrated-sulfuric-acid-transfer-magnetic-pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Concentrated-sulfuric-acid-transfer-magnetic-pump-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/acid-pump-selection-guide\/\">Acid Pump: Types, Materials, Applications &amp; Selection Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/acid-pump\/\" rel=\"tag\">Acid Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/fluoroplastic-pump\/\" rel=\"tag\">Fluoroplastic Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/magnetic-drive-acid-pump\/\" rel=\"tag\">magnetic drive acid pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4158 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-process-pump tag-heavy-duty-centrifugal-pump tag-heavy-duty-magnetic-pump tag-stainless-steel-heavy-duty-pump tag-teflon-lined-heavy-duty-pump tag-zero-leakage-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/heavy-duty-centrifugal-pump-selection-guide-2026-sizing-specs\/\" aria-label=\"Heavy Duty Centrifugal Pump Selection Guide 2026: Sizing &amp; Specs\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"CYQ Series Horizontal Heavy-Duty TEFLON Lined Magnetic Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/heavy-duty-centrifugal-pump-selection-guide-2026-sizing-specs\/\">Heavy Duty Centrifugal Pump Selection Guide 2026: Sizing &amp; Specs<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/chemical-process-pump\/\" rel=\"tag\">chemical process pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/heavy-duty-centrifugal-pump\/\" rel=\"tag\">heavy duty centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/heavy-duty-magnetic-pump\/\" rel=\"tag\">heavy duty magnetic pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/stainless-steel-heavy-duty-pump\/\" rel=\"tag\">stainless steel heavy duty pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/teflon-lined-heavy-duty-pump\/\" rel=\"tag\">teflon lined heavy duty pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/zero-leakage-pump\/\" rel=\"tag\">zero leakage pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4172 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-transfer-pump tag-chemical-pump tag-chemical-transfer-pump tag-heavy-duty-centrifugal-pump tag-heavy-duty-centrifugal-pumps tag-heavy-duty-process-pump tag-industrial-use-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/heavy-duty-centrifugal-pumps-for-industrial-use-2026-guide\/\" aria-label=\"Heavy Duty Centrifugal Pumps for Industrial Use 2026 Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Stainless Steel Magnetic Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/heavy-duty-centrifugal-pumps-for-industrial-use-2026-guide\/\">Heavy Duty Centrifugal Pumps for Industrial Use 2026 Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/chemical-transfer-pump\/\" rel=\"tag\">Chemical Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/heavy-duty-centrifugal-pump\/\" rel=\"tag\">heavy duty centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/heavy-duty-centrifugal-pumps\/\" rel=\"tag\">heavy duty centrifugal pumps<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/heavy-duty-process-pump\/\" rel=\"tag\">heavy duty process pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/industrial-use-pump\/\" rel=\"tag\">industrial use pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4153 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-high-pressure-water-pump tag-multistage-booster-pump tag-vertical-multistage-centrifugal-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/vertical-multistage-centrifugal-pump-guide-2026-sizing-specs\/\" aria-label=\"Vertical Multistage Centrifugal Pump Guide 2026: Sizing &amp; Specs\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"vertical multistage centrifugal pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/vertical-multistage-centrifugal-pump-guide-2026-sizing-specs\/\">Vertical Multistage Centrifugal Pump Guide 2026: Sizing &amp; Specs<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/high-pressure-water-pump\/\" rel=\"tag\">high pressure water pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/multistage-booster-pump\/\" rel=\"tag\">multistage booster pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/vertical-multistage-centrifugal-pump\/\" rel=\"tag\">vertical multistage centrifugal pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4206 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-single-stage-centrifugal-pump tag-single-stage-chemical-centrifugal-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/single-stage-centrifugal-pump-types-and-selection-guide-2026\/\" aria-label=\"Single Stage Centrifugal Pump: Types and Selection Guide 2026\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"PTFEPFA Chemical Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-300x300.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-150x150.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-768x768.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-12x12.webp 12w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/single-stage-centrifugal-pump-types-and-selection-guide-2026\/\">Single Stage Centrifugal Pump: Types and Selection Guide 2026<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/single-stage-centrifugal-pump\/\" rel=\"tag\">single stage centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/single-stage-chemical-centrifugal-pump\/\" rel=\"tag\">single stage chemical centrifugal pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4201 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-self-priming-pump tag-industrial-self-priming-pump tag-self-priming-centrifugal-pump tag-self-priming-centrifugal-pump-2 tag-what-is-a-self-priming-centrifugal-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-66-67\" style=\"padding-bottom:66.67%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/fr\/blog\/what-is-a-self-priming-centrifugal-pump-a-complete-guide-2026\/\" aria-label=\"What is a Self-Priming Centrifugal Pump? A Complete Guide 2026\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"537\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Self-Priming-Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10.webp 751w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10-300x215.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10-150x107.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10-18x12.webp 18w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/fr\/blog\/what-is-a-self-priming-centrifugal-pump-a-complete-guide-2026\/\">What is a Self-Priming Centrifugal Pump? A Complete Guide 2026<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/fr\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/fr\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>\u00c9tiquettes<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/fr\/tag\/chemical-self-priming-pump\/\" rel=\"tag\">chemical self priming pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/industrial-self-priming-pump\/\" rel=\"tag\">industrial self priming pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/self-priming-centrifugal-pump\/\" rel=\"tag\">self priming centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/self-priming-centrifugal-pump-2\/\" rel=\"tag\">Self-Priming Centrifugal Pump<\/a>, <a href=\"https:\/\/changyupump.com\/fr\/tag\/what-is-a-self-priming-centrifugal-pump\/\" rel=\"tag\">what is a self priming centrifugal pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-1114] --><style>.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id1114_136e69-11 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1114_136e69-11 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{display:flex;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col,.kadence-column1114_03d1b0-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_03d1b0-0d{text-align:left;}.kadence-column1114_03d1b0-0d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_03d1b0-0d kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading1114_6c6840-24 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1114_6c6840-24\">Request a free quote<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1114_7bff25-4d wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1114_7bff25-4d\">Please fill in the details of your pumped liquid, including flow, head, specific gravity, and temperature, so we can recommend the best pump and provide a precise quote.<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1114_923d6b-76 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1114_3d05c4-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_3d05c4-55\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Customized Pump Solutions<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_a819a4-1b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_a819a4-1b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_users kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M17 21v-2a4 4 0 0 0-4-4H5a4 4 0 0 0-4 4v2\"\/><circle cx=\"9\" cy=\"7\" r=\"4\"\/><path d=\"M23 21v-2a4 4 0 0 0-3-3.87\"\/><path d=\"M16 3.13a4 4 0 0 1 0 7.75\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fast Quotation within 24 hours<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_05ee61-11 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_05ee61-11\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_feather kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20.24 12.24a6 6 0 0 0-8.49-8.49L5 10.5V19h8.5z\"\/><line x1=\"16\" y1=\"8\" x2=\"2\" y2=\"22\"\/><line x1=\"17\" y1=\"15\" x2=\"9\" y2=\"15\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Factory Direct with Competitive Price<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_5f1d2f-38 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_5f1d2f-38\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_settings kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"3\"\/><path d=\"M19.4 15a1.65 1.65 0 0 0 .33 1.82l.06.06a2 2 0 0 1 0 2.83 2 2 0 0 1-2.83 0l-.06-.06a1.65 1.65 0 0 0-1.82-.33 1.65 1.65 0 0 0-1 1.51V21a2 2 0 0 1-2 2 2 2 0 0 1-2-2v-.09A1.65 1.65 0 0 0 9 19.4a1.65 1.65 0 0 0-1.82.33l-.06.06a2 2 0 0 1-2.83 0 2 2 0 0 1 0-2.83l.06-.06a1.65 1.65 0 0 0 .33-1.82 1.65 1.65 0 0 0-1.51-1H3a2 2 0 0 1-2-2 2 2 0 0 1 2-2h.09A1.65 1.65 0 0 0 4.6 9a1.65 1.65 0 0 0-.33-1.82l-.06-.06a2 2 0 0 1 0-2.83 2 2 0 0 1 2.83 0l.06.06a1.65 1.65 0 0 0 1.82.33H9a1.65 1.65 0 0 0 1-1.51V3a2 2 0 0 1 2-2 2 2 0 0 1 2 2v.09a1.65 1.65 0 0 0 1 1.51 1.65 1.65 0 0 0 1.82-.33l.06-.06a2 2 0 0 1 2.83 0 2 2 0 0 1 0 2.83l-.06.06a1.65 1.65 0 0 0-.33 1.82V9a1.65 1.65 0 0 0 1.51 1H21a2 2 0 0 1 2 2 2 2 0 0 1-2 2h-.09a1.65 1.65 0 0 0-1.51 1z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Professional engineers, one-on-one technical consultation<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_a211a7-13 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_a211a7-13\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_award kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"8\" r=\"7\"\/><polyline points=\"8.21 13.89 7 23 12 20 17 23 15.79 13.88\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">CE\/ISO certified pumps with strict testing before shipment<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.kadence-column1114_77e08c-18 > .kt-inside-inner-col{display:flex;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col,.kadence-column1114_77e08c-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_77e08c-18{position:relative;}.kadence-column1114_77e08c-18, .kt-inside-inner-col > .kadence-column1114_77e08c-18:not(.specificity){margin-top:var(--global-kb-spacing-lg, 3rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);}@media all and (max-width: 1024px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_77e08c-18 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading1114_b234f2-d2 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1114_b234f2-d2\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons1114_296db3-9a .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons1114_296db3-9a{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons1114_296db3-9a{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons1114_296db3-9a alignnone\"><style>.kt-svg-item-1114_b484c3-db .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_b484c3-db .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:20px;}.kt-svg-item-1114_b484c3-db:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_b484c3-db\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=61564021046258\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_3f5c48-35 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_3f5c48-35 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_3f5c48-35\"><a href=\"https:\/\/www.linkedin.com\/company\/anhui-changyu-pump-valve-co-ltd\/?viewAsMember=true\" class=\"kt-svg-icon-link\" aria-label=\"Linkedin\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_linkedin\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_7e9ec1-58 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_7e9ec1-58 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:17px;}.kt-svg-item-1114_7e9ec1-58:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_7e9ec1-58\"><a href=\"https:\/\/www.instagram.com\/changyupump\/\" class=\"kt-svg-icon-link\" aria-label=\"Ins\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_instagram\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"2\" y=\"2\" width=\"20\" height=\"20\" rx=\"5\" ry=\"5\"\/><path d=\"M16 11.37A4 4 0 1 1 12.63 8 4 4 0 0 1 16 11.37z\"\/><line x1=\"17.5\" y1=\"6.5\" x2=\"17.5\" y2=\"6.5\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_177ba8-54 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_177ba8-54 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}.kt-svg-item-1114_177ba8-54:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_177ba8-54\"><a href=\"https:\/\/www.youtube.com\/@Changyu-CY\" class=\"kt-svg-icon-link\" aria-label=\"Youtube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col,.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{column-gap:0px;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_ac3a5c-85{text-align:left;}.kadence-column1114_ac3a5c-85{position:relative;}@media all and (max-width: 1024px){.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_ac3a5c-85 kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;background:var(--global-palette2, #2B6CB0);}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit:hover, .kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit:focus {background:#019141;}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-1114_7d9556-ee kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_1114_7d9556-ee_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_1114_7d9556-ee_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Address\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_1114_7d9556-ee_2\" data-label=\"Phone\/WA\" type=\"text\" placeholder=\"Phone\/WA\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_3\" id=\"kb_field_1114_7d9556-ee_3\" data-label=\"Country\" type=\"text\" placeholder=\"Country\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-3\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-4 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_4\" id=\"kb_field_1114_7d9556-ee_4\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-4\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"1114_7d9556-ee\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"1114\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\"><strong>Send Your Inquiry Now<\/strong><\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Veuillez activer JavaScript dans votre navigateur pour envoyer le formulaire.<\/div><style>.kadence-form-1114_7d9556-ee .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-1114] -->\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pompe \u00e0 eau centrifuge horizontale ISO 2858 de ChangyuPump avec un d\u00e9bit de 1,5-1660 m\u00b3\/h, un faible niveau sonore et une conception multi-application pour les syst\u00e8mes industriels, HVAC et d'approvisionnement en eau.<\/p>","protected":false},"featured_media":4468,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"show","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"class_list":["post-1133","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Horizontal-Centrifugal-Water-Pump-1-1024x768.webp",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/changyupump.com\/fr\/wp-json\/wp\/v2\/product\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/changyupump.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/changyupump.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/changyupump.com\/fr\/wp-json\/wp\/v2\/media\/4468"}],"wp:attachment":[{"href":"https:\/\/changyupump.com\/fr\/wp-json\/wp\/v2\/media?parent=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}