{"id":1075,"date":"2026-05-06T14:27:17","date_gmt":"2026-05-06T14:27:17","guid":{"rendered":"https:\/\/changyupump.com\/?post_type=product&#038;p=1075"},"modified":"2026-05-09T02:28:46","modified_gmt":"2026-05-09T02:28:46","slug":"cyf-series-fluoroplastic-centrifugal-pump","status":"publish","type":"product","link":"https:\/\/changyupump.com\/id\/product\/cyf-series-fluoroplastic-centrifugal-pump\/","title":{"rendered":"Pompa Sentrifugal Fluoroplastik Seri CYF"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id1075_bbd2da-91{margin-top:-20px;}.kb-row-layout-id1075_bbd2da-91 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_bbd2da-91 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_bbd2da-91 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1075_bbd2da-91 > .kt-row-layout-overlay{opacity:0.95;background-color:#f0f2f4;}@media all and (max-width: 1024px){.kb-row-layout-id1075_bbd2da-91 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_bbd2da-91 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_bbd2da-91 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col,.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_fbd9dd-6b{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_fbd9dd-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_fbd9dd-6b\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-type-thumbslider.kb-gallery-id-1075_b73e47-78 .kt-blocks-carousel-init {margin-bottom:10px;}.kb-gallery-id-1075_b73e47-78 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1075_b73e47-78 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1075_b73e47-78 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-thumbslider kb-gallery-id-1075_b73e47-78 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div id=\"kb-slider-1075_b73e47-78\" class=\"kt-blocks-carousel-init splide kb-blocks-slider kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"4\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-thumb-slider-1075_b73e47-78\"  data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp\" data-id=\"4979\" class=\"wp-image-4979 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp\" data-id=\"4980\" class=\"wp-image-4980 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-1024x576.webp\" width=\"1024\" height=\"576\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp\" data-id=\"4981\" class=\"wp-image-4981 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-1024x576.webp\" width=\"1024\" height=\"576\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" data-id=\"4982\" class=\"wp-image-4982 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><div id=\"kb-thumb-slider-1075_b73e47-78\" class=\"kb-blocks-slider splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-speed=\"7000\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-slider-1075_b73e47-78\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp\" width=\"1024\" height=\"768\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp\" data-id=\"4979\" class=\"wp-image-4979 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp\" width=\"1024\" height=\"768\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp\" data-id=\"4980\" class=\"wp-image-4980 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-2-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp\" width=\"1024\" height=\"576\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp\" data-id=\"4981\" class=\"wp-image-4981 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-3-18x10.webp 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" width=\"1024\" height=\"576\" alt=\"Fluoroplastic Centrifugal Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" data-id=\"4982\" class=\"wp-image-4982 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-18x10.webp 18w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column1075_961413-76 > .kt-inside-inner-col,.kadence-column1075_961413-76 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_961413-76 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_961413-76 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_961413-76 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_961413-76 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_961413-76{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_961413-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_961413-76 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_961413-76\"><div class=\"kt-inside-inner-col\">\n<h1 class=\"wp-block-heading has-large-font-size\">CYF Series Fluoroplastic Centrifugal Pump<\/h1>\n\n\n\n<p style=\"font-size:18px\"><strong>Corrosion-Resistant Chemical Pump for Acids, Alkalis &amp; Aggressive Liquids<\/strong><\/p>\n\n\n\n<p>CYF Series Fluoroplastic Centrifugal Pump is a single-stage single-suction chemical pump designed according to international standards and advanced non-metallic pump technology. Engineered with FEP, PFA, and PTFE fluoroplastic lining, it delivers outstanding corrosion resistance, stable operation, and long service life in highly aggressive industrial environments.<\/p>\n\n\n\n<p style=\"font-size:18px\">Suitable for transporting sulfuric acid, hydrochloric acid, nitric acid, hydrofluoric acid, alkalis, oxidizing agents, solvents, and corrosive wastewater.<\/p>\n\n\n<style>.kb-table-container1075_068411-0c{overflow-x:auto;}.kb-table1075_068411-0c td:nth-of-type(1), .kb-table1075_068411-0c th:nth-of-type(1){width:30%;}.kb-table1075_068411-0c{table-layout:fixed;width:100%;}.kb-table-container .kb-table1075_068411-0c th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table1075_068411-0c caption{text-align:center;}.kb-table-container .kb-table1075_068411-0c td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}.kb-table-container .kb-table1075_068411-0c tr:nth-of-type(odd){background-color:rgba(225,225,225,0.8);}.kb-table-container .kb-table1075_068411-0c td, .kb-table1075_068411-0c th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-table-container .kb-table1075_068411-0c td, .kb-table1075_068411-0c th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-table-container .kb-table1075_068411-0c td, .kb-table1075_068411-0c th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-table-container kb-table-container1075_068411-0c wp-block-kadence-table\"><table class=\"kb-table kb-table1075_068411-0c\">\n<tr class=\"kb-table-row kb-table-row1075_64bad1-de\">\n<th class=\"kb-table-data kb-table-data1075_51c2bc-24\">\n\n<p class=\"has-text-align-left\">Flow Rate Range :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1075_e2a386-0a\">\n\n<p>1.6 m\u00b3\/h-2600 m\u00b3\/h<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1075_7be34e-36\">\n<th class=\"kb-table-data kb-table-data1075_aa82b3-c0\">\n\n<p class=\"has-text-align-left\">Head Range: <\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1075_bd87b2-76\">\n\n<p>5 m-130 m<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1075_9c2e32-1c\">\n<th class=\"kb-table-data kb-table-data1075_21b3d8-48\">\n\n<p class=\"has-text-align-left\">Motor Power :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1075_bb7c04-12\">\n\n<p>1.5 kw-110 kw<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1075_bd0856-91\">\n<th class=\"kb-table-data kb-table-data1075_4e4055-22\">\n\n<p class=\"has-text-align-left\">Speed:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1075_bdaf2f-92\">\n\n<p class=\"has-text-align-left\">1450-2900 r\/min<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1075_a13b52-8f\">\n<th class=\"kb-table-data kb-table-data1075_94845b-96\">\n\n<p class=\"has-text-align-left\">Medium Temperature Range:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1075_f8f051-23\">\n\n<p>-20\u00b0C~180\u00b0C<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row1075_190f8c-fe\">\n<th class=\"kb-table-data kb-table-data1075_5475f0-13\">\n\n<p class=\"has-text-align-left\">Customizable Materials:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data1075_18df6d-b3\">\n\n<p>Steel lined with <a href=\"https:\/\/fluoropolymers.alfa-chemistry.com\/products\/fep-fluorinated-ethylene-propylene.html\" data-type=\"link\" data-id=\"https:\/\/fluoropolymers.alfa-chemistry.com\/products\/fep-fluorinated-ethylene-propylene.html\" target=\"_blank\" rel=\"noopener\">FEP<\/a>, PFA, or PTEF<\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n<style>.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{display:flex;}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{padding-left:0px;}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col,.kadence-column1075_c32a35-e2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_c32a35-e2{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_c32a35-e2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_c32a35-e2{position:relative;}.kadence-column1075_c32a35-e2, .kt-inside-inner-col > .kadence-column1075_c32a35-e2:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_c32a35-e2{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_c32a35-e2{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_c32a35-e2{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_c32a35-e2{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_c32a35-e2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_c32a35-e2\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1075_749083-6e .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1075_749083-6e .kt-blocks-modal-link:hover, #kt-modal1075_749083-6e .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1075_749083-6e .kt-modal-overlay, #kt-target-modal1075_749083-6e .kt-modal-overlay, .kb-modal-content1075_749083-6e .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1075_749083-6e .kt-modal-container, #kt-target-modal1075_749083-6e .kt-modal-container, .kb-modal-content1075_749083-6e .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1075_749083-6e .kt-modal-container, #kt-target-modal1075_749083-6e .kt-modal-container, .kb-modal-content1075_749083-6e .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1075_749083-6e .kt-modal-container, #kt-target-modal1075_749083-6e .kt-modal-container, .kb-modal-content1075_749083-6e .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1075_749083-6e .kt-modal-close svg, #kt-target-modal1075_749083-6e .kt-modal-close svg, .kb-modal-content1075_749083-6e .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1075_749083-6e .kt-modal-container, #kt-target-modal1075_749083-6e .kt-modal-container, .kb-modal-content1075_749083-6e .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1075_749083-6e .kt-modal-close svg, #kt-target-modal1075_749083-6e .kt-modal-close svg, .kb-modal-content1075_749083-6e .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1075_749083-6e .kt-modal-container, #kt-target-modal1075_749083-6e .kt-modal-container, .kb-modal-content1075_749083-6e .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1075_749083-6e .kt-modal-close svg, #kt-target-modal1075_749083-6e .kt-modal-close svg, .kb-modal-content1075_749083-6e .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1075_749083-6e\"><div id=\"kt-target-modal1075_749083-6e\" class=\"kb-modal-content1075_749083-6e kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1075_749083-6e-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1075_749083-6e\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_cd2354-a5 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_cd2354-a5 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_cd2354-a5 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_cd2354-a5 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_cd2354-a5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_cd2354-a5 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_cd2354-a5 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_c02a2b-01 > .kt-inside-inner-col,.kadence-column1075_c02a2b-01 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_c02a2b-01 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_c02a2b-01 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_c02a2b-01 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_c02a2b-01 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_c02a2b-01{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_c02a2b-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_c02a2b-01 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_c02a2b-01\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">What Is a Fluoroplastic Centrifugal Pump?<\/h2>\n\n\n\n<p>A fluoroplastic centrifugal pump is a corrosion-resistant chemical pump designed for transporting aggressive liquids that conventional metal pumps cannot safely handle. The CYF Series adopts a metal casing lined with high-performance fluoroplastics such as FEP, PFA, and PTFE to provide long-term resistance against highly corrosive chemicals.<\/p>\n\n\n\n<p>Fluoroplastic centrifugal pump impeller, pump body and other flow-through parts all adopt perfluorinated or fluorine-lined corrosion-isolating medium structures. The pump cover, impeller and shaft sleeve are all made of metal inserts wrapped with fluoroplastics and sintered and pressed as a whole. The flow-through pump shaft and sliding bearings adopt corrosion-resistant industrial ceramic structure, which has the characteristics of compact and reasonable structure, strong corrosion resistance, and strict and reliable sealing performance.<\/p>\n\n\n\n<p>The pump is widely used in industries requiring reliable transfer of acids, alkalis, solvents, and chemical wastewater.<\/p>\n\n\n<style>.kb-row-layout-id1075_4f0957-59 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_4f0957-59 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_4f0957-59 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1075_4f0957-59 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_4f0957-59 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_4f0957-59 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_4f0957-59 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_0111b0-04 > .kt-inside-inner-col,.kadence-column1075_0111b0-04 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_0111b0-04 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_0111b0-04 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_0111b0-04 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_0111b0-04 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_0111b0-04{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_0111b0-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_0111b0-04 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_0111b0-04\"><div class=\"kt-inside-inner-col\"><style>.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap .kt-video-svg-icon{color:#ffffff;}.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap .kt-video-svg-icon > svg{stroke-width:2;}.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap .kadence-video-overlay{opacity:0.3;;mix-blend-mode:none;;background:#000000;;}.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap:hover .kadence-video-overlay{opacity:0.5;;}.glightbox-kadence-dark.kadence-popup-1075_17940c-13 .goverlay{background:#000000;opacity:0.8;}.glightbox-container.kadence-popup-1075_17940c-13 .gclose path, .glightbox-container.kadence-popup-1075_17940c-13 .gnext path, .glightbox-container.kadence-popup-1075_17940c-13 .gprev path{fill:#ffffff;}.glightbox-container.kadence-popup-1075_17940c-13 .gslide-video, .glightbox-container.kadence-popup-1075_17940c-13 .gvideo-local{max-width:900px !important;}@media all and (max-width: 1024px){.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}@media all and (max-width: 767px){.kadence-video-popup1075_17940c-13 .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-videopopup kadence-video-popup1075_17940c-13\"><div class=\"kadence-video-popup-wrap kadence-video-noshadow\"><div class=\"kadence-video-intrinsic \"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" alt=\"Fluoroplastic Centrifugal Pump\" width=\"1200\" height=\"675\" class=\"kadence-video-poster wp-image-4982\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-18x10.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><div class=\"kadence-video-overlay\"><\/div><a class=\"kadence-video-popup-link kadence-video-type-external\" href=\"https:\/\/www.youtube.com\/watch?v=Kgpy2i-gRR4&amp;pp=0gcJCQMLAYcqIYzv\" role=\"button\" data-popup-class=\"kadence-popup-1075_17940c-13\" data-effect=\"none\" data-popup-id=\"kadence-local-video-1075_17940c-13\" data-popup-auto=\"true\" data-youtube-cookies=\"true\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_play kt-video-svg-icon kt-video-svg-icon-style-default kt-video-svg-icon-fas play kt-video-play-animation-none kt-video-svg-icon-size-auto\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Play<\/title><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"\/><\/svg><\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_983c7c-51 > .kt-inside-inner-col,.kadence-column1075_983c7c-51 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_983c7c-51 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_983c7c-51 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_983c7c-51 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_983c7c-51 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_983c7c-51{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_983c7c-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_983c7c-51 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_983c7c-51\"><div class=\"kt-inside-inner-col\"><style>.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap .kt-video-svg-icon{color:#ffffff;}.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap .kt-video-svg-icon > svg{stroke-width:2;}.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap .kadence-video-overlay{opacity:0.3;;mix-blend-mode:none;;background:#000000;;}.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap:hover .kadence-video-overlay{opacity:0.5;;}.glightbox-kadence-dark.kadence-popup-1075_87f0ba-bb .goverlay{background:#000000;opacity:0.8;}.glightbox-container.kadence-popup-1075_87f0ba-bb .gclose path, .glightbox-container.kadence-popup-1075_87f0ba-bb .gnext path, .glightbox-container.kadence-popup-1075_87f0ba-bb .gprev path{fill:#ffffff;}.glightbox-container.kadence-popup-1075_87f0ba-bb .gslide-video, .glightbox-container.kadence-popup-1075_87f0ba-bb .gvideo-local{max-width:900px !important;}@media all and (max-width: 1024px){.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}@media all and (max-width: 767px){.kadence-video-popup1075_87f0ba-bb .kadence-video-popup-wrap{border-top-color:rgba(255,255,255,0.8);border-top-style:solid;border-right-color:rgba(255,255,255,0.8);border-right-style:solid;border-bottom-color:rgba(255,255,255,0.8);border-bottom-style:solid;border-left-color:rgba(255,255,255,0.8);border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-videopopup kadence-video-popup1075_87f0ba-bb\"><div class=\"kadence-video-popup-wrap kadence-video-noshadow\"><div class=\"kadence-video-intrinsic \"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1.webp\" alt=\"Acid Resistant Pump\" width=\"1200\" height=\"675\" class=\"kadence-video-poster wp-image-4977\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Acid-Resistant-Pump-1-18x10.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><div class=\"kadence-video-overlay\"><\/div><a class=\"kadence-video-popup-link kadence-video-type-external\" href=\"https:\/\/www.youtube.com\/watch?v=dbeUOTMXpMM\" role=\"button\" data-popup-class=\"kadence-popup-1075_87f0ba-bb\" data-effect=\"none\" data-popup-id=\"kadence-local-video-1075_87f0ba-bb\" data-popup-auto=\"true\" data-youtube-cookies=\"true\" data-media-ratio=\"4:3\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fas_play kt-video-svg-icon kt-video-svg-icon-style-default kt-video-svg-icon-fas play kt-video-play-animation-none kt-video-svg-icon-size-auto\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  role=\"img\"><title>Play<\/title><path d=\"M424.4 214.7L72.4 6.6C43.8-10.3 0 6.1 0 47.9V464c0 37.5 40.7 60.1 72.4 41.3l352-208c31.4-18.5 31.5-64.1 0-82.6z\"\/><\/svg><\/span><\/a><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_1d5dda-8c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_1d5dda-8c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_1d5dda-8c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_1d5dda-8c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_1d5dda-8c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_1d5dda-8c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_1d5dda-8c alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col,.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_5d2f3f-84{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_5d2f3f-84 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_5d2f3f-84\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">CYF Fluoroplastic Centrifugal Pump Structure<\/h2>\n\n\n\n<p>Detailed specifications are listed below. For custom configurations or specific requirements, please <a href=\"https:\/\/changyupump.com\/contacts\/\" data-type=\"page\" data-id=\"17\">contact our technical team<\/a>.<\/p>\n\n\n<style>.kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list{margin-right:-10px;}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list li .kt-tab-title{margin-right:10px;}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #eeeeee);}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #EDF2F7);}.wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:#ffffff;background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}@media all and (max-width: 767px){.kt-tabs-id1075_1d2db0-f6 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id1075_1d2db0-f6 kt-tabs-has-2-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list kb-tabs-list-columns kb-tab-title-columns-6\"><li id=\"tab-strongstrongstrongpartsstrongstrongstrong\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-strongstrongstrongpartsstrongstrongstrong\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\"><strong><strong><strong>Parts<\/strong><\/strong><\/strong><\/span><\/a><\/li><li id=\"tab-strongstrongstrongspecificationsstrongstrongstrong\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-strongstrongstrongspecificationsstrongstrongstrong\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\"><strong><strong><strong>Specifications<\/strong><\/strong><\/strong><\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab1075_87f56b-71\"><div class=\"kt-tab-inner-content-inner\">\n<h2 class=\"wp-block-heading\">Part of Fluoroplastic Centrifugal Pump<\/h2>\n\n\n\n<p>The CYF Series Fluoroplastic Centrifugal Pump adopts a heavy-duty corrosion-resistant structural design specifically engineered for aggressive chemical transfer applications. Each core component is optimized for chemical compatibility, sealing reliability, mechanical strength, and long-term operational stability.<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"580\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/fluoroplastic-centrifugal-pump-parts-e1764903311318.webp\" alt=\"fluoroplastic centrifugal pump parts\" class=\"wp-image-1083\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/fluoroplastic-centrifugal-pump-parts-e1764903311318.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/fluoroplastic-centrifugal-pump-parts-e1764903311318-300x170.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/fluoroplastic-centrifugal-pump-parts-e1764903311318-768x435.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n<p>The pump casing adopts a metal shell with fluoroplastic lining for enhanced mechanical strength and corrosion resistance. The impeller and pump cover are molded with fluoroplastics and reinforced with metal inserts.<\/p>\n\n\n<style>.kb-row-layout-id1075_0673e7-ef > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_0673e7-ef > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_0673e7-ef > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(40% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(60% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1075_0673e7-ef > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_0673e7-ef > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_0673e7-ef > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_0673e7-ef alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_21f616-c3 > .kt-inside-inner-col,.kadence-column1075_21f616-c3 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_21f616-c3 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_21f616-c3 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_21f616-c3 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_21f616-c3 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_21f616-c3{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_21f616-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_21f616-c3 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_21f616-c3\"><div class=\"kt-inside-inner-col\">\n<p>The shaft seal uses an external bellows mechanical seal design:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stationary Ring: 99.9% alumina ceramic or silicon carbide<\/li>\n\n\n\n<li>Rotary Ring: PTFE-filled material or silicon carbide<\/li>\n<\/ul>\n\n\n\n<p>This structure provides:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Excellent chemical resistance<\/li>\n\n\n\n<li>Reliable sealing performance<\/li>\n\n\n\n<li>Stable operation<\/li>\n\n\n\n<li>Reduced leakage risks<\/li>\n\n\n\n<li>Extended service life<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_b028b0-6a > .kt-inside-inner-col,.kadence-column1075_b028b0-6a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_b028b0-6a > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_b028b0-6a > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_b028b0-6a > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_b028b0-6a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_b028b0-6a{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_b028b0-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_b028b0-6a > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_b028b0-6a\"><div class=\"kt-inside-inner-col\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"481\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Parts-of-Centrifugal-Pump-4-1024x481.webp\" alt=\"Parts of Centrifugal Pump\" class=\"wp-image-1653\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Parts-of-Centrifugal-Pump-4-1024x481.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Parts-of-Centrifugal-Pump-4-300x141.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Parts-of-Centrifugal-Pump-4-768x360.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Parts-of-Centrifugal-Pump-4.webp 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_62f2c2-9b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_62f2c2-9b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_62f2c2-9b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1075_62f2c2-9b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_62f2c2-9b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_62f2c2-9b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_62f2c2-9b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_f73949-cb > .kt-inside-inner-col,.kadence-column1075_f73949-cb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_f73949-cb > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_f73949-cb > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_f73949-cb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_f73949-cb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_f73949-cb{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_f73949-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_f73949-cb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_f73949-cb\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading\">Working Principle<\/h2>\n\n\n\n<p>The fluoroplastic lined centrifugal pump operates through centrifugal force generated by the rotating impeller.<\/p>\n\n\n\n<p>When the motor drives the impeller at high speed, liquid enters through the suction inlet and is accelerated outward by centrifugal force. The kinetic energy is converted into pressure energy inside the pump casing, allowing the liquid to be continuously delivered through the discharge pipeline.<\/p>\n\n\n\n<p>The fluoroplastic-lined flow passage protects the pump from corrosion while maintaining efficient and stable liquid transportation.<\/p>\n\n\n\n<p>This design enables the pump to safely handle:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Strong acids<\/li>\n\n\n\n<li>Strong alkalis<\/li>\n\n\n\n<li>Corrosive chemical liquids<\/li>\n\n\n\n<li>High-temperature chemical media<\/li>\n\n\n\n<li>Industrial wastewater<\/li>\n<\/ul>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_cd74e9-4b > .kt-inside-inner-col,.kadence-column1075_cd74e9-4b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_cd74e9-4b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_cd74e9-4b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_cd74e9-4b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_cd74e9-4b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_cd74e9-4b{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_cd74e9-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_cd74e9-4b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_cd74e9-4b\"><div class=\"kt-inside-inner-col\"><style>.kb-image1075_3b0f1f-45 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1075_3b0f1f-45 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"680\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-working-principle.webp\" alt=\"\" class=\"kb-img wp-image-1079\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-working-principle.webp 700w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-working-principle-300x291.webp 300w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><em><strong>Need a Reliable Fluoroplastic Centrifugal Pump Solution?<\/strong><br><\/em>Contact Changyu today for technical support, pump selection assistance, and customized quotations for your chemical transfer applications.<\/p>\n\n\n<style>.kb-row-layout-id1075_e0153d-eb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_e0153d-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_e0153d-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1075_e0153d-eb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_e0153d-eb > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_e0153d-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_e0153d-eb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_031cfc-6b > .kt-inside-inner-col{display:flex;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col,.kadence-column1075_031cfc-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_031cfc-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_031cfc-6b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_031cfc-6b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_031cfc-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_031cfc-6b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_031cfc-6b{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_031cfc-6b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_031cfc-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_031cfc-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_031cfc-6b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_031cfc-6b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_031cfc-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_031cfc-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_031cfc-6b\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +<a href=\"https:\/\/wa.me\/8613651913727\" data-type=\"link\" data-id=\"https:\/\/wa.me\/8613651913727\" target=\"_blank\" rel=\"noopener\">86-13651913727<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_de170a-af > .kt-inside-inner-col{display:flex;}.kadence-column1075_de170a-af > .kt-inside-inner-col,.kadence-column1075_de170a-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_de170a-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_de170a-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1075_de170a-af > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1075_de170a-af > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1075_de170a-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_de170a-af{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_de170a-af{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_de170a-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_de170a-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_de170a-af{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_de170a-af{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_de170a-af{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_de170a-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_de170a-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_de170a-af{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_de170a-af{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_de170a-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_de170a-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_de170a-af\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab1075_d2c813-2a\"><div class=\"kt-tab-inner-content-inner\">\n<h3 class=\"wp-block-heading\"><strong><strong>Technical Specifications of CYF Fluoroplastic Centrifugal Pump<\/strong><\/strong><\/h3>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th>Model Series<\/th><th>CYF Fluoroplastic Centrifugal Pump<\/th><\/tr><\/thead><tbody><tr><td>Pump Type<\/td><td>Single-stage Single-suction Centrifugal Pump<\/td><\/tr><tr><td>Flow Range<\/td><td>1.6 m\u00b3\/h \u2013 2600 m\u00b3\/h<\/td><\/tr><tr><td>Head Range<\/td><td>5 m \u2013 130 m<\/td><\/tr><tr><td>Motor Power<\/td><td>1.5 kW \u2013 110 kW<\/td><\/tr><tr><td>Speed<\/td><td>1450 \u2013 2900 r\/min<\/td><\/tr><tr><td>Temperature Range<\/td><td>-20\u00b0C to 180\u00b0C<\/td><\/tr><tr><td>Lining Materials<\/td><td>FEP \/ PFA \/ PTFE<\/td><\/tr><tr><td>Casing Structure<\/td><td>Metal Shell with Fluoroplastic Lining<\/td><\/tr><tr><td>Impeller Type<\/td><td>Closed \/ Semi-open<\/td><\/tr><tr><td>Seal Type<\/td><td>External Bellows Mechanical Seal<\/td><\/tr><tr><td>Stationary Ring Material<\/td><td>Alumina Ceramic \/ Silicon Carbide<\/td><\/tr><tr><td>Rotary Ring Material<\/td><td>PTFE Filled Material \/ Silicon Carbide<\/td><\/tr><tr><td>Shaft Material<\/td><td>High-strength Alloy Steel<\/td><\/tr><tr><td>Applicable Media<\/td><td>Acids, Alkalis, Solvents, Corrosive Liquids<\/td><\/tr><tr><td>Applications<\/td><td>Chemical, Electroplating, Pharmaceutical, Metallurgy, Wastewater Treatment<\/td><\/tr><tr><td>Installation Type<\/td><td>Horizontal<\/td><\/tr><tr><td>Customization<\/td><td>Material &amp; Seal Customization Available<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\">Notes<\/h4>\n\n\n\n<p>Below are further models of our pumps. If you are unsure how to select this Fluoroplastic Centrifugal Pump, please contact our team now; our technical specialists are on hand to provide you with a solution. Should you have further requirements, our factory also offers custom manufacturing services.<\/p>\n\n\n<style>.kb-row-layout-id1075_781f3a-1c > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_781f3a-1c > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_781f3a-1c > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1075_781f3a-1c > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_781f3a-1c > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_781f3a-1c > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_781f3a-1c alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_917b0c-03 > .kt-inside-inner-col{display:flex;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col,.kadence-column1075_917b0c-03 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_917b0c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_917b0c-03{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_917b0c-03{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_917b0c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_917b0c-03{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_917b0c-03{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_917b0c-03{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_917b0c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_917b0c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_917b0c-03{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_917b0c-03{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_917b0c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_917b0c-03 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_917b0c-03\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +<a href=\"https:\/\/wa.me\/8613651913727\" data-type=\"link\" data-id=\"https:\/\/wa.me\/8613651913727\" target=\"_blank\" rel=\"noopener\">86-13651913727<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_8bf39b-db > .kt-inside-inner-col{display:flex;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col,.kadence-column1075_8bf39b-db > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_8bf39b-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_8bf39b-db{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_8bf39b-db{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_8bf39b-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_8bf39b-db{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_8bf39b-db{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_8bf39b-db{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_8bf39b-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_8bf39b-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_8bf39b-db{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_8bf39b-db{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_8bf39b-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_8bf39b-db > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_8bf39b-db\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Specifications.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Sematan CYF Series Specifications.pdf.\"><\/object><a id=\"wp-block-file--media-be024dad-9668-4848-94a9-456db3d1add5\" href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Specifications.pdf\">CYF Series Specifications.pdf<\/a><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Specifications.pdf\" class=\"wp-block-file__button wp-element-button\" aria-describedby=\"wp-block-file--media-be024dad-9668-4848-94a9-456db3d1add5\" download>Download<\/a><\/div>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>2: Performance curve<\/strong><\/h3>\n\n\n<style>.kb-image1075_f619e4-64 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1075_f619e4-64 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1917\" height=\"2560\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-scaled.webp\" alt=\"\" class=\"kb-img wp-image-1089\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-scaled.webp 1917w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-225x300.webp 225w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-767x1024.webp 767w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-768x1026.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-1150x1536.webp 1150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Performance-curve-of-fluoroplastic-centrifugal-pump-1533x2048.webp 1533w\" sizes=\"auto, (max-width: 1917px) 100vw, 1917px\" \/><\/figure>\n<\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_7d8b7b-d9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_7d8b7b-d9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_7d8b7b-d9 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_7d8b7b-d9 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_7d8b7b-d9 > .kt-row-column-wrap{padding-top:80px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_7d8b7b-d9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_7d8b7b-d9 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_0e9f78-bc > .kt-inside-inner-col,.kadence-column1075_0e9f78-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_0e9f78-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_0e9f78-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_0e9f78-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_0e9f78-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_0e9f78-bc{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_0e9f78-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_0e9f78-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_0e9f78-bc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1075_90e4f4-3f, .wp-block-kadence-advancedheading.kt-adv-heading1075_90e4f4-3f[data-kb-block=\"kb-adv-heading1075_90e4f4-3f\"]{text-align:center;font-size:20px;font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading1075_90e4f4-3f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1075_90e4f4-3f[data-kb-block=\"kb-adv-heading1075_90e4f4-3f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1075_90e4f4-3f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1075_90e4f4-3f[data-kb-block=\"kb-adv-heading1075_90e4f4-3f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading1075_90e4f4-3f wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading1075_90e4f4-3f\">Why Choose It?<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1075_99cfe4-59, .wp-block-kadence-advancedheading.kt-adv-heading1075_99cfe4-59[data-kb-block=\"kb-adv-heading1075_99cfe4-59\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading1075_99cfe4-59 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1075_99cfe4-59[data-kb-block=\"kb-adv-heading1075_99cfe4-59\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1075_99cfe4-59 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1075_99cfe4-59[data-kb-block=\"kb-adv-heading1075_99cfe4-59\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1075_99cfe4-59 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1075_99cfe4-59\">Advantages of the Fluoroplastic Centrifugal Pump<\/h2>\n\n\n<style>.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id1075_4ff173-fb > .kt-row-layout-overlay{opacity:0.00;}@media all and (max-width: 1024px){.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1075_4ff173-fb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_4ff173-fb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col{display:flex;}.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col,.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_4cdc5d-24{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_4cdc5d-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_4cdc5d-24 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1075_7633d4-5c .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_7633d4-5c .kt-info-svg-icon-flip, .kt-info-box1075_7633d4-5c .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1075_7633d4-5c .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_7633d4-5c .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1075_7633d4-5c .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1075_7633d4-5c .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_7633d4-5c\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_aperture kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"14.31\" y1=\"8\" x2=\"20.05\" y2=\"17.94\"\/><line x1=\"9.69\" y1=\"8\" x2=\"21.17\" y2=\"8\"\/><line x1=\"7.38\" y1=\"12\" x2=\"13.12\" y2=\"2.06\"\/><line x1=\"9.69\" y1=\"16\" x2=\"3.95\" y2=\"6.06\"\/><line x1=\"14.31\" y1=\"16\" x2=\"2.83\" y2=\"16\"\/><line x1=\"16.62\" y1=\"12\" x2=\"10.88\" y2=\"21.94\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong><strong>Corrosion resistance<\/strong><\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">The metal housing is lined with FEP, and the metal inserts in the pump cover, impeller, and shaft sleeve are coated with fluoroplastic. The dynamic seal ring is filled with PTFE, providing resistance to various types of corrosion.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1075_31f179-69 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_31f179-69 .kt-info-svg-icon-flip, .kt-info-box1075_31f179-69 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1075_31f179-69 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_31f179-69 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1075_31f179-69 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1075_31f179-69 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_31f179-69\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_archive kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"21 8 21 21 3 21 3 8\"\/><rect x=\"1\" y=\"3\" width=\"22\" height=\"5\"\/><line x1=\"10\" y1=\"12\" x2=\"14\" y2=\"12\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong><strong>High-temperature resistant<\/strong><\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">The materials and structural design used can withstand high temperatures, meeting the demands of special working environments.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1075_06d786-6e .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_06d786-6e .kt-info-svg-icon-flip, .kt-info-box1075_06d786-6e .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1075_06d786-6e .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_06d786-6e .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1075_06d786-6e .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1075_06d786-6e .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_06d786-6e\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_settings kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"3\"\/><path d=\"M19.4 15a1.65 1.65 0 0 0 .33 1.82l.06.06a2 2 0 0 1 0 2.83 2 2 0 0 1-2.83 0l-.06-.06a1.65 1.65 0 0 0-1.82-.33 1.65 1.65 0 0 0-1 1.51V21a2 2 0 0 1-2 2 2 2 0 0 1-2-2v-.09A1.65 1.65 0 0 0 9 19.4a1.65 1.65 0 0 0-1.82.33l-.06.06a2 2 0 0 1-2.83 0 2 2 0 0 1 0-2.83l.06-.06a1.65 1.65 0 0 0 .33-1.82 1.65 1.65 0 0 0-1.51-1H3a2 2 0 0 1-2-2 2 2 0 0 1 2-2h.09A1.65 1.65 0 0 0 4.6 9a1.65 1.65 0 0 0-.33-1.82l-.06-.06a2 2 0 0 1 0-2.83 2 2 0 0 1 2.83 0l.06.06a1.65 1.65 0 0 0 1.82.33H9a1.65 1.65 0 0 0 1-1.51V3a2 2 0 0 1 2-2 2 2 0 0 1 2 2v.09a1.65 1.65 0 0 0 1 1.51 1.65 1.65 0 0 0 1.82-.33l.06-.06a2 2 0 0 1 2.83 0 2 2 0 0 1 0 2.83l-.06.06a1.65 1.65 0 0 0-.33 1.82V9a1.65 1.65 0 0 0 1.51 1H21a2 2 0 0 1 2 2 2 2 0 0 1-2 2h-.09a1.65 1.65 0 0 0-1.51 1z\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong><strong><strong><strong><strong>Easy to disassemble and inspect<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">The design facilitates maintenance, with components that are easy to disassemble and inspect, saving maintenance time and improving efficiency.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_221935-93 > .kt-inside-inner-col,.kadence-column1075_221935-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_221935-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_221935-93 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_221935-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_221935-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_221935-93{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_221935-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_221935-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_221935-93 inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image1075_b3d353-7d .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image1075_b3d353-7d img.kb-img, .kb-image1075_b3d353-7d .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;box-shadow:inset 0px 0px 60px -15px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image1075_b3d353-7d\"><figure class=\"aligncenter size-full kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"675\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp\" alt=\"Fluoroplastic Centrifugal Pump\" class=\"kb-img wp-image-4982\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-4-18x10.webp 18w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/><\/div><figcaption>Fluoroplastic Centrifugal Pump <\/figcaption><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_73cf82-ef > .kt-inside-inner-col{display:flex;}.kadence-column1075_73cf82-ef > .kt-inside-inner-col,.kadence-column1075_73cf82-ef > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_73cf82-ef > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_73cf82-ef > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_73cf82-ef > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_73cf82-ef > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_73cf82-ef{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_73cf82-ef > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_73cf82-ef > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_73cf82-ef inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1075_ce526e-50 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_ce526e-50 .kt-info-svg-icon-flip, .kt-info-box1075_ce526e-50 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1075_ce526e-50 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_ce526e-50 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1075_ce526e-50 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1075_ce526e-50 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_ce526e-50\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong><strong>Stable performance<\/strong><\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Advanced structural design and high-quality materials ensure smooth pump operation and continuous power supply.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1075_d7b28c-8f .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_d7b28c-8f .kt-info-svg-icon-flip, .kt-info-box1075_d7b28c-8f .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1075_d7b28c-8f .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_d7b28c-8f .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1075_d7b28c-8f .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_d7b28c-8f\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_cpu kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"4\" y=\"4\" width=\"16\" height=\"16\" rx=\"2\" ry=\"2\"\/><rect x=\"9\" y=\"9\" width=\"6\" height=\"6\"\/><line x1=\"9\" y1=\"1\" x2=\"9\" y2=\"4\"\/><line x1=\"15\" y1=\"1\" x2=\"15\" y2=\"4\"\/><line x1=\"9\" y1=\"20\" x2=\"9\" y2=\"23\"\/><line x1=\"15\" y1=\"20\" x2=\"15\" y2=\"23\"\/><line x1=\"20\" y1=\"9\" x2=\"23\" y2=\"9\"\/><line x1=\"20\" y1=\"14\" x2=\"23\" y2=\"14\"\/><line x1=\"1\" y1=\"9\" x2=\"4\" y2=\"9\"\/><line x1=\"1\" y1=\"14\" x2=\"4\" y2=\"14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong><strong>Wear-resistant<\/strong><\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">The stationary ring of the shaft seal is made of 99.9% alumina ceramic or silicon carbide, while the moving ring is filled with PTFE. These materials offer high hardness and low friction coefficients, reducing wear and extending service life.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box1075_cf6c93-30 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_cf6c93-30 .kt-info-svg-icon-flip, .kt-info-box1075_cf6c93-30 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box1075_cf6c93-30 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_cf6c93-30 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box1075_cf6c93-30 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_cf6c93-30\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_arrowRightCircle kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 16 16 12 12 8\"\/><line x1=\"8\" y1=\"12\" x2=\"16\" y2=\"12\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong><strong><strong><strong><strong><strong><strong><strong> Long service life:<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/h3><p class=\"kt-blocks-info-box-text\">The use of corrosion-resistant and wear-resistant materials, reasonable structural design, and stable performance extend the pump&#8217;s service life and reduce replacement costs.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_add57e-40 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_add57e-40 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_add57e-40 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_add57e-40 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_add57e-40 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_add57e-40 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_add57e-40 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_0dc718-1c > .kt-inside-inner-col,.kadence-column1075_0dc718-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_0dc718-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_0dc718-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_0dc718-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_0dc718-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_0dc718-1c{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_0dc718-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_0dc718-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_0dc718-1c\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1075_39482e-eb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_39482e-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_39482e-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_39482e-eb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_39482e-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_39482e-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_39482e-eb alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_4928c7-9f > .kt-inside-inner-col,.kadence-column1075_4928c7-9f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_4928c7-9f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_4928c7-9f > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_4928c7-9f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_4928c7-9f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_4928c7-9f{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_4928c7-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_4928c7-9f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_4928c7-9f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1075_61e2b2-6c, .wp-block-kadence-advancedheading.kt-adv-heading1075_61e2b2-6c[data-kb-block=\"kb-adv-heading1075_61e2b2-6c\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:36px;line-height:1.4;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1075_61e2b2-6c mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1075_61e2b2-6c[data-kb-block=\"kb-adv-heading1075_61e2b2-6c\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1075_61e2b2-6c img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1075_61e2b2-6c[data-kb-block=\"kb-adv-heading1075_61e2b2-6c\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading1075_61e2b2-6c wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1075_61e2b2-6c\">Application Industries<\/h2>\n\n\n\n<p class=\"has-text-align-center\" style=\"padding-right:3rem;padding-left:3rem\">The CYF Series Fluoroplastic Centrifugal Pump can continuously handle a wide range of highly corrosive and chemically aggressive media, including sulfuric acid, hydrochloric acid, hydrofluoric acid, nitric acid, aqua regia, strong alkalis, oxidizing agents, organic solvents, reducing agents, and corrosive wastewater. Its fluoroplastic-lined flow passages ensure stable operation and reliable corrosion resistance in harsh industrial environments.<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id1075_d33944-4f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id1075_d33944-4f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_d33944-4f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_dffb46-e1 > .kt-inside-inner-col,.kadence-column1075_dffb46-e1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_dffb46-e1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_dffb46-e1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_dffb46-e1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_dffb46-e1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_dffb46-e1{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_dffb46-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_dffb46-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_dffb46-e1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_ca34de-07 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_ca34de-07 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_ca34de-07.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1075_ca34de-07 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1075_ca34de-07 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:848px;height:0px;max-width:100%;}.kt-info-box1075_ca34de-07 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_ca34de-07 .kt-info-svg-icon-flip, .kt-info-box1075_ca34de-07 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1075_ca34de-07 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_ca34de-07 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1075_ca34de-07 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1075_ca34de-07 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1075_ca34de-07 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1075_ca34de-07 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1075_ca34de-07 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_ca34de-07\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Electroplating-and-metal-treatment.webp\" alt=\"Electroplating and metal treatment\" width=\"848\" height=\"566\" class=\"kt-info-box-image wp-image-2770\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Electroplating-and-metal-treatment.webp 848w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Electroplating-and-metal-treatment-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Electroplating-and-metal-treatment-768x513.webp 768w\" sizes=\"auto, (max-width: 848px) 100vw, 848px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Electroplating Industry<\/h3><p class=\"kt-blocks-info-box-text\">Suitable for acid circulation systems, plating chemical transfer, and corrosive wastewater handling.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_342f03-f2 > .kt-inside-inner-col,.kadence-column1075_342f03-f2 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_342f03-f2 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_342f03-f2 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_342f03-f2 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_342f03-f2 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_342f03-f2{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_342f03-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_342f03-f2 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_342f03-f2\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_8d1965-ac .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_8d1965-ac .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_8d1965-ac.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1075_8d1965-ac .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1075_8d1965-ac .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1080px;height:0px;max-width:100%;}.kt-info-box1075_8d1965-ac .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_8d1965-ac .kt-info-svg-icon-flip, .kt-info-box1075_8d1965-ac .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1075_8d1965-ac .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_8d1965-ac .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1075_8d1965-ac .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1075_8d1965-ac .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1075_8d1965-ac .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1075_8d1965-ac .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1075_8d1965-ac .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_8d1965-ac\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Chemical-Industry.webp\" alt=\"Chemical Industry\" width=\"1080\" height=\"693\" class=\"kt-info-box-image wp-image-2461\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Chemical-Industry.webp 1080w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Chemical-Industry-300x193.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Chemical-Industry-1024x657.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Chemical-Industry-768x493.webp 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Chemical Industry<\/h3><p class=\"kt-blocks-info-box-text\">Used for transferring acids, alkalis, solvents, and corrosive chemical solutions in chemical production plants.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_48db81-19 > .kt-inside-inner-col,.kadence-column1075_48db81-19 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_48db81-19 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_48db81-19 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_48db81-19 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_48db81-19 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_48db81-19{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_48db81-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_48db81-19 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_48db81-19\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_757765-e1 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_757765-e1 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_757765-e1.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1075_757765-e1 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1075_757765-e1 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1080px;height:0px;max-width:100%;}.kt-info-box1075_757765-e1 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_757765-e1 .kt-info-svg-icon-flip, .kt-info-box1075_757765-e1 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1075_757765-e1 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_757765-e1 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1075_757765-e1 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1075_757765-e1 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1075_757765-e1 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1075_757765-e1 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1075_757765-e1 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_757765-e1\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy.webp\" alt=\"HVAC and District Energy\" width=\"1080\" height=\"721\" class=\"kt-info-box-image wp-image-4473\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy.webp 1080w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-1024x684.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-768x513.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/04\/HVAC-and-District-Energy-18x12.webp 18w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Power &amp; Environment<\/h3><p class=\"kt-blocks-info-box-text\">Handles aggressive chemical media in desulfurization, refining, and chemical treatment systems.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_201502-b1 > .kt-inside-inner-col,.kadence-column1075_201502-b1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_201502-b1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_201502-b1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_201502-b1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_201502-b1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_201502-b1{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_201502-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_201502-b1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_201502-b1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box1075_4ae667-a8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_4ae667-a8.wp-block-kadence-infobox{max-width:100%;}.kt-info-box1075_4ae667-a8 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box1075_4ae667-a8 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:550px;height:0px;max-width:100%;}.kt-info-box1075_4ae667-a8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box1075_4ae667-a8 .kt-info-svg-icon-flip, .kt-info-box1075_4ae667-a8 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box1075_4ae667-a8 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box1075_4ae667-a8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box1075_4ae667-a8\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy.webp\" alt=\"Metallurgy\" width=\"550\" height=\"367\" class=\"kt-info-box-image wp-image-3262\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy.webp 550w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy-18x12.webp 18w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Metallurgy &amp; Pickling<\/h3><p class=\"kt-blocks-info-box-text\">Applicable for acid pickling lines and corrosive process liquid circulation.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading has-text-align-left\"><strong>Field Applications<\/strong>:<\/h2>\n\n\n<style>.kb-image1075_6ba867-6c .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image1075_6ba867-6c\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1300\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Fluoroplastic-Centrifugal-Pump-Application.webp\" alt=\"\" class=\"kb-img wp-image-1081\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Fluoroplastic-Centrifugal-Pump-Application.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Fluoroplastic-Centrifugal-Pump-Application-236x300.webp 236w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Fluoroplastic-Centrifugal-Pump-Application-807x1024.webp 807w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYF-Series-Fluoroplastic-Centrifugal-Pump-Application-768x975.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Fluoroplastic Centrifugal Pump Supplier In China<\/strong><\/h2>\n\n\n<style>.kb-row-layout-id1075_dda832-57 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_dda832-57 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_dda832-57 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1075_dda832-57 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_dda832-57 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_dda832-57 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_dda832-57 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_dfffdd-4e > .kt-inside-inner-col,.kadence-column1075_dfffdd-4e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_dfffdd-4e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_dfffdd-4e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_dfffdd-4e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_dfffdd-4e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_dfffdd-4e{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_dfffdd-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_dfffdd-4e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_dfffdd-4e\"><div class=\"kt-inside-inner-col\">\n<p><a href=\"https:\/\/changyupump.com\/about-us\/\" data-type=\"page\" data-id=\"16\">Changyu Pump<\/a> specializes in the design and manufacture of CYF Series Fluoroplastic Centrifugal Pumps, providing high-performance solutions for highly corrosive, high-temperature, and chemically aggressive fluid-transfer applications.<\/p>\n\n\n\n<p>With advanced CNC machining capabilities, precision fluoroplastic lining technology, and strict <a href=\"https:\/\/www.iso.org\/standard\/62085.html\" data-type=\"link\" data-id=\"https:\/\/www.iso.org\/standard\/62085.html\" target=\"_blank\" rel=\"noopener\">ISO<\/a>-based quality control systems, we ensure every pump delivers stable hydraulic performance, excellent corrosion resistance, and reliable long-term operation under demanding industrial conditions.<\/p>\n\n\n\n<p>The CYF series is engineered with a metal shell fully lined with FEP, PFA, or PTFE, combined with corrosion-resistant ceramic and silicon carbide sealing systems, making it suitable for chemical, electroplating, pharmaceutical, metallurgy, power generation, and wastewater treatment industries where conventional metal pumps fail due to corrosion or chemical attack.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col,.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_3ee0ed-89{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_3ee0ed-89 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_3ee0ed-89\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CHANGYU company introduce\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/WEFwgg-Bu8U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_f4b7c2-b6 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_f4b7c2-b6 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_f4b7c2-b6 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1075_f4b7c2-b6 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_f4b7c2-b6 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_f4b7c2-b6 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_f4b7c2-b6 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_c3d89b-95 > .kt-inside-inner-col,.kadence-column1075_c3d89b-95 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_c3d89b-95 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_c3d89b-95 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_c3d89b-95 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_c3d89b-95 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_c3d89b-95{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_c3d89b-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_c3d89b-95 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_c3d89b-95\"><div class=\"kt-inside-inner-col\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Looking for a high-performance Fluoroplastic Centrifugal Pump supplier in China?<\/h3>\n\n\n\n<p>Changyu provides reliable corrosion-resistant pump solutions for global industrial applications. Contact our engineering team today for product selection, technical consultation, and customized quotations.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col,.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_0cdbf7-a6{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_0cdbf7-a6 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_0cdbf7-a6\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1075_17fe15-26 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_17fe15-26 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_17fe15-26 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id1075_17fe15-26 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_17fe15-26 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1075_17fe15-26 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_17fe15-26 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{display:flex;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col,.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_bb9ab6-72{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_bb9ab6-72{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_bb9ab6-72{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_bb9ab6-72{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_bb9ab6-72{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_bb9ab6-72{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_bb9ab6-72{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_bb9ab6-72 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_bb9ab6-72\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +<a href=\"https:\/\/wa.me\/8613651913727\" data-type=\"link\" data-id=\"https:\/\/wa.me\/8613651913727\" target=\"_blank\" rel=\"noopener\">86-13651913727<\/a><\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_b0205a-15 > .kt-inside-inner-col{display:flex;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col,.kadence-column1075_b0205a-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_b0205a-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_b0205a-15{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_b0205a-15{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_b0205a-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_b0205a-15{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_b0205a-15{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_b0205a-15{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_b0205a-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_b0205a-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_b0205a-15{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_b0205a-15{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_b0205a-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_b0205a-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_b0205a-15\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_8f81d0-e2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_8f81d0-e2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_8f81d0-e2 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:942px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_8f81d0-e2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_8f81d0-e2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_8f81d0-e2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_8f81d0-e2 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1075_4b9aec-24 > .kt-inside-inner-col,.kadence-column1075_4b9aec-24 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_4b9aec-24 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_4b9aec-24 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_4b9aec-24 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_4b9aec-24 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_4b9aec-24{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_4b9aec-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_4b9aec-24 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_4b9aec-24\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">FAQs<\/h2>\n\n\n<style>.kt-accordion-id1075_cabe55-aa .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id1075_cabe55-aa .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;background:#ffffff;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #eeeeee;border-right:1px solid #eeeeee;border-bottom:1px solid #eeeeee;border-left:2px solid #eeeeee;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#ffffff;color:#444444;padding-top:14px;padding-right:16px;padding-bottom:14px;padding-left:16px;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa .kt-blocks-accordion-header:focus-visible{color:#444444;background:#ffffff;border-top-color:#878787;border-top-style:solid;border-right-color:#878787;border-right-style:solid;border-bottom-color:#878787;border-bottom-style:solid;border-left-color:#878787;border-left-style:solid;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id1075_cabe55-aa .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#444444;background:#ffffff;border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#0e9cd1;border-left-style:solid;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id1075_cabe55-aa:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}@media all and (max-width: 1024px){.kt-accordion-id1075_cabe55-aa .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #eeeeee;border-right:1px solid #eeeeee;border-bottom:1px solid #eeeeee;border-left:2px solid #eeeeee;}}@media all and (max-width: 1024px){.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa .kt-blocks-accordion-header:focus-visible{border-top-color:#878787;border-top-style:solid;border-right-color:#878787;border-right-style:solid;border-bottom-color:#878787;border-bottom-style:solid;border-left-color:#878787;border-left-style:solid;}}@media all and (max-width: 1024px){.kt-accordion-id1075_cabe55-aa .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#0e9cd1;border-left-style:solid;}}@media all and (max-width: 767px){.kt-accordion-id1075_cabe55-aa .kt-accordion-inner-wrap{display:block;}.kt-accordion-id1075_cabe55-aa .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id1075_cabe55-aa .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:1px solid transparent;border-bottom:1px solid transparent;border-left:1px solid transparent;}.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #eeeeee;border-right:1px solid #eeeeee;border-bottom:1px solid #eeeeee;border-left:2px solid #eeeeee;}.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id1075_cabe55-aa .kt-blocks-accordion-header:focus-visible{border-top-color:#878787;border-top-style:solid;border-right-color:#878787;border-right-style:solid;border-bottom-color:#878787;border-bottom-style:solid;border-left-color:#878787;border-left-style:solid;}.kt-accordion-id1075_cabe55-aa .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id1075_cabe55-aa > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top-color:#eeeeee;border-top-style:solid;border-right-color:#eeeeee;border-right-style:solid;border-bottom-color:#eeeeee;border-bottom-style:solid;border-left-color:#0e9cd1;border-left-style:solid;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id1075_cabe55-aa kt-accordion-has-6-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-arrow kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"0\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane1075_6655e1-21\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What chemicals can a fluoroplastic centrifugal pump handle?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>It can handle strong acids, alkalis, oxidizing agents, organic solvents, and highly corrosive industrial liquids.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane1075_71808a-e0\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What is the temperature range of the CYF pump?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>The operating temperature range is from -20\u00b0C to 180\u00b0C.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane1075_062a0b-c2\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">What fluoroplastic materials are available?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>FEP, PFA, and PTFE lining materials are available depending on the application requirements.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-4 kt-pane1075_956abb-5c\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Is the pump suitable for continuous industrial operation?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Yes. The CYF Series is designed for long-term continuous operation in harsh industrial environments.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-5 kt-pane1075_88ee05-e1\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Can the pump be customized?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<p>Yes. Material selection, sealing systems, motor configurations, and operating parameters can all be customized according to project requirements.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Factory Show<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-1075_7a75d6-22{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-1075_7a75d6-22 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-1075_7a75d6-22 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-1075_7a75d6-22 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-1075_7a75d6-22 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-1075_7a75d6-22 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"5\" data-columns-xl=\"5\" data-columns-md=\"5\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-id=\"954\" class=\"wp-image-954\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" width=\"900\" height=\"529\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-id=\"959\" class=\"wp-image-959\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-300x176.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-768x451.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-id=\"927\" class=\"wp-image-927\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-id=\"921\" class=\"wp-image-921\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-id=\"930\" class=\"wp-image-930\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-id=\"940\" class=\"wp-image-940\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" width=\"900\" height=\"506\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-id=\"945\" class=\"wp-image-945\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-id=\"926\" class=\"wp-image-926\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-id=\"944\" class=\"wp-image-944\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" width=\"900\" height=\"504\" alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-id=\"949\" class=\"wp-image-949\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-768x430.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n<style>.kb-image1075_f479f6-1a .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1075_f479f6-1a size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"838\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-2.webp\" alt=\"\" class=\"kb-img wp-image-1077\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-2.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-2-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-2-1024x572.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-2-768x429.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n<style>.kb-image1075_5e2c40-c3 .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1075_5e2c40-c3 size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"703\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-1.webp\" alt=\"\" class=\"kb-img wp-image-1080\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-1.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-1-300x141.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-1-1024x480.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-1-768x360.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n<style>.kb-row-layout-id1075_70f067-eb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_70f067-eb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_70f067-eb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1075_70f067-eb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_70f067-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_70f067-eb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_70f067-eb alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col,.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_9eb3b1-27{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_9eb3b1-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_9eb3b1-27\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Blog<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_81be48-13 > .kt-inside-inner-col,.kadence-column1075_81be48-13 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_81be48-13 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_81be48-13 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_81be48-13 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_81be48-13 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_81be48-13{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_81be48-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_81be48-13 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_81be48-13\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop1075_54f76e-18 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop1075_54f76e-18 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop1075_54f76e-18 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-post-loop1075_54f76e-18 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop1075_54f76e-18 .entry-content:after{height:0px;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop1075_54f76e-18 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop1075_54f76e-18 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop1075_54f76e-18.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop1075_54f76e-18 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-832 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/fluoroplastic-pump-for-caustic-soda\/\" aria-label=\"Fluoroplastic centrifugal pumps can easily cope with the problem of caustic soda transportation\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Fluoroplastic-centrifugal-pumps-can-easily-cope-with-the-problem-of-caustic-soda-transportation-1024x1024.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Fluoroplastic centrifugal pumps can easily cope with the problem of caustic soda transportation\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Fluoroplastic-centrifugal-pumps-can-easily-cope-with-the-problem-of-caustic-soda-transportation-1024x1024.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Fluoroplastic-centrifugal-pumps-can-easily-cope-with-the-problem-of-caustic-soda-transportation-300x300.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Fluoroplastic-centrifugal-pumps-can-easily-cope-with-the-problem-of-caustic-soda-transportation-150x150.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Fluoroplastic-centrifugal-pumps-can-easily-cope-with-the-problem-of-caustic-soda-transportation-768x768.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Fluoroplastic-centrifugal-pumps-can-easily-cope-with-the-problem-of-caustic-soda-transportation.webp 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/fluoroplastic-pump-for-caustic-soda\/\">Fluoroplastic centrifugal pumps can easily cope with the problem of caustic soda transportation<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4872 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-centrifugal-pump tag-chemical-pump tag-industrial-centrifugal-pumps tag-industrial-pump-selection tag-industrial-series-centrifugal-pumps\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/industrial-series-centrifugal-pumps-the-complete-selection-application-guide\/\" aria-label=\"Industrial Series Centrifugal Pumps: The Complete Selection &amp; Application Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Industrial-Series-Centrifugal-Pumps.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Industrial-Series-Centrifugal-Pumps\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Industrial-Series-Centrifugal-Pumps.webp 1000w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Industrial-Series-Centrifugal-Pumps-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Industrial-Series-Centrifugal-Pumps-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Industrial-Series-Centrifugal-Pumps-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Industrial-Series-Centrifugal-Pumps-16x12.webp 16w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/industrial-series-centrifugal-pumps-the-complete-selection-application-guide\/\">Industrial Series Centrifugal Pumps: The Complete Selection &amp; Application Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/centrifugal-pump\/\" rel=\"tag\">centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/industrial-centrifugal-pumps\/\" rel=\"tag\">Industrial Centrifugal Pumps<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/industrial-pump-selection\/\" rel=\"tag\">industrial pump selection<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/industrial-series-centrifugal-pumps\/\" rel=\"tag\">Industrial Series Centrifugal Pumps<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4158 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-process-pump tag-heavy-duty-centrifugal-pump tag-heavy-duty-magnetic-pump tag-stainless-steel-heavy-duty-pump tag-teflon-lined-heavy-duty-pump tag-zero-leakage-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/heavy-duty-centrifugal-pump-selection-guide-2026-sizing-specs\/\" aria-label=\"Heavy Duty Centrifugal Pump Selection Guide 2026: Sizing &amp; Specs\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"CYQ Series Horizontal Heavy-Duty TEFLON Lined Magnetic Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-Series-Horizontal-Heavy-Duty-TEFLON-Lined-Magnetic-Pump-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/heavy-duty-centrifugal-pump-selection-guide-2026-sizing-specs\/\">Heavy Duty Centrifugal Pump Selection Guide 2026: Sizing &amp; Specs<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-process-pump\/\" rel=\"tag\">chemical process pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/heavy-duty-centrifugal-pump\/\" rel=\"tag\">heavy duty centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/heavy-duty-magnetic-pump\/\" rel=\"tag\">heavy duty magnetic pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/stainless-steel-heavy-duty-pump\/\" rel=\"tag\">stainless steel heavy duty pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/teflon-lined-heavy-duty-pump\/\" rel=\"tag\">teflon lined heavy duty pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/zero-leakage-pump\/\" rel=\"tag\">zero leakage pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4172 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-transfer-pump tag-chemical-pump tag-chemical-transfer-pump tag-heavy-duty-centrifugal-pump tag-heavy-duty-centrifugal-pumps tag-heavy-duty-process-pump tag-industrial-use-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/heavy-duty-centrifugal-pumps-for-industrial-use-2026-guide\/\" aria-label=\"Heavy Duty Centrifugal Pumps for Industrial Use 2026 Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Stainless Steel Magnetic Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Stainless-Steel-Magnetic-Pump-7.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/heavy-duty-centrifugal-pumps-for-industrial-use-2026-guide\/\">Heavy Duty Centrifugal Pumps for Industrial Use 2026 Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-transfer-pump\/\" rel=\"tag\">Chemical Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/heavy-duty-centrifugal-pump\/\" rel=\"tag\">heavy duty centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/heavy-duty-centrifugal-pumps\/\" rel=\"tag\">heavy duty centrifugal pumps<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/heavy-duty-process-pump\/\" rel=\"tag\">heavy duty process pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/industrial-use-pump\/\" rel=\"tag\">industrial use pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4153 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-high-pressure-water-pump tag-multistage-booster-pump tag-vertical-multistage-centrifugal-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/vertical-multistage-centrifugal-pump-guide-2026-sizing-specs\/\" aria-label=\"Vertical Multistage Centrifugal Pump Guide 2026: Sizing &amp; Specs\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"vertical multistage centrifugal pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/vertical-multistage-centrifugal-pump-2-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/vertical-multistage-centrifugal-pump-guide-2026-sizing-specs\/\">Vertical Multistage Centrifugal Pump Guide 2026: Sizing &amp; Specs<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/high-pressure-water-pump\/\" rel=\"tag\">high pressure water pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/multistage-booster-pump\/\" rel=\"tag\">multistage booster pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/vertical-multistage-centrifugal-pump\/\" rel=\"tag\">vertical multistage centrifugal pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4206 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-single-stage-centrifugal-pump tag-single-stage-chemical-centrifugal-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/single-stage-centrifugal-pump-types-and-selection-guide-2026\/\" aria-label=\"Single Stage Centrifugal Pump: Types and Selection Guide 2026\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"PTFEPFA Chemical Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-300x300.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-150x150.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-768x768.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/PTFEPFA-Chemical-Pump-3-12x12.webp 12w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/single-stage-centrifugal-pump-types-and-selection-guide-2026\/\">Single Stage Centrifugal Pump: Types and Selection Guide 2026<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/single-stage-centrifugal-pump\/\" rel=\"tag\">single stage centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/single-stage-chemical-centrifugal-pump\/\" rel=\"tag\">single stage chemical centrifugal pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4201 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-self-priming-pump tag-industrial-self-priming-pump tag-self-priming-centrifugal-pump tag-self-priming-centrifugal-pump-2 tag-what-is-a-self-priming-centrifugal-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/what-is-a-self-priming-centrifugal-pump-a-complete-guide-2026\/\" aria-label=\"What is a Self-Priming Centrifugal Pump? A Complete Guide 2026\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"751\" height=\"537\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Self-Priming-Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10.webp 751w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10-300x215.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10-150x107.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/FZB-Fluoroplastic-Self-Priming-Pump-for-Corrosive-Chemical-Transfer-10-18x12.webp 18w\" sizes=\"auto, (max-width: 751px) 100vw, 751px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/what-is-a-self-priming-centrifugal-pump-a-complete-guide-2026\/\">What is a Self-Priming Centrifugal Pump? A Complete Guide 2026<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-self-priming-pump\/\" rel=\"tag\">chemical self priming pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/industrial-self-priming-pump\/\" rel=\"tag\">industrial self priming pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/self-priming-centrifugal-pump\/\" rel=\"tag\">self priming centrifugal pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/self-priming-centrifugal-pump-2\/\" rel=\"tag\">Self-Priming Centrifugal Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/what-is-a-self-priming-centrifugal-pump\/\" rel=\"tag\">what is a self priming centrifugal pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4086 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-ptfe-centrifugal-pump tag-ptfe-chemical-pump tag-ptfe-lined-centrifugal-pump tag-ptfe-magnetic-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/the-best-ptfe-lined-centrifugal-pump-for-corrosive-liquids\/\" aria-label=\"the Best PTFE Lined Centrifugal Pump for Corrosive Liquids\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/IHF-Series-Fluorine-Plastic-Lined-Centrifugal-Pump-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"IHF Series Fluorine Plastic Lined Centrifugal Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/IHF-Series-Fluorine-Plastic-Lined-Centrifugal-Pump-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/IHF-Series-Fluorine-Plastic-Lined-Centrifugal-Pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/IHF-Series-Fluorine-Plastic-Lined-Centrifugal-Pump-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/IHF-Series-Fluorine-Plastic-Lined-Centrifugal-Pump.webp 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/the-best-ptfe-lined-centrifugal-pump-for-corrosive-liquids\/\">the Best PTFE Lined Centrifugal Pump for Corrosive Liquids<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/ptfe-centrifugal-pump\/\" rel=\"tag\">PTFE Centrifugal Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/ptfe-chemical-pump\/\" rel=\"tag\">PTFE chemical pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/ptfe-lined-centrifugal-pump\/\" rel=\"tag\">PTFE Lined Centrifugal Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/ptfe-magnetic-pump\/\" rel=\"tag\">PTFE magnetic pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4493 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-transfer-pump tag-fluorine-lined-pump-2 tag-fluoroplastic-pump tag-magnetic-drive-fluorine-pump tag-pfa-lined-pump tag-ptfe-lined-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/top-5-fluorine-lined-pumps-for-corrosive-chemical-applications\/\" aria-label=\"Top 5 Fluorine Lined Pumps for Corrosive Chemical Applications\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Ultra-high-molecular-weight-polyethylene-fluorine-lined-centrifugal-pump_-the-optimal-engineering-solution-for-sodium-chlorate-transportation-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Ultra-high-molecular-weight-polyethylene-fluorine-lined-centrifugal-pump_-the-optimal-engineering-solution-for-sodium-chlorate-transportation-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Ultra-high-molecular-weight-polyethylene-fluorine-lined-centrifugal-pump_-the-optimal-engineering-solution-for-sodium-chlorate-transportation-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Ultra-high-molecular-weight-polyethylene-fluorine-lined-centrifugal-pump_-the-optimal-engineering-solution-for-sodium-chlorate-transportation-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Ultra-high-molecular-weight-polyethylene-fluorine-lined-centrifugal-pump_-the-optimal-engineering-solution-for-sodium-chlorate-transportation.webp 1140w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/top-5-fluorine-lined-pumps-for-corrosive-chemical-applications\/\">Top 5 Fluorine Lined Pumps for Corrosive Chemical Applications<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/fluorine-lined-pump-2\/\" rel=\"tag\">fluorine lined pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/fluoroplastic-pump\/\" rel=\"tag\">Fluoroplastic Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/magnetic-drive-fluorine-pump\/\" rel=\"tag\">magnetic drive fluorine pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/pfa-lined-pump\/\" rel=\"tag\">PFA lined pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/ptfe-lined-pump\/\" rel=\"tag\">PTFE lined pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3798 post type-post status-publish format-standard has-post-thumbnail hentry category-blog\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/ptfe-lined-pump-vs-stainless-steel-pump\/\" aria-label=\"PTFE Lined Pump vs Stainless Steel Pump\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/PTFE-lined-pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"PTFE lined pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/PTFE-lined-pump.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/PTFE-lined-pump-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/PTFE-lined-pump-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/PTFE-lined-pump-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/PTFE-lined-pump-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/ptfe-lined-pump-vs-stainless-steel-pump\/\">PTFE Lined Pump vs Stainless Steel Pump<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/jadechangyupump-com\/\" class=\"kt-blocks-post-author-link fn\">jade@changyupump.com<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4545 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-transfer-pump tag-fluosilicic-acid-pump tag-hydrofluosilicic-acid-pump tag-magnetic-drive-acid-pump tag-water-treatment-chemical-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/how-to-choose-a-fluosilicic-acid-pump-for-water-treatment\/\" aria-label=\"How to Choose a Fluosilicic Acid Pump for Water Treatment\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"slurry pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/slurry-pump-for-sulfuric-acid-7.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/how-to-choose-a-fluosilicic-acid-pump-for-water-treatment\/\">How to Choose a Fluosilicic Acid Pump for Water Treatment<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-transfer-pump\/\" rel=\"tag\">Chemical Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/fluosilicic-acid-pump\/\" rel=\"tag\">Fluosilicic acid pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/hydrofluosilicic-acid-pump\/\" rel=\"tag\">Hydrofluosilicic acid pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/magnetic-drive-acid-pump\/\" rel=\"tag\">magnetic drive acid pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/water-treatment-chemical-pump\/\" rel=\"tag\">Water treatment chemical pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-4327 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-magnetic-pump tag-fluorine-lined-pump tag-hf-transfer-pump tag-hydrofluoric-acid-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/hydrofluoric-acid-pump-materials-safety-selection-guide\/\" aria-label=\"Hydrofluoric Acid Pump: Materials, Safety &amp; Selection Guide\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Acid-Centrifugal-Transfer-Pump-5-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Acid Centrifugal Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Acid-Centrifugal-Transfer-Pump-5-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Acid-Centrifugal-Transfer-Pump-5-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Acid-Centrifugal-Transfer-Pump-5-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Acid-Centrifugal-Transfer-Pump-5-1536x1152.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Acid-Centrifugal-Transfer-Pump-5.webp 1900w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/hydrofluoric-acid-pump-materials-safety-selection-guide\/\">Hydrofluoric Acid Pump: Materials, Safety &amp; Selection Guide<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-magnetic-pump\/\" rel=\"tag\">Chemical Magnetic Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/fluorine-lined-pump\/\" rel=\"tag\">fluorine-lined pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/hf-transfer-pump\/\" rel=\"tag\">HF transfer pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/hydrofluoric-acid-pump\/\" rel=\"tag\">Hydrofluoric Acid Pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3914 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-transfer-pump tag-chemical-pump tag-hydrofluoric-acid-pump tag-hydrofluoric-pump\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/hydrofluoric-acid-pump-selection-guide-zero-leakage-safe-transfer\/\" aria-label=\"Hydrofluoric Acid Pump Selection Guide: Zero-Leakage &amp; Safe Transfer\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"675\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Magnetic-Pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Magnetic Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Magnetic-Pump.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Magnetic-Pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Magnetic-Pump-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Magnetic-Pump-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2022\/06\/Magnetic-Pump-16x12.webp 16w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/hydrofluoric-acid-pump-selection-guide-zero-leakage-safe-transfer\/\">Hydrofluoric Acid Pump Selection Guide: Zero-Leakage &amp; Safe Transfer<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/hydrofluoric-acid-pump\/\" rel=\"tag\">Hydrofluoric Acid Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/hydrofluoric-pump\/\" rel=\"tag\">Hydrofluoric Pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1075_6dd8dc-09 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1075_6dd8dc-09 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1075_6dd8dc-09 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id1075_6dd8dc-09 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1075_6dd8dc-09 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1075_6dd8dc-09 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1075_6dd8dc-09 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1075_d6c045-6b > .kt-inside-inner-col{display:flex;}.kadence-column1075_d6c045-6b > .kt-inside-inner-col,.kadence-column1075_d6c045-6b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_d6c045-6b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_d6c045-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_d6c045-6b > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1075_d6c045-6b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_d6c045-6b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_d6c045-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_d6c045-6b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_d6c045-6b{text-align:left;}.kadence-column1075_d6c045-6b{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1075_d6c045-6b{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_d6c045-6b{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_d6c045-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1075_d6c045-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1075_d6c045-6b{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_d6c045-6b{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1075_d6c045-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1075_d6c045-6b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_d6c045-6b kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4, .wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4[data-kb-block=\"kb-adv-heading1075_502a47-d4\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4[data-kb-block=\"kb-adv-heading1075_502a47-d4\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4[data-kb-block=\"kb-adv-heading1075_502a47-d4\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4, .wp-block-kadence-advancedheading.kt-adv-heading1075_502a47-d4[data-kb-block=\"kb-adv-heading1075_502a47-d4\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading1075_502a47-d4 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1075_502a47-d4\">Request a free quote<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1075_42bf5d-71, .wp-block-kadence-advancedheading.kt-adv-heading1075_42bf5d-71[data-kb-block=\"kb-adv-heading1075_42bf5d-71\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1075_42bf5d-71 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1075_42bf5d-71[data-kb-block=\"kb-adv-heading1075_42bf5d-71\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1075_42bf5d-71 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1075_42bf5d-71[data-kb-block=\"kb-adv-heading1075_42bf5d-71\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1075_42bf5d-71 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1075_42bf5d-71\">Please fill in the details of your pumped liquid, including flow, head, specific gravity, and temperature, so we can recommend the best pump and provide a precise quote.<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1075_ab2004-a6:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1075_ab2004-a6 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:var(--global-kb-spacing-sm, 1.5rem);margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1075_ab2004-a6 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1075_ab2004-a6 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1075_ab2004-a6 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1075_ab2004-a6 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1075_4534ca-68 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1075_4534ca-68\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Customized Pump Solutions<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1075_cd822e-61 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1075_cd822e-61\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_users kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M17 21v-2a4 4 0 0 0-4-4H5a4 4 0 0 0-4 4v2\"\/><circle cx=\"9\" cy=\"7\" r=\"4\"\/><path d=\"M23 21v-2a4 4 0 0 0-3-3.87\"\/><path d=\"M16 3.13a4 4 0 0 1 0 7.75\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fast Quotation within 24 hours<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1075_11efe2-75 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1075_11efe2-75\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_feather kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20.24 12.24a6 6 0 0 0-8.49-8.49L5 10.5V19h8.5z\"\/><line x1=\"16\" y1=\"8\" x2=\"2\" y2=\"22\"\/><line x1=\"17\" y1=\"15\" x2=\"9\" y2=\"15\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Factory Direct with Competitive Price<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1075_41590a-f5 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1075_41590a-f5\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_settings kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"3\"\/><path d=\"M19.4 15a1.65 1.65 0 0 0 .33 1.82l.06.06a2 2 0 0 1 0 2.83 2 2 0 0 1-2.83 0l-.06-.06a1.65 1.65 0 0 0-1.82-.33 1.65 1.65 0 0 0-1 1.51V21a2 2 0 0 1-2 2 2 2 0 0 1-2-2v-.09A1.65 1.65 0 0 0 9 19.4a1.65 1.65 0 0 0-1.82.33l-.06.06a2 2 0 0 1-2.83 0 2 2 0 0 1 0-2.83l.06-.06a1.65 1.65 0 0 0 .33-1.82 1.65 1.65 0 0 0-1.51-1H3a2 2 0 0 1-2-2 2 2 0 0 1 2-2h.09A1.65 1.65 0 0 0 4.6 9a1.65 1.65 0 0 0-.33-1.82l-.06-.06a2 2 0 0 1 0-2.83 2 2 0 0 1 2.83 0l.06.06a1.65 1.65 0 0 0 1.82.33H9a1.65 1.65 0 0 0 1-1.51V3a2 2 0 0 1 2-2 2 2 0 0 1 2 2v.09a1.65 1.65 0 0 0 1 1.51 1.65 1.65 0 0 0 1.82-.33l.06-.06a2 2 0 0 1 2.83 0 2 2 0 0 1 0 2.83l-.06.06a1.65 1.65 0 0 0-.33 1.82V9a1.65 1.65 0 0 0 1.51 1H21a2 2 0 0 1 2 2 2 2 0 0 1-2 2h-.09a1.65 1.65 0 0 0-1.51 1z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Professional engineers, one-on-one technical consultation<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1075_698048-18 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1075_698048-18\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_award kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"8\" r=\"7\"\/><polyline points=\"8.21 13.89 7 23 12 20 17 23 15.79 13.88\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">CE\/ISO certified pumps with strict testing before shipment<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.kadence-column1075_1871bc-73 > .kt-inside-inner-col{display:flex;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col,.kadence-column1075_1871bc-73 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1075_1871bc-73 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col > *, .kadence-column1075_1871bc-73 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1075_1871bc-73 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_1871bc-73{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_1871bc-73 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1075_1871bc-73 > .kt-inside-inner-col > *, .kadence-column1075_1871bc-73 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1075_1871bc-73 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column1075_1871bc-73 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col > *, .kadence-column1075_1871bc-73 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1075_1871bc-73 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1075_1871bc-73 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_1871bc-73 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3, .wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3[data-kb-block=\"kb-adv-heading1075_22cfbb-e3\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3[data-kb-block=\"kb-adv-heading1075_22cfbb-e3\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3[data-kb-block=\"kb-adv-heading1075_22cfbb-e3\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3, .wp-block-kadence-advancedheading.kt-adv-heading1075_22cfbb-e3[data-kb-block=\"kb-adv-heading1075_22cfbb-e3\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading1075_22cfbb-e3 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1075_22cfbb-e3\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons1075_bcb3ce-1a .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons1075_bcb3ce-1a{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons1075_bcb3ce-1a{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons1075_bcb3ce-1a alignnone\"><style>.kt-svg-item-1075_cd0854-1e .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1075_cd0854-1e .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:20px;}.kt-svg-item-1075_cd0854-1e:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1075_cd0854-1e\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=61564021046258\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1075_ebd4dd-2a .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1075_ebd4dd-2a .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:17px;}.kt-svg-item-1075_ebd4dd-2a:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1075_ebd4dd-2a\"><a href=\"https:\/\/www.instagram.com\/changyupump\/\" class=\"kt-svg-icon-link\" aria-label=\"Ins\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_instagram\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"2\" y=\"2\" width=\"20\" height=\"20\" rx=\"5\" ry=\"5\"\/><path d=\"M16 11.37A4 4 0 1 1 12.63 8 4 4 0 0 1 16 11.37z\"\/><line x1=\"17.5\" y1=\"6.5\" x2=\"17.5\" y2=\"6.5\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1075_01e5f4-28 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1075_01e5f4-28 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}.kt-svg-item-1075_01e5f4-28:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1075_01e5f4-28\"><a href=\"https:\/\/www.youtube.com\/@Changyu-CY\" class=\"kt-svg-icon-link\" aria-label=\"Youtube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1075_05f066-07 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1075_05f066-07 > .kt-inside-inner-col,.kadence-column1075_05f066-07 > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column1075_05f066-07 > .kt-inside-inner-col{column-gap:0px;}.kadence-column1075_05f066-07 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1075_05f066-07 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1075_05f066-07 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column1075_05f066-07 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1075_05f066-07{text-align:left;}.kadence-column1075_05f066-07{position:relative;}@media all and (max-width: 1024px){.kadence-column1075_05f066-07 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1075_05f066-07 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1075_05f066-07 kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-1075_4c7714-e0 .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-1075_4c7714-e0 .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-1075_4c7714-e0 .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;background:var(--global-palette2, #2B6CB0);}.kadence-form-1075_4c7714-e0 .kb-form .kadence-blocks-form-field .kb-forms-submit:hover, .kadence-form-1075_4c7714-e0 .kb-form .kadence-blocks-form-field .kb-forms-submit:focus {background:#019141;}.kadence-form-1075_4c7714-e0 .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-1075_4c7714-e0 kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_1075_4c7714-e0_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_1075_4c7714-e0_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Address\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_1075_4c7714-e0_2\" data-label=\"Phone\/WA\" type=\"text\" placeholder=\"Phone\/WA\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_3\" id=\"kb_field_1075_4c7714-e0_3\" data-label=\"Country\" type=\"text\" placeholder=\"Country\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-3\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-4 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_4\" id=\"kb_field_1075_4c7714-e0_4\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-4\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"1075_4c7714-e0\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"1075\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\"><strong>Send Your Inquiry Now<\/strong><\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-1075_4c7714-e0 .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CYF Fluoroplastic Centrifugal Pump is designed for handling highly corrosive chemicals such as acids, alkalis, solvents and wastewater. With FEP, PFA or PTFE lined flow parts, it delivers excellent corrosion resistance, stable operation and long service life. Widely used in chemical, electroplating, pharmaceutical, metallurgy and wastewater treatment industries. Direct China manufacturer supply with customization support.<\/p>","protected":false},"featured_media":4979,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"show","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"class_list":["post-1075","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/changyupump.com\/wp-content\/uploads\/2026\/05\/Fluoroplastic-Centrifugal-Pump-1-1024x768.webp",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/product\/1075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/media\/4979"}],"wp:attachment":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/media?parent=1075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}