{"id":4016,"date":"2026-03-25T03:33:52","date_gmt":"2026-03-25T03:33:52","guid":{"rendered":"https:\/\/changyupump.com\/?post_type=product&#038;p=4016"},"modified":"2026-04-24T02:05:11","modified_gmt":"2026-04-24T02:05:11","slug":"chemical-resistant-submersible-pump-supplier","status":"publish","type":"product","link":"https:\/\/changyupump.com\/id\/product\/chemical-resistant-submersible-pump-supplier\/","title":{"rendered":"Pompa Celup Tahan Bahan Kimia Seri FYH"},"content":{"rendered":"<style>.kb-row-layout-wrap.wp-block-kadence-rowlayout.kb-row-layout-id4016_416d61-f7{margin-top:-20px;margin-bottom:50px;}.kb-row-layout-id4016_416d61-f7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_416d61-f7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_416d61-f7 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4016_416d61-f7 > .kt-row-layout-overlay{opacity:0.95;background-color:#f0f2f4;}@media all and (max-width: 1024px){.kb-row-layout-id4016_416d61-f7 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_416d61-f7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_416d61-f7 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4016_f62c2a-7e > .kt-inside-inner-col,.kadence-column4016_f62c2a-7e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_f62c2a-7e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_f62c2a-7e > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_f62c2a-7e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_f62c2a-7e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_f62c2a-7e{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_f62c2a-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_f62c2a-7e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_f62c2a-7e\"><div class=\"kt-inside-inner-col\"><style>.kb-gallery-type-thumbslider.kb-gallery-id-4016_d5614c-89 .kt-blocks-carousel-init {margin-bottom:10px;}.kb-gallery-id-4016_d5614c-89 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-4016_d5614c-89 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-4016_d5614c-89 alignnone wp-block-kadence-advancedgallery\"><div class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-thumbslider kb-gallery-id-4016_d5614c-89 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-lightbox-caption=\"true\"><div class=\"kt-blocks-carousel kt-carousel-container-dotstyle-dark\"><div id=\"kb-slider-4016_d5614c-89\" class=\"kt-blocks-carousel-init splide kb-blocks-slider kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"4\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-thumb-slider-4016_d5614c-89\"  data-slider-auto=\"\" data-slider-speed=\"7000\" data-slider-gap=\"10px\" data-slider-gap-tablet=\"10px\" data-slider-gap-mobile=\"10px\" data-show-pause-button=\"false\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp\" data-id=\"4019\" class=\"wp-image-4019 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp\" data-id=\"4018\" class=\"wp-image-4018 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp\" data-id=\"4024\" class=\"wp-image-4024 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp\" data-id=\"4029\" class=\"wp-image-4029 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp\" data-id=\"4020\" class=\"wp-image-4020 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-1024x768.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump (1)\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp\" data-id=\"4017\" class=\"wp-image-4017 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><div id=\"kb-thumb-slider-4016_d5614c-89\" class=\"kb-blocks-slider splide kt-carousel-arrowstyle-none kt-carousel-dotstyle-dark\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-arrows=\"false\" data-slider-fade=\"true\" data-slider-dots=\"false\" data-slider-hover-pause=\"false\" data-slider-speed=\"7000\" data-slider-type=\"thumbnail\" data-slider-nav=\"kb-slider-4016_d5614c-89\"><div class=\"splide__track\"><ul class=\"splide__list\"><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp\" data-id=\"4019\" class=\"wp-image-4019 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-12-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp\" data-id=\"4018\" class=\"wp-image-4018 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-11-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp\" data-id=\"4024\" class=\"wp-image-4024 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-5-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp\" data-id=\"4029\" class=\"wp-image-4029 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-10-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp\" data-id=\"4020\" class=\"wp-image-4020 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><li class=\"kb-slide-item kb-gallery-carousel-item splide__slide\"><div class=\"kadence-blocks-gallery-thumb-item\"><div class=\"kadence-blocks-gallery-thumb-item-inner\"><figure class=\"kb-gallery-figure\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp\" width=\"1024\" height=\"768\" alt=\"Chemical Resistant Submersible Pump (1)\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp\" data-id=\"4017\" class=\"wp-image-4017 skip-lazy\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1.webp 1200w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-1-16x12.webp 16w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/figure><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n\n\n<style>.kadence-column4016_49c50a-b5 > .kt-inside-inner-col,.kadence-column4016_49c50a-b5 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_49c50a-b5 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_49c50a-b5 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_49c50a-b5 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_49c50a-b5 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_49c50a-b5{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_49c50a-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_49c50a-b5 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_49c50a-b5\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-large-font-size\">FYH Series Chemical Resistant Submersible Pump<\/h2>\n\n\n\n<p style=\"font-size:18px\">The FYH series of chemical resistant submersible pumps is a long-shaft vertical centrifugal pump. Their submersible components in contact with the liquid are entirely moulded from fluoroplastic, offering advantages such as a wide range of corrosion resistance and high efficiency. They can operate without priming and can pump corrosive media, including acids, alkalis, organic solvents, and strong oxidising agents at any concentration, without sustaining damage.<\/p>\n\n\n<style>.kb-table-container4016_fb8dfd-fd{overflow-x:auto;}.kb-table4016_fb8dfd-fd td:nth-of-type(1), .kb-table4016_fb8dfd-fd th:nth-of-type(1){width:30%;}.kb-table4016_fb8dfd-fd{table-layout:fixed;width:100%;}.kb-table-container .kb-table4016_fb8dfd-fd th{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;}.kb-table-container .kb-table4016_fb8dfd-fd caption{text-align:center;}.kb-table-container .kb-table4016_fb8dfd-fd td{padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-right:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-xxs, 0.5rem);padding-left:var(--global-kb-spacing-xxs, 0.5rem);text-align:left;}.kb-table-container .kb-table4016_fb8dfd-fd tr:nth-of-type(odd){background-color:rgba(225,225,225,0.8);}.kb-table-container .kb-table4016_fb8dfd-fd td, .kb-table4016_fb8dfd-fd th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}@media all and (max-width: 1024px){.kb-table-container .kb-table4016_fb8dfd-fd td, .kb-table4016_fb8dfd-fd th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}@media all and (max-width: 767px){.kb-table-container .kb-table4016_fb8dfd-fd td, .kb-table4016_fb8dfd-fd th{border-top:1px solid var(--global-palette7, #EDF2F7);border-right:1px solid var(--global-palette7, #EDF2F7);border-bottom:1px solid var(--global-palette7, #EDF2F7);border-left:1px solid var(--global-palette7, #EDF2F7);}}<\/style><div class=\"kb-table-container kb-table-container4016_fb8dfd-fd wp-block-kadence-table\"><table class=\"kb-table kb-table4016_fb8dfd-fd\">\n<tr class=\"kb-table-row kb-table-row4016_bf8508-c7\">\n<th class=\"kb-table-data kb-table-data4016_25cbaf-96\">\n\n<p class=\"has-text-align-left\">Flow Rate Range :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data4016_662413-50\">\n\n<p>5m\u00b3\/h~400m\u00b3\/h<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row4016_44fb65-92\">\n<th class=\"kb-table-data kb-table-data4016_f43633-cd\">\n\n<p class=\"has-text-align-left\">Head Range: <\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data4016_02db9b-ed\">\n\n<p>5m~50m<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row4016_002985-02\">\n<th class=\"kb-table-data kb-table-data4016_8d43a6-3b\">\n\n<p class=\"has-text-align-left\">Motor Power :<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data4016_3f48b2-ae\">\n\n<p>0.75kw~90kw<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row4016_486ba9-f2\">\n<th class=\"kb-table-data kb-table-data4016_a56deb-ff\">\n\n<p class=\"has-text-align-left\">Speed:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data4016_c2582d-f4\">\n\n<p class=\"has-text-align-left\">968-3450 r\/min<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row4016_d3a627-7e\">\n<th class=\"kb-table-data kb-table-data4016_aac0aa-ef\">\n\n<p class=\"has-text-align-left\">Medium Temperature Range:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data4016_6a76ef-6f\">\n\n<p>-20\u00b0C~90\u00b0C<\/p>\n\n<\/td>\n<\/tr>\n\n<tr class=\"kb-table-row kb-table-row4016_0f881a-cb\">\n<th class=\"kb-table-data kb-table-data4016_b60134-69\">\n\n<p class=\"has-text-align-left\">Customizable Materials:<\/p>\n\n<\/th>\n\n<td class=\"kb-table-data kb-table-data4016_e1c01f-f5\">\n\n<p>UHMWPE\u3001FEP<\/p>\n\n<\/td>\n<\/tr>\n<\/table><\/div>\n\n<!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Introduction<\/h2>\n\n\n\n<p id=\"p-rc_15ef67f36b38e499-37\">The <strong>FYH Series Chemical Resistant Submersible Pump<\/strong> is a high-performance, <strong>long-shaft vertical centrifugal pump<\/strong> specifically engineered for the most demanding chemical environments, including chemical processing, petroleum refining, and wastewater treatment. Designed with a robust vertical structure, this pump uses a submerged hydraulic end, allowing immediate startup without manual priming or liquid filling, a critical advantage for efficient and safe fluid transfer.<\/p>\n\n\n<style>.kb-row-layout-id4016_03b67c-1b > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_03b67c-1b > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_03b67c-1b > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4016_03b67c-1b > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_03b67c-1b > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_03b67c-1b > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_03b67c-1b alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_59eacc-98 > .kt-inside-inner-col,.kadence-column4016_59eacc-98 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_59eacc-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_59eacc-98 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_59eacc-98 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_59eacc-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_59eacc-98{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_59eacc-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_59eacc-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_59eacc-98\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"FYH series stainless steel semi submersible submers\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/8WVSrquJBak?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_08e2eb-8f > .kt-inside-inner-col,.kadence-column4016_08e2eb-8f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_08e2eb-8f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_08e2eb-8f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_08e2eb-8f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_08e2eb-8f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_08e2eb-8f{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_08e2eb-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_08e2eb-8f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_08e2eb-8f\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"FYH Fluoroplastic Submersible Pump Product Introduction\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/F59lIZm7G9s?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p id=\"p-rc_15ef67f36b38e499-38\" style=\"margin-top:var(--wp--preset--spacing--40)\">Built to withstand extreme chemical aggression, the FYH series features wetted parts fully lined with &#8220;Plastic King&#8221; (fluoroplastics) such as <strong>PTFE and FEP (F46)<\/strong>. These materials offer world-class corrosion resistance against any concentration of acids, alkalis, strong oxidizers, and organic solvents. The innovative design includes a high-strength fluoroplastic alloy casing and a silicon carbide shaft sleeve that significantly reduces wear and increases overall energy efficiency. Whether applied in industrial sulfuric acid transfer, fine chemical electrolysis, or textile dyeing, the FYH Series Chemical Resistant Submersible Pump delivers reliable, quiet, and maintenance-free performance in environments prone to severe corrosion.<\/p>\n\n\n<style>.kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list li{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;margin-right:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list li:last-child{margin-right:0px;}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list{margin-right:-10px;}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list li .kt-tab-title{margin-right:10px;}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list li .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{line-height:1.4em;font-weight:regular;font-style:normal;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;border-top-left-radius:4px;border-top-right-radius:4px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;padding-top:8px;padding-right:20px;padding-bottom:8px;padding-left:20px;border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #eeeeee);}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title{margin-top:0px;margin-right:8px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list li .kt-tab-title:hover, .wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .kt-tabs-accordion-title .kt-tab-title:hover{border-color:var(--global-palette7, #eeeeee);color:var(--global-palette4, #2D3748);background:var(--global-palette7, #EDF2F7);}.wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-title-list li.kt-tab-title-active .kt-tab-title, .wp-block-kadence-tabs .kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .kt-tabs-accordion-title.kt-tab-title-active .kt-tab-title{border-color:var(--global-palette7, #eeeeee);color:#ffffff;background:var(--global-palette2, #2B6CB0);}@media all and (max-width: 1024px){.kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}@media all and (max-width: 767px){.kt-tabs-id4016_717c1f-21 > .kt-tabs-content-wrap > .wp-block-kadence-tab{border-top:3px solid var(--global-palette2, #2B6CB0);border-right:0px solid #0a6689;border-bottom:0px solid #0a6689;border-left:0px solid #0a6689;}}<\/style>\n<div class=\"wp-block-kadence-tabs alignnone\"><div class=\"kt-tabs-wrap kt-tabs-id4016_717c1f-21 kt-tabs-has-2-tabs kt-active-tab-1 kt-tabs-layout-tabs kt-tabs-tablet-layout-inherit kt-tabs-mobile-layout-inherit kt-tab-alignment-left \"><ul class=\"kt-tabs-title-list kb-tabs-list-columns kb-tab-title-columns-6\"><li id=\"tab-strongpartsstrong\" class=\"kt-title-item kt-title-item-1 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-active\"><a href=\"#tab-strongpartsstrong\" data-tab=\"1\" class=\"kt-tab-title kt-tab-title-1 \"><span class=\"kt-title-text\"><strong>Parts<\/strong><\/span><\/a><\/li><li id=\"tab-strongspecificationsstrong\" class=\"kt-title-item kt-title-item-2 kt-tabs-svg-show-always kt-tabs-icon-side-right kt-tab-title-inactive\"><a href=\"#tab-strongspecificationsstrong\" data-tab=\"2\" class=\"kt-tab-title kt-tab-title-2 \"><span class=\"kt-title-text\"><strong>Specifications<\/strong><\/span><\/a><\/li><\/ul><div class=\"kt-tabs-content-wrap\">\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-1 kt-inner-tab4016_f266a3-a5\"><div class=\"kt-tab-inner-content-inner\">\n<h3 class=\"wp-block-heading\">Parts of Chemical Resistant Submersible Pump<\/h3>\n\n\n\n<p>The FYH Series is a practical and reliable fluid handling solution designed for demanding chemical environments, such as industrial pickling, hazardous liquid transfer, and wastewater treatment. Unlike horizontal pumps, this long-shaft vertical centrifugal pump is engineered to be partially submerged, allowing it to start immediately without manual priming or liquid filling.<\/p>\n\n\n<style>.kb-image4016_22c5c4-be.kb-image-is-ratio-size, .kb-image4016_22c5c4-be .kb-image-is-ratio-size{max-width:1200px;width:100%;}.wp-block-kadence-column > .kt-inside-inner-col > .kb-image4016_22c5c4-be.kb-image-is-ratio-size, .wp-block-kadence-column > .kt-inside-inner-col > .kb-image4016_22c5c4-be .kb-image-is-ratio-size{align-self:unset;}.kb-image4016_22c5c4-be figure{max-width:1200px;}.kb-image4016_22c5c4-be .image-is-svg, .kb-image4016_22c5c4-be .image-is-svg img{width:100%;}.kb-image4016_22c5c4-be .kb-image-has-overlay:after{opacity:0.3;}<\/style>\n<div class=\"wp-block-kadence-image kb-image4016_22c5c4-be\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1600\" height=\"730\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659.webp\" alt=\"Structure-of-a-Chemical-Resistant-Submersible-Pump\" class=\"kb-img wp-image-4030\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659.webp 1600w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659-300x137.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659-1024x467.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659-150x68.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659-768x350.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659-1536x701.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Structure-of-a-Chemical-Resistant-Submersible-Pump-e1774576893659-18x8.webp 18w\" sizes=\"auto, (max-width: 1600px) 100vw, 1600px\" \/><figcaption>Structure of a Chemical Resistant Submersible Pump<\/figcaption><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">No.<\/th><th class=\"has-text-align-center\" data-align=\"center\">Part Name<\/th><th class=\"has-text-align-center\" data-align=\"center\">Material<\/th><th class=\"has-text-align-center\" data-align=\"center\">No.<\/th><th class=\"has-text-align-center\" data-align=\"center\">Part Name<\/th><th class=\"has-text-align-center\" data-align=\"center\">Material<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">1<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pump Casing<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fluoroplastic Alloy<\/td><td class=\"has-text-align-center\" data-align=\"center\">5<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pump Cover<\/td><td class=\"has-text-align-center\" data-align=\"center\">F46<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">2<\/td><td class=\"has-text-align-center\" data-align=\"center\">Impeller<\/td><td class=\"has-text-align-center\" data-align=\"center\">Fluoroplastic Alloy<\/td><td class=\"has-text-align-center\" data-align=\"center\">6<\/td><td class=\"has-text-align-center\" data-align=\"center\">Shaft Sleeve<\/td><td class=\"has-text-align-center\" data-align=\"center\">Silicon Carbide<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">3<\/td><td class=\"has-text-align-center\" data-align=\"center\">Packing<\/td><td class=\"has-text-align-center\" data-align=\"center\">PE (Polyethylene)<\/td><td class=\"has-text-align-center\" data-align=\"center\">7<\/td><td class=\"has-text-align-center\" data-align=\"center\">Pump Shaft<\/td><td class=\"has-text-align-center\" data-align=\"center\">45# Steel Lined with F46<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">4<\/td><td class=\"has-text-align-center\" data-align=\"center\">Nut<\/td><td class=\"has-text-align-center\" data-align=\"center\">45# Steel Lined with F46<\/td><td class=\"has-text-align-center\" data-align=\"center\">8<\/td><td class=\"has-text-align-center\" data-align=\"center\">Base Plate<\/td><td class=\"has-text-align-center\" data-align=\"center\">Polyvinyl Chloride, Carbon Steel<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style>.kb-row-layout-id4016_719206-17 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_719206-17 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_719206-17 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4016_719206-17 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_719206-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_719206-17 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_719206-17 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col,.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_d0c9b1-65{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_d0c9b1-65 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_d0c9b1-65\"><div class=\"kt-inside-inner-col\">\n<h3 class=\"wp-block-heading has-medium-font-size\">All-copper coil<\/h3>\n\n\n\n<p>100% copper wire \u00b7 Equipped with a thermal protector that automatically shuts down the machine in the event of abnormal operation, such as overload, to prevent damage<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Impeller<\/h3>\n\n\n\n<p>High-quality impeller \u00b7 Reinforced inlet ring \u00b7 Enhanced strength \u00b7 Resistant to deformation<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Bearings<\/h3>\n\n\n\n<p>High-precision bearings<\/p>\n\n\n\n<p>Quiet operation \u00b7 Stable performance \u00b7 High-load capacity \u00b7 Imported lubricating grease \u00b7 Long service life<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-medium-font-size\">Mechanical seal<\/h3>\n\n\n\n<p>High-quality, high-temperature-resistant mechanical seal \u00b7 Excellent sealing performance \u00b7 Corrosion-resistant \u00b7 Rust-proof<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_73af55-98 > .kt-inside-inner-col{display:flex;}.kadence-column4016_73af55-98 > .kt-inside-inner-col,.kadence-column4016_73af55-98 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_73af55-98 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_73af55-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column4016_73af55-98 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column4016_73af55-98 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column4016_73af55-98 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4016_73af55-98{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_73af55-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_73af55-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_73af55-98 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_73af55-98{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4016_73af55-98{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_73af55-98{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_73af55-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4016_73af55-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4016_73af55-98{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_73af55-98{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_73af55-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_73af55-98 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_73af55-98\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-4016_1c8e38-a8{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-4016_1c8e38-a8 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-4016_1c8e38-a8 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-4016_1c8e38-a8 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}.kb-gallery-id-4016_1c8e38-a8 .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{font-size:var(--global-kb-font-size-sm, 0.9rem);}.kb-gallery-caption-style-bottom.kb-gallery-id-4016_1c8e38-a8 .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption, .kb-gallery-caption-style-bottom-hover.kb-gallery-id-4016_1c8e38-a8 .kadence-blocks-gallery-item .kadence-blocks-gallery-item-inner .kadence-blocks-gallery-item__caption{background:linear-gradient(0deg, rgba(0, 0, 0, 0.5) 0, rgba(0, 0, 0, 0) 100%);}<\/style><div class=\"kb-gallery-wrap-id-4016_1c8e38-a8 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-4016_1c8e38-a8 kb-gallery-caption-style-bottom kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor.webp\" data-description=\"Copper-core Motor\" data-alt=\"Copper-core Motor\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-square kb-has-image-ratio-square\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor.webp\" width=\"538\" height=\"392\" alt=\"Copper-core Motor\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor.webp\" data-id=\"3630\" class=\"wp-image-3630\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor.webp 538w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor-300x219.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor-150x109.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Copper-core-motor-16x12.webp 16w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Copper-core Motor<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3.webp\" data-description=\"Impeller\" data-alt=\"Impeller\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-square kb-has-image-ratio-square\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3.webp\" width=\"986\" height=\"812\" alt=\"Impeller\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3.webp\" data-id=\"3461\" class=\"wp-image-3461\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3.webp 986w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3-300x247.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3-150x124.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3-768x632.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Impeller-3-15x12.webp 15w\" sizes=\"auto, (max-width: 986px) 100vw, 986px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Impeller<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings.webp\" data-description=\"Bearings\" data-alt=\"Bearings\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-square kb-has-image-ratio-square\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings.webp\" width=\"496\" height=\"496\" alt=\"Bearings\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings.webp\" data-id=\"3627\" class=\"wp-image-3627\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings.webp 496w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings-300x300.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings-150x150.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/Bearings-12x12.webp 12w\" sizes=\"auto, (max-width: 496px) 100vw, 496px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Bearings<\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-has-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal.webp\" data-description=\"Mechanical Seal\" data-alt=\"Mechanical Seal\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-square kb-has-image-ratio-square\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal.webp\" width=\"865\" height=\"762\" alt=\"Mechanical Seal\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal.webp\" data-id=\"3462\" class=\"wp-image-3462\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal.webp 865w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal-300x264.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal-150x132.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal-768x677.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Mechanical-Seal-14x12.webp 14w\" sizes=\"auto, (max-width: 865px) 100vw, 865px\" \/><\/div><div class=\"kadence-blocks-gallery-item__caption\">Mechanical Seal<\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><em><strong>Notice:<em>Notice:<\/em><\/strong> Trust our industrial-grade <strong>FYH Series Chemical Resistant Submersible Pump<\/strong> to minimise operational downtime and lower your total cost of ownership in highly corrosive chemical applications. By utilizing a high-performance long-shaft vertical design that allows for immediate startup without priming and advanced fluoroplastic alloy linings (PTFE\/FEP), our engineering ensures a safer, more stable, and corrosion-free fluid handling environment for your most aggressive media.<\/em><\/p>\n\n\n<style>.kb-row-layout-id4016_01ae99-69 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_01ae99-69 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_01ae99-69 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id4016_01ae99-69 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_01ae99-69 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_01ae99-69 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_01ae99-69 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{display:flex;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col,.kadence-column4016_61ecd7-4f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4016_61ecd7-4f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_61ecd7-4f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_61ecd7-4f{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4016_61ecd7-4f{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_61ecd7-4f{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4016_61ecd7-4f{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_61ecd7-4f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_61ecd7-4f > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_61ecd7-4f\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +86-13651913727<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{display:flex;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col,.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4016_ec1cdc-ff{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_ec1cdc-ff{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_ec1cdc-ff{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4016_ec1cdc-ff{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_ec1cdc-ff{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4016_ec1cdc-ff{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_ec1cdc-ff{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_ec1cdc-ff > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_ec1cdc-ff\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-tab kt-tab-inner-content kt-inner-tab-2 kt-inner-tab4016_88ef0a-77\"><div class=\"kt-tab-inner-content-inner\">\n<h2 class=\"wp-block-heading\">Technical Specifications: FYH Series Chemical Resistant Submersible Pump<\/h2>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-fixed-layout\"><thead><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Parameter<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Specifications<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Parameter<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Specifications<\/strong><\/td><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Model<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">FYH <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Material<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Engineering Plastics \/ <a href=\"https:\/\/en.wikipedia.org\/wiki\/Fluoropolymer\" data-type=\"link\" data-id=\"https:\/\/en.wikipedia.org\/wiki\/Fluoropolymer\" target=\"_blank\" rel=\"noopener\">Fluoroplastics<\/a> <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Drive Method<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Electric <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Pump Shaft Position<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Vertical (Side-mounted) <sup><\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Impeller Structure<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Closed Impeller <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Number of Impellers<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Single-stage <sup><\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Suction Method<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Single Suction <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Working Principle<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Centrifugal Pump <sup><\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Performance<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Corrosion Resistant <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Pumping Medium<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Highly Corrosive Media <sup><\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Head Range<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">5m \u2013 50m <sup><\/sup><sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Speed<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">2900 r\/min <sup><\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Power Output<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">1.5kW \u2013 18.5kW <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Flow Rate<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">5m\u00b3\/h \u2013 400m\u00b3\/h <\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Voltage<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">380V <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Standard Weight<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">~80kg <sup><\/sup><\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong>Temperature Range<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">-20\u00b0C to 90\u00b0C <sup><\/sup><\/td><td class=\"has-text-align-center\" data-align=\"center\"><strong>Application<\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Chemical Pump <sup><\/sup><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n<style>.wp-block-kadence-advancedgallery.kb-gallery-wrap-id-4016_ee3ed8-f0{margin-top:var(--global-kb-spacing-xs, 1rem);}.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-4016_ee3ed8-f0{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-4016_ee3ed8-f0 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-4016_ee3ed8-f0 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-4016_ee3ed8-f0 .kb-slide-item .kb-gal-image-radius img{border-radius:10px 10px 10px 10px;;}<\/style><div class=\"kb-gallery-wrap-id-4016_ee3ed8-f0 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-4016_ee3ed8-f0 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4.webp\" data-id=\"4023\" class=\"wp-image-4023\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-4-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3.webp\" data-id=\"4022\" class=\"wp-image-4022\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-3-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2.webp\" width=\"900\" height=\"506\" alt=\"Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2.webp\" data-id=\"4021\" class=\"wp-image-4021\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-2-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\" tabindex=\"0\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kadence-blocks-gallery-item-hide-caption\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land32 kb-has-image-ratio-land32\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8.webp\" width=\"900\" height=\"506\" alt=\"FYH Series Chemical Resistant Submersible Pump\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8.webp\" data-id=\"4027\" class=\"wp-image-4027\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-8-18x10.webp 18w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<h3 class=\"wp-block-heading\"><strong>Model Identification Code (Example)<\/strong><\/h3>\n\n\n\n<p>To help <a href=\"https:\/\/changyupump.com\/\" data-type=\"page\" data-id=\"6\">Changyu Pump<\/a> engineers select the right FYH Series<strong> Chemical Resistant Submersible Pump<\/strong> for your project, please refer to the following naming convention:<\/p>\n\n\n\n<p>Example: <strong>50FYH-20-25<\/strong>:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>50<\/strong>: Pump Inlet Diameter (mm) <sup><\/sup><\/li>\n\n\n\n<li><strong>FYH<\/strong>: Series Name (Fluoroplastic Chemical Resistant Submersible Pump) <sup><\/sup><sup><\/sup><sup><\/sup><sup><\/sup><\/li>\n\n\n\n<li><strong>20\uff1a<\/strong>Flow (m\u00b3\/h)<\/li>\n\n\n\n<li><strong>25<\/strong>: Rated Head (m)<\/li>\n<\/ul>\n\n\n\n<p><strong><em>Notice:<\/em><\/strong> Due to the variety of specific gravity and viscosity in different chemical media, please contact our technical team with your specific liquid concentration and working temperature (ranging from -20\u00b0C to 90\u00b0C). <br>We provide customised industrial solutions, including adjustable shaft lengths and material adaptations, to lower your total cost of ownership.<\/p>\n\n\n<style>.kb-row-layout-id4016_4866f7-6f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_4866f7-6f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_4866f7-6f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)))minmax(0, calc(50% - ((var(--global-kb-gap-md, 2rem) * 1 )\/2)));}.kb-row-layout-id4016_4866f7-6f > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_4866f7-6f > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_4866f7-6f > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_4866f7-6f alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_daa968-e4 > .kt-inside-inner-col{display:flex;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col,.kadence-column4016_daa968-e4 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_daa968-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4016_daa968-e4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_daa968-e4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_daa968-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_daa968-e4{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4016_daa968-e4{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_daa968-e4{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_daa968-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4016_daa968-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4016_daa968-e4{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_daa968-e4{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_daa968-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_daa968-e4 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:flex-start;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_daa968-e4\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-text-align-left\"><strong>Email:&nbsp;<a href=\"mailto:jade@changyupump.com\">jade@changyupump.com<\/a><\/strong><\/p>\n\n\n\n<p><strong>Phone: +86-13651913727<\/strong><\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_d77da7-16 > .kt-inside-inner-col{display:flex;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col,.kadence-column4016_d77da7-16 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_d77da7-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col > .kb-image-is-ratio-size{align-self:stretch;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col > .wp-block-kadence-advancedgallery{align-self:stretch;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column4016_d77da7-16{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_d77da7-16{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_d77da7-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_d77da7-16{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column4016_d77da7-16{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_d77da7-16{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_d77da7-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column4016_d77da7-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column4016_d77da7-16{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_d77da7-16{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column4016_d77da7-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column4016_d77da7-16 > .kt-inside-inner-col{flex-direction:column;justify-content:center;align-items:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_d77da7-16\"><div class=\"kt-inside-inner-col\"><!-- [element-1116] --><style>.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{display:flex;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{padding-left:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col,.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1116_b4e12a-5e{position:relative;}.kadence-column1116_b4e12a-5e, .kt-inside-inner-col > .kadence-column1116_b4e12a-5e:not(.specificity){margin-top:var(--global-kb-spacing-md, 2rem);}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1116_b4e12a-5e{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1116_b4e12a-5e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1116_b4e12a-5e\"><div class=\"kt-inside-inner-col\"><style>#kt-modal1116_989c94-4c .kt-blocks-modal-link{color:var(--global-palette9, #ffffff);background:#019141;border-radius:10px;font-size:18px;line-height:24px;font-family:var( --global-body-font-family, inherit );font-style:normal;font-weight:500;border-width:0px 0px 0px 0px;padding:15px 30px 15px 30px;margin:0px 0px 0px 0px;}#kt-modal1116_989c94-4c .kt-blocks-modal-link:hover, #kt-modal1116_989c94-4c .kt-blocks-modal-link:focus{color:#ffffff;background:var(--global-palette4, #2D3748);border-color:var(--global-palette4, #2D3748);}#kt-modal1116_989c94-4c .kt-modal-overlay, #kt-target-modal1116_989c94-4c .kt-modal-overlay, .kb-modal-content1116_989c94-4c .kt-modal-overlay{-ms-flex-pack:center;justify-content:center;-ms-flex-align:center;align-items:center;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;max-width:600px;-ms-flex-pack:flex-start;justify-content:flex-start;text-align:left;-ms-flex-align:flex-start;align-items:flex-start;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{padding-top:30px;padding-right:30px;padding-bottom:30px;padding-left:30px;margin-top:20px;margin-right:20px;margin-bottom:20px;margin-left:20px;}#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{background:#ffffff;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}}@media all and (max-width: 1024px){#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}@media all and (max-width: 767px){#kt-modal1116_989c94-4c .kt-modal-container, #kt-target-modal1116_989c94-4c .kt-modal-container, .kb-modal-content1116_989c94-4c .kt-modal-container{width:100%;border-top:0px solid rgba(255,255,255,0);border-right:0px solid rgba(255,255,255,0);border-bottom:0px solid rgba(255,255,255,0);border-left:0px solid rgba(255,255,255,0);}#kt-modal1116_989c94-4c .kt-modal-close svg, #kt-target-modal1116_989c94-4c .kt-modal-close svg, .kb-modal-content1116_989c94-4c .kt-modal-close svg{width:24px;height:24px;}}<\/style>\n<div class=\"wp-block-kadence-modal alignleft kt-modal-linkalign-left\" id=\"kt-modal1116_989c94-4c\"><div id=\"kt-target-modal1116_989c94-4c\" class=\"kb-modal-content1116_989c94-4c kadence-block-pro-modal kt-m-animate-in-fadeup kt-m-animate-out-fadeout\" aria-hidden=\"true\"><div class=\"kt-modal-overlay\" tabindex=\"-1\" data-modal-close=\"true\"><div class=\"kt-modal-container kt-modal-height-fittocontent kt-close-position-inside\" role=\"dialog\" aria-modal=\"true\"><button class=\"kt-modal-close\" aria-label=\"Close Modal\" data-modal-close=\"true\"><svg viewBox=\"0 0 24 24\" fill=\"none\" stroke=\"currentColor\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><line x1=\"18\" y1=\"6\" x2=\"6\" y2=\"18\"><\/line><line x1=\"6\" y1=\"6\" x2=\"18\" y2=\"18\"><\/line><\/svg><\/button><div id=\"kt-modal1116_989c94-4c-content\" class=\"kt-modal-content\">\n<h4 class=\"wp-block-heading has-text-align-center\"><strong>REQUEST A QUOTE<\/strong><\/h4>\n\n\n<style>.kadence-form-885_43a79e-2b .kb-form .kadence-blocks-form-field .kb-forms-submit{color:var(--global-palette9, #ffffff);background:#019141;}.kadence-form-885_43a79e-2b .kadence-blocks-form-success{color:var(--global-palette2, #2B6CB0);}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-885_43a79e-2b kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\" data-error-message=\"Please fix the error to continue.\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_0\">Name<\/label><input name=\"kb_field_0\" id=\"kb_field_885_43a79e-2b_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_1\">Email<span class=\"required\">*<\/span><\/label><input name=\"kb_field_1\" id=\"kb_field_885_43a79e-2b_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Adress\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_2\">Phone<span class=\"required\">*<\/span><\/label><input name=\"kb_field_2\" id=\"kb_field_885_43a79e-2b_2\" data-label=\"Phone\" type=\"tel\" placeholder=\"Mobile Phone\" value=\"\" data-type=\"tel\" class=\"kb-field kb-text-style-field kb-tel-field kb-field-2\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-100 kb-input-size-standard\"><label for=\"kb_field_885_43a79e-2b_3\">Message<\/label><textarea name=\"kb_field_3\" id=\"kb_field_885_43a79e-2b_3\" data-label=\"Message\" type=\"textarea\" placeholder=\"Please tell us your specific requirements...\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-3\" rows=\"4\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"885_43a79e-2b\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"885\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-auto\">Submit<\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-885_43a79e-2b .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div><\/div><\/div><button class=\"kb-btn-global-custom kt-modal-label-show kt-blocks-modal-link\" data-modal-open=\"kt-target-modal1116_989c94-4c\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-btn-svg-icon kt-btn-svg-icon-fe edit kt-btn-side-left\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-blocks-modal-link-inner\"> Inquiry Now<\/span><\/button><\/div>\n<\/div><\/div>\n<!-- [\/element-1116] -->\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><tbody><tr><td rowspan=\"2\">NO.<\/td><td rowspan=\"2\">Model<\/td><td rowspan=\"2\">Flow<br>(m\u00b3\/h)<\/td><td rowspan=\"2\">Head<br>(m)<\/td><td rowspan=\"2\">Rev<br>(r\/min)<\/td><td colspan=\"2\">Power<\/td><td rowspan=\"2\">Caliber<br>(mm)<\/td><\/tr><tr><td>Axial<br>power<\/td><td>Motor<br>power<\/td><\/tr><tr><td>1&nbsp;<\/td><td>32FYH-5-20<\/td><td>5&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>0.8&nbsp;<\/td><td>2.2&nbsp;<\/td><td rowspan=\"2\">32\u00d725<\/td><\/tr><tr><td>2&nbsp;<\/td><td>32FYH-10-15<\/td><td>10&nbsp;<\/td><td>15&nbsp;<\/td><td>2900&nbsp;<\/td><td>1.17&nbsp;<\/td><td>2.2&nbsp;<\/td><\/tr><tr><td>3&nbsp;<\/td><td>40FYH-10-20<\/td><td>10&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>1.5&nbsp;<\/td><td>3&nbsp;<\/td><td rowspan=\"2\">40\u00d732<\/td><\/tr><tr><td>4&nbsp;<\/td><td>40FYH-15-20<\/td><td>15&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>2.34&nbsp;<\/td><td>3&nbsp;<\/td><\/tr><tr><td>5&nbsp;<\/td><td>50FYH-10-25<\/td><td>10&nbsp;<\/td><td>25&nbsp;<\/td><td>2900&nbsp;<\/td><td>3.4&nbsp;<\/td><td>4&nbsp;<\/td><td rowspan=\"7\">50&#215;40<\/td><\/tr><tr><td>6&nbsp;<\/td><td>50FYH-10-30<\/td><td>10&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>4.1&nbsp;<\/td><td>5.5&nbsp;<\/td><\/tr><tr><td>7&nbsp;<\/td><td>50FYH-15-30<\/td><td>15&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>5.3&nbsp;<\/td><td>5.5&nbsp;<\/td><\/tr><tr><td>8&nbsp;<\/td><td>50FYH-20-20<\/td><td>20&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>4.6&nbsp;<\/td><td>5.5&nbsp;<\/td><\/tr><tr><td>9&nbsp;<\/td><td>50FYH-20-25<\/td><td>20&nbsp;<\/td><td>25&nbsp;<\/td><td>2900&nbsp;<\/td><td>5.45&nbsp;<\/td><td>5.5&nbsp;<\/td><\/tr><tr><td>10&nbsp;<\/td><td>50FYH-10-40<\/td><td>10&nbsp;<\/td><td>40&nbsp;<\/td><td>2900&nbsp;<\/td><td>6.1&nbsp;<\/td><td>7.5&nbsp;<\/td><\/tr><tr><td>11&nbsp;<\/td><td>50FYH-20-30<\/td><td>20&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>6.54&nbsp;<\/td><td>7.5&nbsp;<\/td><\/tr><tr><td>12&nbsp;<\/td><td>65FYH-25-25<\/td><td>25&nbsp;<\/td><td>25&nbsp;<\/td><td>2900&nbsp;<\/td><td>5.68&nbsp;<\/td><td>7.5&nbsp;<\/td><td rowspan=\"4\">65&#215;50<\/td><\/tr><tr><td>13&nbsp;<\/td><td>65FYH-25-30<\/td><td>25&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>6.8&nbsp;<\/td><td>7.5&nbsp;<\/td><\/tr><tr><td>14&nbsp;<\/td><td>65FYH-30-20<\/td><td>30&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>5.8&nbsp;<\/td><td>7.5&nbsp;<\/td><\/tr><tr><td>15&nbsp;<\/td><td>65FYH-40-20<\/td><td>40&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>6.82&nbsp;<\/td><td>7.5&nbsp;<\/td><\/tr><tr><td>16&nbsp;<\/td><td>65FYH-30-25<\/td><td>30&nbsp;<\/td><td>25&nbsp;<\/td><td>2900&nbsp;<\/td><td>5.84&nbsp;<\/td><td>7.5&nbsp;<\/td><td rowspan=\"6\">65\u00d750<\/td><\/tr><tr><td>17&nbsp;<\/td><td>65FYH-30-30<\/td><td>30&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>6.5&nbsp;<\/td><td>7.5&nbsp;<\/td><\/tr><tr><td>18&nbsp;<\/td><td>65FYH-25-40<\/td><td>25&nbsp;<\/td><td>40&nbsp;<\/td><td>2900&nbsp;<\/td><td>7.79&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>19&nbsp;<\/td><td>65FYH-30-40<\/td><td>30&nbsp;<\/td><td>40&nbsp;<\/td><td>2900&nbsp;<\/td><td>9.35&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>20&nbsp;<\/td><td>65FYH-35-30<\/td><td>35&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>8.2&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>21&nbsp;<\/td><td>65FYH-30-50<\/td><td>30&nbsp;<\/td><td>50&nbsp;<\/td><td>2900&nbsp;<\/td><td>11.7&nbsp;<\/td><td>15&nbsp;<\/td><\/tr><tr><td>22&nbsp;<\/td><td>80FYH-60-15<\/td><td>60&nbsp;<\/td><td>15&nbsp;<\/td><td>2900&nbsp;<\/td><td>6.2&nbsp;<\/td><td>7.5&nbsp;<\/td><td rowspan=\"6\">80&#215;65<\/td><\/tr><tr><td>23&nbsp;<\/td><td>80FYH-60-20<\/td><td>60&nbsp;<\/td><td>20&nbsp;<\/td><td>2900&nbsp;<\/td><td>9.3&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>24&nbsp;<\/td><td>80FYH-50-25<\/td><td>50&nbsp;<\/td><td>25&nbsp;<\/td><td>2900&nbsp;<\/td><td>9.7&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>25&nbsp;<\/td><td>80FYH-50-30<\/td><td>50&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>10.6&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>26&nbsp;<\/td><td>80FYH-40-30<\/td><td>40&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>10.4&nbsp;<\/td><td>11&nbsp;<\/td><\/tr><tr><td>27&nbsp;<\/td><td>80FYH-60-25<\/td><td>60&nbsp;<\/td><td>25&nbsp;<\/td><td>2900&nbsp;<\/td><td>11.5&nbsp;<\/td><td>15&nbsp;<\/td><\/tr><tr><td>28&nbsp;<\/td><td>100FYH-60-30<\/td><td>60&nbsp;<\/td><td>30&nbsp;<\/td><td>2900&nbsp;<\/td><td>14&nbsp;<\/td><td>15&nbsp;<\/td><td rowspan=\"3\">100&#215;80<\/td><\/tr><tr><td>29&nbsp;<\/td><td>100FYH-80-15<\/td><td>80&nbsp;<\/td><td>15&nbsp;<\/td><td>2900&nbsp;<\/td><td>12.8&nbsp;<\/td><td>15&nbsp;<\/td><\/tr><tr><td>30&nbsp;<\/td><td>100FYH-100-10<\/td><td>100&nbsp;<\/td><td>10&nbsp;<\/td><td>2900&nbsp;<\/td><td>13.6&nbsp;<\/td><td>18.5&nbsp;<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/FYH-Submersible-Pump-pdf.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Sematan FYH-Submersible Pump pdf.\"><\/object><a id=\"wp-block-file--media-a859567f-9974-4f16-a21f-a4a6e35e82ca\" href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/FYH-Submersible-Pump-pdf.pdf\">FYH-Submersible Pump pdf<\/a><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/FYH-Submersible-Pump-pdf.pdf\" class=\"wp-block-file__button wp-element-button\" aria-describedby=\"wp-block-file--media-a859567f-9974-4f16-a21f-a4a6e35e82ca\" download>Download<\/a><\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n<style>.kb-row-layout-id4016_e2cc68-aa > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_e2cc68-aa > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_e2cc68-aa > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4016_e2cc68-aa > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_e2cc68-aa > .kt-row-column-wrap{padding-top:80px;padding-bottom:100px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_e2cc68-aa > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_e2cc68-aa alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_120c34-12 > .kt-inside-inner-col,.kadence-column4016_120c34-12 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_120c34-12 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_120c34-12 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_120c34-12 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_120c34-12 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_120c34-12{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_120c34-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_120c34-12 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_120c34-12 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4016_6de82b-cb, .wp-block-kadence-advancedheading.kt-adv-heading4016_6de82b-cb[data-kb-block=\"kb-adv-heading4016_6de82b-cb\"]{text-align:center;font-size:20px;font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading4016_6de82b-cb mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4016_6de82b-cb[data-kb-block=\"kb-adv-heading4016_6de82b-cb\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4016_6de82b-cb img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4016_6de82b-cb[data-kb-block=\"kb-adv-heading4016_6de82b-cb\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<div class=\"kt-adv-heading4016_6de82b-cb wp-block-kadence-advancedheading has-theme-palette-1-color has-text-color\" data-kb-block=\"kb-adv-heading4016_6de82b-cb\">Why Choose It?<\/div>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading4016_3c0872-37, .wp-block-kadence-advancedheading.kt-adv-heading4016_3c0872-37[data-kb-block=\"kb-adv-heading4016_3c0872-37\"]{padding-bottom:0px;margin-top:var(--global-kb-spacing-xxs, 0.5rem);text-align:center;font-size:var(--global-kb-font-size-lg, 2rem);font-style:normal;font-family:var( --global-heading-font-family, inherit );}.wp-block-kadence-advancedheading.kt-adv-heading4016_3c0872-37 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4016_3c0872-37[data-kb-block=\"kb-adv-heading4016_3c0872-37\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4016_3c0872-37 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4016_3c0872-37[data-kb-block=\"kb-adv-heading4016_3c0872-37\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4016_3c0872-37 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading4016_3c0872-37\">Advantages of the Chemical Resistant Submersible Pump<\/h2>\n\n\n<style>.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap{align-content:center;}:where(.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:center;}.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap{column-gap:40px;row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xs, 1rem);}.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap{grid-template-columns:repeat(3, minmax(0, 1fr));}.kb-row-layout-id4016_bc2df9-53 > .kt-row-layout-overlay{opacity:0.00;}@media all and (max-width: 1024px){.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id4016_bc2df9-53 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_bc2df9-53 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-3-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-middle kb-theme-content-width\">\n<style>.kadence-column4016_b10f7d-30 > .kt-inside-inner-col{display:flex;}.kadence-column4016_b10f7d-30 > .kt-inside-inner-col,.kadence-column4016_b10f7d-30 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_b10f7d-30 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_b10f7d-30 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_b10f7d-30 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_b10f7d-30 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_b10f7d-30{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_b10f7d-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_b10f7d-30 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_b10f7d-30 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box4016_652b45-f1 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_652b45-f1 .kt-info-svg-icon-flip, .kt-info-box4016_652b45-f1 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box4016_652b45-f1 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_652b45-f1 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box4016_652b45-f1 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box4016_652b45-f1 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_652b45-f1\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_aperture kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><line x1=\"14.31\" y1=\"8\" x2=\"20.05\" y2=\"17.94\"\/><line x1=\"9.69\" y1=\"8\" x2=\"21.17\" y2=\"8\"\/><line x1=\"7.38\" y1=\"12\" x2=\"13.12\" y2=\"2.06\"\/><line x1=\"9.69\" y1=\"16\" x2=\"3.95\" y2=\"6.06\"\/><line x1=\"14.31\" y1=\"16\" x2=\"2.83\" y2=\"16\"\/><line x1=\"16.62\" y1=\"12\" x2=\"10.88\" y2=\"21.94\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Fully fluorinated construction for ultimate corrosion resistance<\/h3><p class=\"kt-blocks-info-box-text\">All wetted parts are sintered and moulded from high-quality fluoroplastic alloys (PTFE\/FEP), enabling the long-term conveyance of strong acids, strong alkalis and strong oxidising agents at any concentration, whilst ensuring the pump body remains free from oxidation and corrosion.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box4016_946b29-a6 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_946b29-a6 .kt-info-svg-icon-flip, .kt-info-box4016_946b29-a6 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box4016_946b29-a6 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_946b29-a6 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box4016_946b29-a6 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box4016_946b29-a6 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_946b29-a6\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_archive kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><polyline points=\"21 8 21 21 3 21 3 8\"\/><rect x=\"1\" y=\"3\" width=\"22\" height=\"5\"\/><line x1=\"10\" y1=\"12\" x2=\"14\" y2=\"12\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Long-shaft vertical design, ready to run immediately<\/h3><p class=\"kt-blocks-info-box-text\">Featuring a long-shaft vertical self-priming design, the inlet extends directly into the fluid, allowing the pump to start without the need for cumbersome priming or venting procedures, thereby significantly improving operational efficiency and response times.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_34c54d-0f > .kt-inside-inner-col,.kadence-column4016_34c54d-0f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_34c54d-0f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_34c54d-0f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_34c54d-0f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_34c54d-0f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_34c54d-0f{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_34c54d-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_34c54d-0f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_34c54d-0f inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kb-image4016_217898-f9 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;}.kb-image4016_217898-f9 img.kb-img, .kb-image4016_217898-f9 .kb-img img{border-top-left-radius:15px;border-top-right-radius:15px;border-bottom-right-radius:15px;border-bottom-left-radius:15px;box-shadow:inset 0px 0px 60px -15px rgba(0, 0, 0, 0.2);}<\/style>\n<div class=\"wp-block-kadence-image kb-image4016_217898-f9\"><figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1152\" height=\"1440\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303.webp\" alt=\"Chemical Resistant Submersible Pump\" class=\"kb-img wp-image-4031\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303.webp 1152w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303-240x300.webp 240w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303-819x1024.webp 819w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303-120x150.webp 120w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303-768x960.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-scaled-e1774579839303-10x12.webp 10w\" sizes=\"auto, (max-width: 1152px) 100vw, 1152px\" \/><figcaption>FYH Series Chemical Resistant Submersible Pump<\/figcaption><\/figure><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_3316ef-eb > .kt-inside-inner-col{display:flex;}.kadence-column4016_3316ef-eb > .kt-inside-inner-col,.kadence-column4016_3316ef-eb > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_3316ef-eb > .kt-inside-inner-col{row-gap:var(--global-kb-gap-md, 2rem);column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_3316ef-eb > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_3316ef-eb > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_3316ef-eb > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_3316ef-eb{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_3316ef-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_3316ef-eb > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_3316ef-eb inner-column-3\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box4016_162b0b-5a .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_162b0b-5a .kt-info-svg-icon-flip, .kt-info-box4016_162b0b-5a .kt-blocks-info-box-number{font-size:25px;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box4016_162b0b-5a .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_162b0b-5a .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box4016_162b0b-5a .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box4016_162b0b-5a .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_162b0b-5a\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_clock kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"10\"\/><polyline points=\"12 6 12 12 16 14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Precision sealing, quiet and durable<\/h3><p class=\"kt-blocks-info-box-text\">Fitted with high-temperature-resistant mechanical seals and silicon carbide bushings, effectively preventing media leakage; combined with high-precision bearings, ensuring smooth operation, low vibration and a long service life even under heavy loads.<\/p><\/div><\/div><\/div>\n\n\n<style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:rgba(255, 255, 255, 0);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap:hover{background:rgba(242, 242, 242, 0);}.kt-info-box4016_91ec5c-c0 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_91ec5c-c0 .kt-info-svg-icon-flip, .kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-number{font-size:25px;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#eeeeee;border-radius:200px;overflow:hidden;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:15px;padding-right:15px;padding-bottom:15px;padding-left:15px;margin-top:0px;margin-right:20px;margin-bottom:0px;margin-left:0px;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-media .kadence-info-box-image-intrisic img{border-radius:200px;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-media{color:var(--global-palette9, #ffffff);background:var(--global-palette1, #3182CE);border-color:#444444;}.kt-info-box4016_91ec5c-c0 .kt-infobox-textcontent h3.kt-blocks-info-box-title{color:var(--global-palette3, #1A202C);font-size:20px;padding-top:0px;padding-right:0px;padding-bottom:5px;padding-left:10px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_91ec5c-c0 .kt-infobox-textcontent .kt-blocks-info-box-text{color:var(--global-palette3, #1A202C);}.wp-block-kadence-infobox.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-text{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:10px;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-learnmore{background:transparent;border-color:#555555;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap:hover .kt-blocks-info-box-learnmore,.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap .kt-blocks-info-box-learnmore:focus{color:#ffffff;background:#444444;border-color:#444444;}@media all and (max-width: 1024px){.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap{padding-top:20px;padding-right:20px;padding-bottom:20px;padding-left:20px;}}@media all and (max-width: 767px){.kt-info-box4016_91ec5c-c0 .kt-blocks-info-box-link-wrap{padding-top:10px;padding-right:10px;padding-bottom:10px;padding-left:10px;}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_91ec5c-c0\"><div class=\"kt-blocks-info-box-link-wrap kt-blocks-info-box-media-align-left kt-info-halign-left kb-info-box-vertical-media-align-top\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-icon-container kt-info-icon-animate-none\"><div class=\"kadence-info-box-icon-inner-container\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_cpu kt-info-svg-icon\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"4\" y=\"4\" width=\"16\" height=\"16\" rx=\"2\" ry=\"2\"\/><rect x=\"9\" y=\"9\" width=\"6\" height=\"6\"\/><line x1=\"9\" y1=\"1\" x2=\"9\" y2=\"4\"\/><line x1=\"15\" y1=\"1\" x2=\"15\" y2=\"4\"\/><line x1=\"9\" y1=\"20\" x2=\"9\" y2=\"23\"\/><line x1=\"15\" y1=\"20\" x2=\"15\" y2=\"23\"\/><line x1=\"20\" y1=\"9\" x2=\"23\" y2=\"9\"\/><line x1=\"20\" y1=\"14\" x2=\"23\" y2=\"14\"\/><line x1=\"1\" y1=\"9\" x2=\"4\" y2=\"9\"\/><line x1=\"1\" y1=\"14\" x2=\"4\" y2=\"14\"\/><\/svg><\/span><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Intelligent protection, safe operation<\/h3><p class=\"kt-blocks-info-box-text\">Equipped with a 100% pure copper motor and a thermal protector, the machine automatically cuts off the power and stops in the event of abnormal conditions such as jamming or overloading, thereby preventing motor burnout and ensuring production safety in complex operating conditions.<\/p><\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4016_7d781c-cb > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_7d781c-cb > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_7d781c-cb > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4016_7d781c-cb > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_7d781c-cb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_7d781c-cb > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_7d781c-cb alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4016_aba98a-dd > .kt-inside-inner-col,.kadence-column4016_aba98a-dd > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_aba98a-dd > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_aba98a-dd > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_aba98a-dd > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_aba98a-dd > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_aba98a-dd{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_aba98a-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_aba98a-dd > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_aba98a-dd\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id4016_f23061-40 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_f23061-40 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_f23061-40 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4016_f23061-40 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_f23061-40 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_f23061-40 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_f23061-40 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4016_ad35f4-93 > .kt-inside-inner-col,.kadence-column4016_ad35f4-93 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_ad35f4-93 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_ad35f4-93 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_ad35f4-93 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_ad35f4-93 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_ad35f4-93{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_ad35f4-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_ad35f4-93 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_ad35f4-93\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading4016_8f78a2-a8, .wp-block-kadence-advancedheading.kt-adv-heading4016_8f78a2-a8[data-kb-block=\"kb-adv-heading4016_8f78a2-a8\"]{margin-top:var(--global-kb-spacing-xxs, 0.5rem);margin-bottom:var(--global-kb-spacing-md, 2rem);text-align:center;font-size:36px;line-height:1.4;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading4016_8f78a2-a8 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading4016_8f78a2-a8[data-kb-block=\"kb-adv-heading4016_8f78a2-a8\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading4016_8f78a2-a8 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading4016_8f78a2-a8[data-kb-block=\"kb-adv-heading4016_8f78a2-a8\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h2 class=\"kt-adv-heading4016_8f78a2-a8 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading4016_8f78a2-a8\">Applications: FYH Series Chemical Resistant Submersible Pump<\/h2>\n\n\n\n<p class=\"has-text-align-center\" style=\"padding-right:3rem;padding-left:3rem\">The <strong>FYH series<\/strong> is a high-performance corrosion-resistant vertical pump engineered by <strong>Changyu Pump<\/strong> to handle the most aggressive industrial fluids. Its robust fluoroplastic construction makes it an ideal anti-corrosive sump pump for the following sectors:<\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-xxs, 0.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);}.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}.kb-row-layout-id4016_a3233f-e3 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}}@media all and (max-width: 1024px){.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap{grid-template-columns:repeat(4, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap > div:not(.added-for-specificity){grid-column:initial;}.kb-row-layout-id4016_a3233f-e3 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_a3233f-e3 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-4-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_a68070-4c > .kt-inside-inner-col,.kadence-column4016_a68070-4c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_a68070-4c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_a68070-4c > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_a68070-4c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_a68070-4c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_a68070-4c{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_a68070-4c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_a68070-4c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_a68070-4c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_7ec208-e8 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_7ec208-e8.wp-block-kadence-infobox{max-width:100%;}.kt-info-box4016_7ec208-e8 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box4016_7ec208-e8 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1536px;height:0px;max-width:100%;}.kt-info-box4016_7ec208-e8 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_7ec208-e8 .kt-info-svg-icon-flip, .kt-info-box4016_7ec208-e8 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box4016_7ec208-e8 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box4016_7ec208-e8 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_7ec208-e8\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions.webp\" alt=\"Crystallizing Chemical Solutions\" width=\"1536\" height=\"864\" class=\"kt-info-box-image wp-image-3190\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Crystallizing-Chemical-Solutions-18x10.webp 18w\" sizes=\"auto, (max-width: 1536px) 100vw, 1536px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Chemical &amp; Petrochemical<\/h3><p class=\"kt-blocks-info-box-text\">Specialised for transferring any concentration of acids, alkalis, and strong oxidisers. Ideal for acid pickling, electrolyte circulation, and volatile chemical handling.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col,.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_4e2ee3-77{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_4e2ee3-77 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_4e2ee3-77\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_a6a7b7-94.wp-block-kadence-infobox{max-width:100%;}.kt-info-box4016_a6a7b7-94 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box4016_a6a7b7-94 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:1100px;height:0px;max-width:100%;}.kt-info-box4016_a6a7b7-94 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_a6a7b7-94 .kt-info-svg-icon-flip, .kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box4016_a6a7b7-94 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box4016_a6a7b7-94 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_a6a7b7-94\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater.webp\" alt=\"Sediment-laden wastewater\" width=\"1100\" height=\"750\" class=\"kt-info-box-image wp-image-3335\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater.webp 1100w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater-300x205.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater-1024x698.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater-150x102.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater-768x524.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Sediment-laden-wastewater-18x12.webp 18w\" sizes=\"auto, (max-width: 1100px) 100vw, 1100px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\">Wastewater &amp; Environmental<\/h3><p class=\"kt-blocks-info-box-text\">A reliable Chemical Resistant Submersible Pump for acidic wastewater lifting and waste acid recovery. The long-shaft design ensures stability in deep sumps and harsh environments.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_ea3c19-3f > .kt-inside-inner-col,.kadence-column4016_ea3c19-3f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_ea3c19-3f > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_ea3c19-3f > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_ea3c19-3f > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_ea3c19-3f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_ea3c19-3f{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_ea3c19-3f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_ea3c19-3f > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_ea3c19-3f\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_f7d73c-2b .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_f7d73c-2b.wp-block-kadence-infobox{max-width:100%;}.kt-info-box4016_f7d73c-2b .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box4016_f7d73c-2b .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:2048px;height:0px;max-width:100%;}.kt-info-box4016_f7d73c-2b .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_f7d73c-2b .kt-info-svg-icon-flip, .kt-info-box4016_f7d73c-2b .kt-blocks-info-box-number{font-size:50px;}.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box4016_f7d73c-2b .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-text{font-size:16px;}.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box4016_f7d73c-2b .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_f7d73c-2b\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Pharmaceutical-Industry-1.webp\" alt=\"\" width=\"2048\" height=\"1365\" class=\"kt-info-box-image wp-image-2323\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Pharmaceutical-Industry-1.webp 2048w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Pharmaceutical-Industry-1-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Pharmaceutical-Industry-1-1024x683.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Pharmaceutical-Industry-1-768x512.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/11\/Pharmaceutical-Industry-1-1536x1024.webp 1536w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Pharmaceutical &amp; Fine Chemical<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Utilizes Changyu Pump fluoroplastic (PTFE\/FEP) linings to ensure zero toxin decomposition<br>. Perfect for transporting high-purity reagents and pharmaceutical intermediates.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_04ec12-f8 > .kt-inside-inner-col,.kadence-column4016_04ec12-f8 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_04ec12-f8 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_04ec12-f8 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_04ec12-f8 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_04ec12-f8 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_04ec12-f8{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_04ec12-f8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_04ec12-f8 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_04ec12-f8\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-column.kb-section-dir-horizontal > .kt-inside-inner-col > .kt-info-box4016_075c9e-a4 .kt-blocks-info-box-link-wrap{max-width:unset;}.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);background:var(--global-palette9, #ffffff);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_075c9e-a4.wp-block-kadence-infobox{max-width:100%;}.kt-info-box4016_075c9e-a4 .kadence-info-box-image-inner-intrisic-container{max-width:400px;}.kt-info-box4016_075c9e-a4 .kadence-info-box-image-inner-intrisic-container .kadence-info-box-image-intrisic{padding-bottom:66.67%;width:550px;height:0px;max-width:100%;}.kt-info-box4016_075c9e-a4 .kadence-info-box-icon-container .kt-info-svg-icon, .kt-info-box4016_075c9e-a4 .kt-info-svg-icon-flip, .kt-info-box4016_075c9e-a4 .kt-blocks-info-box-number{font-size:50px;}.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-media{background:var(--global-palette9, #ffffff);border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-media-container{margin-top:0px;margin-right:0px;margin-bottom:16px;margin-left:0px;}.kt-info-box4016_075c9e-a4 .kt-infobox-textcontent h3.kt-blocks-info-box-title{font-size:var(--global-kb-font-size-md, 1.25rem);padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:5px;margin-right:0px;margin-bottom:10px;margin-left:0px;}.wp-block-kadence-infobox.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-text{font-size:16px;}.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-learnmore{background:transparent;border-width:0px 0px 0px 0px;padding-top:4px;padding-right:8px;padding-bottom:4px;padding-left:8px;margin-top:10px;margin-right:0px;margin-bottom:10px;margin-left:0px;}@media all and (max-width: 1024px){.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}@media all and (max-width: 767px){.kt-info-box4016_075c9e-a4 .kt-blocks-info-box-link-wrap{border-top:0px solid var(--global-palette7, #eeeeee);border-right:0px solid var(--global-palette7, #eeeeee);border-bottom:0px solid var(--global-palette7, #eeeeee);border-left:0px solid var(--global-palette7, #eeeeee);}}<\/style>\n<div class=\"wp-block-kadence-infobox kt-info-box4016_075c9e-a4\"><span class=\"kt-blocks-info-box-link-wrap info-box-link kt-blocks-info-box-media-align-top kt-info-halign-center\"><div class=\"kt-blocks-info-box-media-container\"><div class=\"kt-blocks-info-box-media kt-info-media-animate-none\"><div class=\"kadence-info-box-image-inner-intrisic-container\"><div class=\"kadence-info-box-image-intrisic kt-info-animate-none kb-info-box-image-ratio kb-info-box-image-ratio-land32\"><div class=\"kadence-info-box-image-inner-intrisic\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy.webp\" alt=\"Metallurgy\" width=\"550\" height=\"367\" class=\"kt-info-box-image wp-image-3262\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy.webp 550w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy-150x100.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Metallurgy-18x12.webp 18w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/div><\/div><\/div><\/div><\/div><div class=\"kt-infobox-textcontent\"><h3 class=\"kt-blocks-info-box-title\"><strong>Metallurgy &amp; Surface Treatment<\/strong><\/h3><p class=\"kt-blocks-info-box-text\">Engineered for electroplating lines and metal finishing. The fluoroplastic-lined structure provides industrial-grade durability against corrosive electrolytes and strong oxidizers.<\/p><\/div><\/span><\/div>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">About Changyu Pump: Your Expert in Chemical Resistant Submersible Pump Solutions<\/h2>\n\n\n<style>.kb-row-layout-id4016_268608-be > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_268608-be > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_268608-be > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4016_268608-be > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_268608-be > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_268608-be > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_268608-be alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_d16a18-4d > .kt-inside-inner-col,.kadence-column4016_d16a18-4d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_d16a18-4d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_d16a18-4d > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_d16a18-4d > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_d16a18-4d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_d16a18-4d{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_d16a18-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_d16a18-4d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_d16a18-4d\"><div class=\"kt-inside-inner-col\">\n<p class=\"has-medium-font-size\">As a premier <strong>Chemical Resistant Submersible Pump<\/strong> manufacturer, Changyu Pump combines decades of engineering expertise with military-grade precision. Our FYH series is backed by multiple high-value utility model patents and international quality certifications, ensuring that every unit delivers stable, zero-leakage performance in the most aggressive environments.<\/p>\n\n\n\n<p>Whether you are dealing with high-temperature sulfuric acid or complex pharmaceutical solvents, our technical team provides customised adaptation schemes, including adjustable shaft lengths and optimised flow configurations, to lower your total cost of ownership.<\/p>\n\n\n\n<p><strong><a href=\"https:\/\/changyupump.com\/contacts\/\" data-type=\"page\" data-id=\"17\">Contact us today<\/a><\/strong> to get a professional technical assessment and discover why leading global industries trust Changyu Pump for their critical chemical transfer needs.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_93b517-06 > .kt-inside-inner-col,.kadence-column4016_93b517-06 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_93b517-06 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_93b517-06 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_93b517-06 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_93b517-06 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_93b517-06{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_93b517-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_93b517-06 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_93b517-06\"><div class=\"kt-inside-inner-col\">\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"CHANGYU company introduce\" width=\"720\" height=\"405\" src=\"https:\/\/www.youtube.com\/embed\/WEFwgg-Bu8U?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<h2 class=\"wp-block-heading\">Why Changyu Pump is Your Trusted Partner?<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong><strong>Chemical Resistant Submersible Pump<\/strong> Specialisation:<\/strong> Our R&amp;D team continuously innovates in fluoroplastic lining technology to extend the lifespan of every Chemical Resistant Submersible Pump.<\/li>\n\n\n\n<li><strong>Advanced Quality Control:<\/strong> Each Hydrochloric Acid Pump undergoes rigorous static and dynamic pressure testing to ensure 100% hermetic sealing before shipment.<\/li>\n\n\n\n<li><strong>Global Supply Chain:<\/strong> As a direct factory, Changyu Pump offers competitive pricing and customizable configurations for your Hydrochloric Acid Pump requirements worldwide.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">Factory Show<\/h2>\n\n\n<style>.wp-block-kadence-advancedgallery .kb-gallery-type-grid.kb-gallery-id-4016_8aff6c-39{margin:-5px;}.kb-gallery-type-grid.kb-gallery-id-4016_8aff6c-39 .kadence-blocks-gallery-item{padding:5px;}.kb-gallery-id-4016_8aff6c-39 .kadence-blocks-gallery-item .kb-gal-image-radius, .kb-gallery-id-4016_8aff6c-39 .kb-slide-item .kb-gal-image-radius img{border-radius:0px 0px 0px 0px;;}<\/style><div class=\"kb-gallery-wrap-id-4016_8aff6c-39 alignnone wp-block-kadence-advancedgallery\"><ul class=\"kb-gallery-ul kb-gallery-non-static kb-gallery-type-grid kb-gallery-id-4016_8aff6c-39 kb-gallery-caption-style-bottom-hover kb-gallery-filter-none kb-gallery-magnific-init\" data-image-filter=\"none\" data-item-selector=\".kadence-blocks-gallery-item\" data-lightbox-caption=\"true\" data-columns-xxl=\"5\" data-columns-xl=\"5\" data-columns-md=\"5\" data-columns-sm=\"4\" data-columns-xs=\"4\" data-columns-ss=\"3\"><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" width=\"900\" height=\"506\" alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp\" data-id=\"954\" class=\"wp-image-954\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory37-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"529\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp\" data-id=\"959\" class=\"wp-image-959\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-300x176.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory42-768x451.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp\" data-id=\"927\" class=\"wp-image-927\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory09-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp\" data-id=\"921\" class=\"wp-image-921\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory03-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp\" data-id=\"930\" class=\"wp-image-930\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory12-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp\" data-id=\"940\" class=\"wp-image-940\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory23-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp\" data-id=\"945\" class=\"wp-image-945\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory28-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp\" data-id=\"926\" class=\"wp-image-926\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory08-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-alt=\"Centrifugal pump factory\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\"   alt=\"Centrifugal pump factory\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp\" data-id=\"944\" class=\"wp-image-944\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory27-768x432.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><li class=\"kadence-blocks-gallery-item\"><div class=\"kadence-blocks-gallery-item-inner\"><figure class=\"kb-gallery-figure kb-gallery-item-has-link kadence-blocks-gallery-item-hide-caption\"><a href=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" class=\"kb-gallery-item-link\"   role=\"button\" aria-haspopup=\"dialog\"><div class=\"kb-gal-image-radius\"><div class=\"kb-gallery-image-contain kadence-blocks-gallery-intrinsic kb-gallery-image-ratio-land43 kb-has-image-ratio-land43\" ><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"504\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\"   alt=\"\" data-full-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-light-image=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp\" data-id=\"949\" class=\"wp-image-949\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32.webp 900w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/centrifugal-pump-factory32-768x430.webp 768w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><\/div><\/a><\/figure><\/div><\/li><\/ul><\/div>\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"838\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4.webp\" alt=\"\" class=\"wp-image-1134\" title=\"Centrifugal Chemical Pump Certificate\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4-300x168.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4-1024x572.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Centrifugal-Chemical-Pump-Certificate-4-768x429.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"703\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3.webp\" alt=\"Custom Visit\" class=\"wp-image-1135\" style=\"object-fit:cover\" title=\"Custom Visit\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3.webp 1500w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-300x141.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-1024x480.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Visit-3-768x360.webp 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center\">FAQs<\/h2>\n\n\n<style>.kb-row-layout-id4016_e10f8c-87 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_e10f8c-87 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_e10f8c-87 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id4016_e10f8c-87 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_e10f8c-87 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id4016_e10f8c-87 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_e10f8c-87 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column4016_a9f480-15 > .kt-inside-inner-col,.kadence-column4016_a9f480-15 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_a9f480-15 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_a9f480-15 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_a9f480-15 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_a9f480-15 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_a9f480-15{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_a9f480-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_a9f480-15 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_a9f480-15\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id4016_6b391e-ad .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id4016_6b391e-ad .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:9px;padding-right:13px;padding-bottom:9px;padding-left:13px;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id4016_6b391e-ad .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_6b391e-ad:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id4016_6b391e-ad .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}}@media all and (max-width: 1024px){.kt-accordion-id4016_6b391e-ad .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}@media all and (max-width: 767px){.kt-accordion-id4016_6b391e-ad .kt-accordion-inner-wrap{display:block;}.kt-accordion-id4016_6b391e-ad .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id4016_6b391e-ad .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4016_6b391e-ad .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id4016_6b391e-ad .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4016_6b391e-ad > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id4016_6b391e-ad kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane4016_d7dfd3-00\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q1: What are the primary advantages of using a Changyu Pump FYH Series for chemical processing?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q1: What are the primary advantages of using a Changyu Pump FYH Series for chemical processing?<\/h3>\n\n\n\n<p><strong>A:<\/strong> The <strong>Changyu Pump<\/strong> FYH series is a specialized long-shaft vertical centrifugal pump designed for maximum reliability in aggressive environments. Its primary advantage lies in the full fluoroplastic (PTFE\/FEP) lining of all wetted parts, which provides world-class resistance to any concentration of acids, alkalis, and strong oxidizers without the risk of material degradation.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane4016_362f35-4e\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q3: What critical precautions should be taken during the installation of this anti-corrosive vertical pump?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q3: What critical precautions should be taken during the installation of this anti-corrosive vertical pump?<\/h3>\n\n\n\n<p id=\"p-rc_b79f4b9e086b47fe-196\"><strong>A:<\/strong> During installation, the <strong>Chemical Resistant Submersible Pump<\/strong> must be fixed vertically, with the outlet piping supported by an independent bracket to avoid putting weight on the pump body. Crucially, the maximum liquid level must remain at least 200mm below the base plate to prevent the medium from eroding the bearings.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane4016_f44203-fb\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q5: What is the maintenance procedure for the impeller and seals of this Fluoroplastic Lined Pump?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q5: What is the maintenance procedure for the impeller and seals of this Fluoroplastic Lined Pump?<\/h3>\n\n\n\n<p id=\"p-rc_b79f4b9e086b47fe-198\"><strong>A:<\/strong> Maintenance for this <strong>Chemical Resistant Submersible Pump<\/strong> is simplified by its modular design. To inspect the impeller or high-quality mechanical seal, the motor and brackets can be removed while the base plate remains in place. Always ensure the concentricity of shaft components during reassembly to maintain the pump&#8217;s quiet and vibration-free operation.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_aa52e2-7b > .kt-inside-inner-col,.kadence-column4016_aa52e2-7b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_aa52e2-7b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_aa52e2-7b > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_aa52e2-7b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_aa52e2-7b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_aa52e2-7b{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_aa52e2-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_aa52e2-7b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_aa52e2-7b\"><div class=\"kt-inside-inner-col\"><style>.kt-accordion-id4016_414a49-40 .kt-accordion-inner-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:10px;}.kt-accordion-id4016_414a49-40 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-right:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);padding-left:var(--global-kb-spacing-sm, 1.5rem);}.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;background:#f2f2f2;color:#555555;padding-top:9px;padding-right:13px;padding-bottom:9px;padding-left:13px;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap .kt-blocks-accordion-icon-trigger:before{background:#555555;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger{background:#555555;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-icon-trigger:before{background:#f2f2f2;}.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40 .kt-blocks-accordion-header:focus-visible{color:#444444;background:#eeeeee;border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion--visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle ) .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#444444;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger, body:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger{background:#444444;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:hover .kt-blocks-accordion-icon-trigger:before, body:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:after, body:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible .kt-blocks-accordion-icon-trigger:before{background:#eeeeee;}.kt-accordion-id4016_414a49-40 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{color:#ffffff;background:#444444;border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basiccircle ):not( .kt-accodion-icon-style-xclosecircle ):not( .kt-accodion-icon-style-arrowcircle )  > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#ffffff;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger{background:#ffffff;}.kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:after, .kt-accordion-id4016_414a49-40:not( .kt-accodion-icon-style-basic ):not( .kt-accodion-icon-style-xclose ):not( .kt-accodion-icon-style-arrow ) .kt-blocks-accordion-header.kt-accordion-panel-active .kt-blocks-accordion-icon-trigger:before{background:#444444;}@media all and (max-width: 1024px){.kt-accordion-id4016_414a49-40 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}}@media all and (max-width: 1024px){.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}}@media all and (max-width: 1024px){.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}}@media all and (max-width: 1024px){.kt-accordion-id4016_414a49-40 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}@media all and (max-width: 767px){.kt-accordion-id4016_414a49-40 .kt-accordion-inner-wrap{display:block;}.kt-accordion-id4016_414a49-40 .kt-accordion-inner-wrap .kt-accordion-pane:not(:first-child){margin-top:10px;}.kt-accordion-id4016_414a49-40 .kt-accordion-panel-inner{border-top:0px solid transparent;border-right:0px solid transparent;border-bottom:0px solid transparent;border-left:0px solid transparent;}.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header{border-top:1px solid #f2f2f2;border-right:1px solid #f2f2f2;border-bottom:1px solid #f2f2f2;border-left:1px solid #f2f2f2;}.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header:hover, \n\t\t\t\tbody:not(.hide-focus-outline) .kt-accordion-id4016_414a49-40 .kt-blocks-accordion-header:focus-visible{border-top:1px solid #878787;border-right:1px solid #878787;border-bottom:1px solid #878787;border-left:1px solid #878787;}.kt-accordion-id4016_414a49-40 .kt-accordion-header-wrap .kt-blocks-accordion-header:focus-visible,\n\t\t\t\t.kt-accordion-id4016_414a49-40 > .kt-accordion-inner-wrap > .wp-block-kadence-pane > .kt-accordion-header-wrap > .kt-blocks-accordion-header.kt-accordion-panel-active{border-top:1px solid #444444;border-right:1px solid #444444;border-bottom:1px solid #444444;border-left:1px solid #444444;}}<\/style>\n<div class=\"wp-block-kadence-accordion alignnone\"><div class=\"kt-accordion-wrap kt-accordion-id4016_414a49-40 kt-accordion-has-3-panes kt-active-pane-0 kt-accordion-block kt-pane-header-alignment-left kt-accodion-icon-style-basic kt-accodion-icon-side-right\" style=\"max-width:none\"><div class=\"kt-accordion-inner-wrap\" data-allow-multiple-open=\"false\" data-start-open=\"none\">\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-1 kt-pane4016_628a55-9e\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q2: Does this Chemical Resistant Submersible Pump require manual priming before startup?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q2: Does this Chemical Resistant Submersible Pump require manual priming before startup?<\/h3>\n\n\n\n<p><strong>A:<\/strong> No, the FYH series <strong>Chemical Resistant Submersible Pump<\/strong> features an instant-start technology. Because the pump inlet is directly submerged in the medium, it functions as a self-priming vertical unit that requires no manual liquid filling or air venting, significantly improving operational safety and efficiency in industrial sumps.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-2 kt-pane4016_af4c23-1b\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q4: How does Changyu Pump ensure the safety of the motor in high-load chemical environments?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q4: How does Changyu Pump ensure the safety of the motor in high-load chemical environments?<\/h3>\n\n\n\n<p id=\"p-rc_b79f4b9e086b47fe-197\"><strong>A:<\/strong> Every <strong>Changyu Pump<\/strong> in the FYH range is equipped with a 100% copper-wire motor featuring an integrated thermal protector. This safety system automatically halts operation during abnormal conditions such as impeller jamming or electrical overload, effectively preventing motor burnout and ensuring long-term stable performance.<\/p>\n<\/div><\/div><\/div>\n\n\n\n<div class=\"wp-block-kadence-pane kt-accordion-pane kt-accordion-pane-3 kt-pane4016_81d137-75\"><div class=\"kt-accordion-header-wrap\"><button class=\"kt-blocks-accordion-header kt-acccordion-button-label-show\" type=\"button\"><span class=\"kt-blocks-accordion-title-wrap\"><span class=\"kt-blocks-accordion-title\">Q6: Can this vertical chemical pump handle high-temperature corrosive fluids?<\/span><\/span><span class=\"kt-blocks-accordion-icon-trigger\"><\/span><\/button><\/div><div class=\"kt-accordion-panel kt-accordion-panel-hidden\"><div class=\"kt-accordion-panel-inner\">\n<h3 class=\"wp-block-heading has-medium-font-size\">Q6: Can this vertical chemical pump handle high-temperature corrosive fluids?<\/h3>\n\n\n\n<p><strong>A:<\/strong> Yes, the FYH series is engineered to handle a wide thermal range from -20\u00b0C~90\u00b0C. By utilizing high-temperature resistant mechanical seals and silicon carbide shaft sleeves, this <strong>Chemical Resistant Submersible Pump<\/strong> remains stable when transporting volatile or hot corrosive media like sulfuric or hydrochloric acid.<\/p>\n<\/div><\/div><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4016_d0ec3a-ae > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_d0ec3a-ae > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_d0ec3a-ae > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xl, 4rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4016_d0ec3a-ae > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_d0ec3a-ae > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_d0ec3a-ae > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_d0ec3a-ae alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4016_70cc59-af > .kt-inside-inner-col,.kadence-column4016_70cc59-af > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_70cc59-af > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_70cc59-af > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_70cc59-af > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_70cc59-af > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_70cc59-af{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_70cc59-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_70cc59-af > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_70cc59-af\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Project Showcases<\/h2>\n\n\n\n<p class=\"has-text-align-center\"><strong>Changyu Pump<\/strong> has successfully deployed the FYH Series Chemical Resistant Submersible Pump in over 500+ industrial projects worldwide, ensuring safe fluid handling in extreme environments.<\/p>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_80b69c-27 > .kt-inside-inner-col,.kadence-column4016_80b69c-27 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_80b69c-27 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_80b69c-27 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_80b69c-27 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_80b69c-27 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_80b69c-27{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_80b69c-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_80b69c-27 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_80b69c-27\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop4016_a569e6-b4 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop4016_a569e6-b4 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop4016_a569e6-b4 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop4016_a569e6-b4 .entry-content:after{height:0px;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop4016_a569e6-b4 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop4016_a569e6-b4 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop4016_a569e6-b4.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop4016_a569e6-b4 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-3648 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/project\/corrosion-resistant-centrifugal-pump-alumina-solution-project-australia\/\" aria-label=\"Corrosion Resistant Centrifugal Pump Project for Alumina Solution Transfer in Australia\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-1024x576.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"corrosion resistant centrifugal pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-1024x576.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-300x169.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-150x84.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-768x432.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2-18x10.webp 18w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/02\/corrosion-resistant-centrifugal-pump-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/project\/corrosion-resistant-centrifugal-pump-alumina-solution-project-australia\/\">Corrosion Resistant Centrifugal Pump Project for Alumina Solution Transfer in Australia<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3357 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/project\/industrial-process-pump-pac-production-india\/\" aria-label=\"Industrial Process Pump Application for PAC Production in India Case\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"397\" height=\"280\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Industrial process pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1.webp 397w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1-300x212.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1-150x106.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/Industrial-process-pump-4-1-18x12.webp 18w\" sizes=\"auto, (max-width: 397px) 100vw, 397px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/project\/industrial-process-pump-pac-production-india\/\">Industrial Process Pump Application for PAC Production in India Case<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3297 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/project\/vietnam-zinc-sulfate-slurry-pump\/\" aria-label=\"Vietnam Zinc Smelter Wet Zinc Sulfate Slurry Pumping Case\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"769\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-1024x769.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"zinc sulfate slurry pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-1024x769.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/zinc-sulfate-slurry-pump-2.webp 1279w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/project\/vietnam-zinc-sulfate-slurry-pump\/\">Vietnam Zinc Smelter Wet Zinc Sulfate Slurry Pumping Case<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3205 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/project\/uhb-slurry-pump-for-sulfuric-acid\/\" aria-label=\"UHB Slurry Pump for Sulfuric Acid in Salt Crystal Separation\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-1024x768.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"slurry pump for sulfuric acid\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-1024x768.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2-16x12.webp 16w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/01\/slurry-pump-for-sulfuric-acid-2.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/project\/uhb-slurry-pump-for-sulfuric-acid\/\">UHB Slurry Pump for Sulfuric Acid in Salt Crystal Separation<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-2841 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/project\/slurry-pump-case-for-sulfuric-acid-waste-gas-scrubber\/\" aria-label=\"Application Case of Slurry Pump for Scrubber in Sulfuric Acid Production Waste Gas Treatment\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"596\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-1024x596.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Case of Slurry Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-1024x596.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-300x175.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-150x87.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310-768x447.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/12\/Application-Case-of-Slurry-Pump-e1766026234310.webp 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/project\/slurry-pump-case-for-sulfuric-acid-waste-gas-scrubber\/\">Application Case of Slurry Pump for Scrubber in Sulfuric Acid Production Waste Gas Treatment<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-878 project type-project status-publish has-post-thumbnail hentry\"><article class=\"kt-blocks-post-grid-item hide-on-js\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/project\/stainless-steel-magnetic-pump-brazil\/\" aria-label=\"Customized Stainless Steel Insulated Magnetic Pump for a Petrochemical Plant in Brazil\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-1024x683.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Custom Stainless Steel Insulated Magnetic Pump for Brazilian Client\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-1024x683.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-300x200.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-768x512.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-1536x1024.webp 1536w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/Custom-Stainless-Steel-Insulated-Magnetic-Pump-for-Brazilian-Client-2048x1366.webp 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/project\/stainless-steel-magnetic-pump-brazil\/\">Customized Stainless Steel Insulated Magnetic Pump for a Petrochemical Plant in Brazil<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id4016_219714-27 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id4016_219714-27 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id4016_219714-27 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id4016_219714-27 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id4016_219714-27 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id4016_219714-27 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id4016_219714-27 alignfull wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-row kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column4016_44ed15-56 > .kt-inside-inner-col,.kadence-column4016_44ed15-56 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_44ed15-56 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_44ed15-56 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_44ed15-56 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_44ed15-56 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_44ed15-56{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_44ed15-56 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_44ed15-56 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_44ed15-56\"><div class=\"kt-inside-inner-col\">\n<h2 class=\"wp-block-heading has-text-align-center\">Related Blogs<\/h2>\n<\/div><\/div>\n\n\n<style>.kadence-column4016_0c5302-c0 > .kt-inside-inner-col,.kadence-column4016_0c5302-c0 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column4016_0c5302-c0 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column4016_0c5302-c0 > .kt-inside-inner-col{flex-direction:column;}.kadence-column4016_0c5302-c0 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column4016_0c5302-c0 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column4016_0c5302-c0{position:relative;}@media all and (max-width: 1024px){.kadence-column4016_0c5302-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column4016_0c5302-c0 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column4016_0c5302-c0\"><div class=\"kt-inside-inner-col\"><style>.kt-post-loop4016_bada72-55 .kadence-post-image{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.kt-post-loop4016_bada72-55 .kt-post-grid-wrap{gap:30px 30px;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;overflow:hidden;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item .kt-blocks-post-grid-item-inner{padding-top:15px;padding-right:25px;padding-bottom:25px;padding-left:25px;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item header{padding-top:0px;padding-right:0px;padding-bottom:10px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item .entry-title{padding-top:10px;padding-right:0px;padding-bottom:5px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:20px;line-height:30px;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item .kt-blocks-post-top-meta{color:#777777;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a{color:#777777;}.kt-post-loop4016_bada72-55 .kt-blocks-post-grid-item .kt-blocks-post-top-meta a:hover{color:#444444;}.kt-post-loop4016_bada72-55 .entry-content{padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:var(--global-kb-font-size-md, 1.25rem);}.kt-post-loop4016_bada72-55 .kt-blocks-post-footer{color:#777777;border-top-width:0px;border-right-width:0px;border-bottom-width:0px;border-left-width:0px;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;font-size:12px;line-height:20px;}.kt-post-loop4016_bada72-55 .entry-content:after{height:0px;}.kt-post-loop4016_bada72-55 .kt-blocks-post-footer a{color:#777777;}.kt-post-loop4016_bada72-55 .kt-blocks-post-footer a:hover{color:#444444;}.kt-post-loop4016_bada72-55 .kb-filter-item{border-top-width:0px;border-right-width:0px;border-bottom-width:2px;border-left-width:0px;padding-top:5px;padding-right:8px;padding-bottom:5px;padding-left:8px;margin-top:0px;margin-right:10px;margin-bottom:0px;margin-left:0px;}.kt-post-loop4016_bada72-55.kt-post-grid-layout-carousel .kb-post-grid-pause-button{color:#fff;background-color:rgba(0, 0, 0, 0.5);border:1px solid transparent;}<\/style><div class=\"wp-block-kadence-postgrid kt-blocks-post-loop-block alignnone kt-post-loop4016_bada72-55 kt-post-grid-layout-carousel kadence-splide-wrap \"><div class=\"kt-post-grid-layout-carousel-wrap splide kt-carousel-arrowstyle-whiteondark kt-carousel-dotstyle-dark kb-slider-group-arrow kb-slider-arrow-position-center\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\" data-slider-anim-speed=\"400\" data-slider-scroll=\"1\" data-slider-dots=\"true\" data-slider-arrows=\"true\" data-slider-hover-pause=\"false\" data-slider-auto=\"true\"  data-slider-auto-scroll=\"false\" data-slider-speed=\"7000\" data-slider-gap=\"30\" data-slider-gap-tablet=\"30\" data-slider-gap-mobile=\"30\" data-slider-gap-unit=\"px\" data-show-pause-button=\"false\" data-item-selector=\".kt-post-masonry-item\" aria-label=\"Post Carousel\"><div class=\"kadence-splide-slider-init splide__track\"><ul class=\"kadence-splide-slider-wrap kt-post-grid-wrap\" data-columns-xxl=\"4\" data-columns-xl=\"4\" data-columns-md=\"4\" data-columns-sm=\"3\" data-columns-xs=\"2\" data-columns-ss=\"2\"><li class=\"kt-post-slider-item post-3924 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-transfer-pump tag-changyu-pump tag-chemical-acid-pump tag-chemical-pump tag-chemical-transfer-pump tag-drum-pump tag-fluoroplastic-pump tag-semi-submerged-pump-2 tag-sump-pump-2 tag-vertical-chemical-pump-2\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/vertical-chemical-pump-the-complete-selection-guide-2026\/\" aria-label=\"Vertical Chemical Pump: The Complete Selection Guide 2026\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/vertical-chemical-pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"Vertical Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/vertical-chemical-pump.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/vertical-chemical-pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/vertical-chemical-pump-150x113.webp 150w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/vertical-chemical-pump-768x576.webp 768w, https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/vertical-chemical-pump-16x12.webp 16w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/vertical-chemical-pump-the-complete-selection-guide-2026\/\">Vertical Chemical Pump: The Complete Selection Guide 2026<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/changyu-pump\/\" rel=\"tag\">Changyu Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-acid-pump\/\" rel=\"tag\">Chemical Acid Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-transfer-pump\/\" rel=\"tag\">Chemical Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/drum-pump\/\" rel=\"tag\">Drum Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/fluoroplastic-pump\/\" rel=\"tag\">Fluoroplastic Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/semi-submerged-pump-2\/\" rel=\"tag\">Semi Submerged Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/sump-pump-2\/\" rel=\"tag\">Sump Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/vertical-chemical-pump-2\/\" rel=\"tag\">Vertical Chemical Pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3974 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-pump tag-chemical-acid-pump tag-chemical-acid-transfer-pump tag-chemical-pump tag-chemical-transfer-pump tag-nitric-acid-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/chemical-acid-transfer-pump-for-nitric-acid\/\" aria-label=\"Chemical Acid Transfer Pump for Nitric Acid\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/FZB-Fluorine-lined-Self-Priming-Centrifugal-Pump\u200b.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"FZB Fluorine-lined Self-Priming Centrifugal Pump\u200b\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/FZB-Fluorine-lined-Self-Priming-Centrifugal-Pump\u200b.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/FZB-Fluorine-lined-Self-Priming-Centrifugal-Pump\u200b-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/FZB-Fluorine-lined-Self-Priming-Centrifugal-Pump\u200b-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/chemical-acid-transfer-pump-for-nitric-acid\/\">Chemical Acid Transfer Pump for Nitric Acid<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/acid-pump\/\" rel=\"tag\">Acid Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-acid-pump\/\" rel=\"tag\">Chemical Acid Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-acid-transfer-pump\/\" rel=\"tag\">Chemical Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-transfer-pump\/\" rel=\"tag\">Chemical Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/nitric-acid-pump\/\" rel=\"tag\">nitric acid pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3844 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-chemical-drum-pump tag-fluoroplastic-submersible-pump tag-semi-submerged-pump tag-semi-submersible-pump tag-stainless-steel-vertical-submersible-pump tag-vertical-column-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/semi-submersible-pump-guide-industrial-chemical-uses\/\" aria-label=\"Semi-submersible Pump Guide: Industrial &amp; Chemical Uses\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"977\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/HD-Chemical-Drum-Pump\u200b-4.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"HD Chemical Drum Pump\u200b\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/HD-Chemical-Drum-Pump\u200b-4.webp 1024w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/HD-Chemical-Drum-Pump\u200b-4-300x286.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/HD-Chemical-Drum-Pump\u200b-4-768x733.webp 768w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/semi-submersible-pump-guide-industrial-chemical-uses\/\">Semi-submersible Pump Guide: Industrial &amp; Chemical Uses<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-drum-pump\/\" rel=\"tag\">chemical drum pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/fluoroplastic-submersible-pump\/\" rel=\"tag\">fluoroplastic submersible pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/semi-submerged-pump\/\" rel=\"tag\">semi-submerged pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/semi-submersible-pump\/\" rel=\"tag\">Semi-submersible Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/stainless-steel-vertical-submersible-pump\/\" rel=\"tag\">stainless steel vertical submersible pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/vertical-column-pump\/\" rel=\"tag\">vertical column pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><li class=\"kt-post-slider-item post-3997 post type-post status-publish format-standard has-post-thumbnail hentry category-blog tag-acid-pump tag-acid-transfer-pump tag-chemical-pump tag-chemical-transfer-pump tag-phosphoric-acid-pump\"><article class=\"kt-blocks-post-grid-item\"><div class=\"kt-blocks-post-grid-item-inner-wrap kt-feat-image-align-top kt-feat-image-mobile-align-top\"><div class=\"kadence-post-image\"><div class=\"kadence-post-image-intrisic kt-image-ratio-75\" style=\"padding-bottom:75%;\"><div class=\"kadence-post-image-inner-intrisic\"><a aria-hidden=\"true\" tabindex=\"-1\" role=\"presentation\" href=\"https:\/\/changyupump.com\/id\/blog\/phosphoric-acid-pump-selection-guide-overcoming-corrosion-viscosity\/\" aria-label=\"Phosphoric Acid Pump Selection Guide: Overcoming Corrosion &amp; Viscosity\" class=\"kadence-post-image-inner-wrap\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-High-Temperature-Magnetic-Drive-Pump.webp\" class=\"attachment-large size-large wp-post-image\" alt=\"CYQ High Temperature Magnetic Drive Pump\" srcset=\"https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-High-Temperature-Magnetic-Drive-Pump.webp 800w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-High-Temperature-Magnetic-Drive-Pump-300x225.webp 300w, https:\/\/changyupump.com\/wp-content\/uploads\/2025\/10\/CYQ-High-Temperature-Magnetic-Drive-Pump-768x576.webp 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/a><\/div><\/div><\/div><div class=\"kt-blocks-post-grid-item-inner\"><header><h2 class=\"entry-title\"><a href=\"https:\/\/changyupump.com\/id\/blog\/phosphoric-acid-pump-selection-guide-overcoming-corrosion-viscosity\/\">Phosphoric Acid Pump Selection Guide: Overcoming Corrosion &amp; Viscosity<\/a><\/h2><div class=\"kt-blocks-post-top-meta\"><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-author-pretext\">By <\/span><a href=\"https:\/\/changyupump.com\/id\/author\/changyu_\/\" class=\"kt-blocks-post-author-link fn\">Changyu_<\/a><\/div><div class=\"kt-blocks-meta-divider kt-blocks-meta-no-divider\"><\/div><div class=\"kt-blocks-post-author\"><span class=\"kt-blocks-category-pretext\">Posted in <\/span><span class=\"kt-blocks-categories\"><a href=\"https:\/\/changyupump.com\/id\/category\/blog\/\" class=\"category-link-blog\" rel=\"tag\">Blog<\/a><\/span><\/div><\/div><\/header><div class=\"entry-content\"><\/div><footer class=\"kt-blocks-post-footer\"><div class=\"kt-blocks-post-footer-left\"><div class=\"kt-blocks-tags kt-blocks-post-footer-section\"><span class=\"kt-blocks-tags-icon\"><svg version=\"1.1\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"kt-blocks-tag-svg\" width=\"36\" height=\"32\" fill=\"currentColor\" viewBox=\"0 0 36 32\"><title>Tag<\/title><path d=\"M34.939 19.939l-8.879-8.879c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h18c0.825 0 1.977-0.477 2.561-1.061l8.879-8.879c0.583-0.583 0.583-1.538-0-2.121zM25 24c-1.657 0-3-1.343-3-3s1.343-3 3-3 3 1.343 3 3-1.343 3-3 3z\"><\/path><path d=\"M2 8h21l-0.939-0.939c-0.583-0.583-1.736-1.061-2.561-1.061h-18c-0.825 0-1.5 0.675-1.5 1.5v19c0 0.825 0.675 1.5 1.5 1.5h0.5v-20z\"><\/path><\/svg><\/span><a href=\"https:\/\/changyupump.com\/id\/tag\/acid-pump\/\" rel=\"tag\">Acid Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/acid-transfer-pump\/\" rel=\"tag\">Acid Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-pump\/\" rel=\"tag\">Chemical Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/chemical-transfer-pump\/\" rel=\"tag\">Chemical Transfer Pump<\/a>, <a href=\"https:\/\/changyupump.com\/id\/tag\/phosphoric-acid-pump\/\" rel=\"tag\">Phosphoric Acid Pump<\/a><\/div><\/div><div class=\"kt-blocks-post-footer-right\"><\/div><\/footer><\/div><\/div><\/article><\/li><\/ul><\/div><\/div><\/div><!-- .wp-block-kadence-postgrid --><\/div><\/div>\n\n<\/div><\/div>\n\n<!-- [element-1114] --><style>.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-lg, 4rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1500px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xl, 4rem);grid-template-columns:minmax(0, calc(45% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)))minmax(0, calc(55% - ((var(--global-kb-gap-lg, 4rem) * 1 )\/2)));}.kb-row-layout-id1114_136e69-11 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-lg, 3rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1114_136e69-11 > .kt-row-column-wrap{padding-right:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1114_136e69-11 alignfull has-theme-palette9-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-row kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{display:flex;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col,.kadence-column1114_03d1b0-0d > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col > .aligncenter{width:100%;}.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_03d1b0-0d{text-align:left;}.kadence-column1114_03d1b0-0d{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 1024px){.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1114_03d1b0-0d{align-self:center;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}.kadence-column1114_03d1b0-0d > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_03d1b0-0d kb-section-dir-vertical inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"]{margin-top:var(--global-kb-spacing-xs, 1rem);margin-bottom:var(--global-kb-spacing-sm, 1.5rem);text-align:left;font-size:32px;line-height:1.1;font-weight:700;font-style:normal;text-transform:capitalize;}.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24, .wp-block-kadence-advancedheading.kt-adv-heading1114_6c6840-24[data-kb-block=\"kb-adv-heading1114_6c6840-24\"]{font-size:var(--global-kb-font-size-lg, 2rem);}}<\/style>\n<h2 class=\"kt-adv-heading1114_6c6840-24 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1114_6c6840-24\">Request a free quote<\/h2>\n\n\n<style>.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"]{margin-bottom:var(--global-kb-spacing-sm, 1.5rem);font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_7bff25-4d[data-kb-block=\"kb-adv-heading1114_7bff25-4d\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<p class=\"kt-adv-heading1114_7bff25-4d wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1114_7bff25-4d\">Please fill in the details of your pumped liquid, including flow, head, specific gravity, and temperature, so we can recommend the best pump and provide a precise quote.<\/p>\n\n\n<style>.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76:not(.this-stops-third-party-issues){margin-top:0px;margin-bottom:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list:not(.this-prevents-issues):not(.this-stops-third-party-issues):not(.tijsloc){margin-top:0px;margin-right:0px;margin-bottom:0px;margin-left:0px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list{grid-row-gap:5px;}.wp-block-kadence-iconlist.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list .kt-svg-icon-list-item-wrap .kt-svg-icon-list-single{margin-right:10px;}.kt-svg-icon-list-items1114_923d6b-76 ul.kt-svg-icon-list .kt-svg-icon-list-level-0 .kt-svg-icon-list-single svg{font-size:20px;}<\/style>\n<div class=\"wp-block-kadence-iconlist kt-svg-icon-list-items kt-svg-icon-list-items1114_923d6b-76 kt-svg-icon-list-columns-1 alignnone\"><ul class=\"kt-svg-icon-list\"><style>.kt-svg-icon-list-item-1114_3d05c4-55 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_3d05c4-55\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_edit kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20 14.66V20a2 2 0 0 1-2 2H4a2 2 0 0 1-2-2V6a2 2 0 0 1 2-2h5.34\"\/><polygon points=\"18 2 22 6 12 16 8 16 8 12 18 2\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Customized Pump Solutions<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_a819a4-1b .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_a819a4-1b\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_users kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M17 21v-2a4 4 0 0 0-4-4H5a4 4 0 0 0-4 4v2\"\/><circle cx=\"9\" cy=\"7\" r=\"4\"\/><path d=\"M23 21v-2a4 4 0 0 0-3-3.87\"\/><path d=\"M16 3.13a4 4 0 0 1 0 7.75\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Fast Quotation within 24 hours<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_05ee61-11 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_05ee61-11\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_feather kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M20.24 12.24a6 6 0 0 0-8.49-8.49L5 10.5V19h8.5z\"\/><line x1=\"16\" y1=\"8\" x2=\"2\" y2=\"22\"\/><line x1=\"17\" y1=\"15\" x2=\"9\" y2=\"15\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Factory Direct with Competitive Price<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_5f1d2f-38 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_5f1d2f-38\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_settings kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"12\" r=\"3\"\/><path d=\"M19.4 15a1.65 1.65 0 0 0 .33 1.82l.06.06a2 2 0 0 1 0 2.83 2 2 0 0 1-2.83 0l-.06-.06a1.65 1.65 0 0 0-1.82-.33 1.65 1.65 0 0 0-1 1.51V21a2 2 0 0 1-2 2 2 2 0 0 1-2-2v-.09A1.65 1.65 0 0 0 9 19.4a1.65 1.65 0 0 0-1.82.33l-.06.06a2 2 0 0 1-2.83 0 2 2 0 0 1 0-2.83l.06-.06a1.65 1.65 0 0 0 .33-1.82 1.65 1.65 0 0 0-1.51-1H3a2 2 0 0 1-2-2 2 2 0 0 1 2-2h.09A1.65 1.65 0 0 0 4.6 9a1.65 1.65 0 0 0-.33-1.82l-.06-.06a2 2 0 0 1 0-2.83 2 2 0 0 1 2.83 0l.06.06a1.65 1.65 0 0 0 1.82.33H9a1.65 1.65 0 0 0 1-1.51V3a2 2 0 0 1 2-2 2 2 0 0 1 2 2v.09a1.65 1.65 0 0 0 1 1.51 1.65 1.65 0 0 0 1.82-.33l.06-.06a2 2 0 0 1 2.83 0 2 2 0 0 1 0 2.83l-.06.06a1.65 1.65 0 0 0-.33 1.82V9a1.65 1.65 0 0 0 1.51 1H21a2 2 0 0 1 2 2 2 2 0 0 1-2 2h-.09a1.65 1.65 0 0 0-1.51 1z\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">Professional engineers, one-on-one technical consultation<\/span><\/li>\n\n\n<style>.kt-svg-icon-list-item-1114_a211a7-13 .kt-svg-icon-list-text mark.kt-highlight{background-color:unset;font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}<\/style>\n<li class=\"wp-block-kadence-listitem kt-svg-icon-list-item-wrap kt-svg-icon-list-item-1114_a211a7-13\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_award kt-svg-icon-list-single\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><circle cx=\"12\" cy=\"8\" r=\"7\"\/><polyline points=\"8.21 13.89 7 23 12 20 17 23 15.79 13.88\"\/><\/svg><\/span><span class=\"kt-svg-icon-list-text\">CE\/ISO certified pumps with strict testing before shipment<\/span><\/li>\n<\/ul><\/div>\n\n\n<style>.kadence-column1114_77e08c-18 > .kt-inside-inner-col{display:flex;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col,.kadence-column1114_77e08c-18 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_77e08c-18{position:relative;}.kadence-column1114_77e08c-18, .kt-inside-inner-col > .kadence-column1114_77e08c-18:not(.specificity){margin-top:var(--global-kb-spacing-lg, 3rem);margin-bottom:var(--global-kb-spacing-xs, 1rem);}@media all and (max-width: 1024px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:center;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kadence-column1114_77e08c-18 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > *, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1114_77e08c-18 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1114_77e08c-18 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_77e08c-18 kb-section-dir-horizontal\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"]{font-size:var(--global-kb-font-size-md, 1.25rem);line-height:1;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2, .wp-block-kadence-advancedheading.kt-adv-heading1114_b234f2-d2[data-kb-block=\"kb-adv-heading1114_b234f2-d2\"]{text-align:center!important;}}<\/style>\n<div class=\"kt-adv-heading1114_b234f2-d2 wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1114_b234f2-d2\">Follow Us:<\/div>\n\n\n<style>.kt-svg-icons1114_296db3-9a .kt-svg-item-0 .kb-svg-icon-wrap{color:var(--global-palette4, #2D3748);font-size:50px;}.wp-block-kadence-icon.kt-svg-icons1114_296db3-9a{justify-content:flex-start;gap:20px;}@media all and (max-width: 1024px){.wp-block-kadence-icon.kt-svg-icons1114_296db3-9a{justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-icon kt-svg-icons kt-svg-icons1114_296db3-9a alignnone\"><style>.kt-svg-item-1114_b484c3-db .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_b484c3-db .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:20px;}.kt-svg-item-1114_b484c3-db:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_b484c3-db\"><a href=\"https:\/\/www.facebook.com\/profile.php?id=61564021046258\" class=\"kt-svg-icon-link\" aria-label=\"Facebook\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_facebook-n\"><svg viewBox=\"0 0 512 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M504 256C504 119 393 8 256 8S8 119 8 256c0 123.78 90.69 226.38 209.25 245V327.69h-63V256h63v-54.64c0-62.15 37-96.48 93.67-96.48 27.14 0 55.52 4.84 55.52 4.84v61h-31.28c-30.8 0-40.41 19.12-40.41 38.73V256h68.78l-11 71.69h-57.78V501C413.31 482.38 504 379.78 504 256z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_3f5c48-35 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_3f5c48-35 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_3f5c48-35\"><a href=\"https:\/\/www.linkedin.com\/company\/anhui-changyu-pump-valve-co-ltd\/?viewAsMember=true\" class=\"kt-svg-icon-link\" aria-label=\"Linkedin\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_linkedin\"><svg viewBox=\"0 0 448 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M416 32H31.9C14.3 32 0 46.5 0 64.3v383.4C0 465.5 14.3 480 31.9 480H416c17.6 0 32-14.5 32-32.3V64.3c0-17.8-14.4-32.3-32-32.3zM135.4 416H69V202.2h66.5V416zm-33.2-243c-21.3 0-38.5-17.3-38.5-38.5S80.9 96 102.2 96c21.2 0 38.5 17.3 38.5 38.5 0 21.3-17.2 38.5-38.5 38.5zm282.1 243h-66.4V312c0-24.8-.5-56.7-34.5-56.7-34.6 0-39.9 27-39.9 54.9V416h-66.4V202.2h63.7v29.2h.9c8.9-16.8 30.6-34.5 62.9-34.5 67.2 0 79.7 44.3 79.7 101.9V416z\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_7e9ec1-58 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_7e9ec1-58 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:17px;}.kt-svg-item-1114_7e9ec1-58:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_7e9ec1-58\"><a href=\"https:\/\/www.instagram.com\/changyupump\/\" class=\"kt-svg-icon-link\" aria-label=\"Ins\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fe_instagram\"><svg viewBox=\"0 0 24 24\"  fill=\"none\" stroke=\"currentColor\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><rect x=\"2\" y=\"2\" width=\"20\" height=\"20\" rx=\"5\" ry=\"5\"\/><path d=\"M16 11.37A4 4 0 1 1 12.63 8 4 4 0 0 1 16 11.37z\"\/><line x1=\"17.5\" y1=\"6.5\" x2=\"17.5\" y2=\"6.5\"\/><\/svg><\/span><\/a><\/div>\n\n\n<style>.kt-svg-item-1114_177ba8-54 .kb-svg-icon-wrap, .kt-svg-style-stacked.kt-svg-item-1114_177ba8-54 .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);font-size:22px;}.kt-svg-item-1114_177ba8-54:hover .kb-svg-icon-wrap{color:var(--global-palette2, #2B6CB0);}<\/style>\n<div class=\"wp-block-kadence-single-icon kt-svg-style-default kt-svg-icon-wrap kt-svg-item-1114_177ba8-54\"><a href=\"https:\/\/www.youtube.com\/@Changyu-CY\" class=\"kt-svg-icon-link\" aria-label=\"Youtube\" target=\"_blank\" rel=\"noopener\"><span class=\"kb-svg-icon-wrap kb-svg-icon-fa_youtube\"><svg viewBox=\"0 0 576 512\"  fill=\"currentColor\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"  aria-hidden=\"true\"><path d=\"M549.655 124.083c-6.281-23.65-24.787-42.276-48.284-48.597C458.781 64 288 64 288 64S117.22 64 74.629 75.486c-23.497 6.322-42.003 24.947-48.284 48.597-11.412 42.867-11.412 132.305-11.412 132.305s0 89.438 11.412 132.305c6.281 23.65 24.787 41.5 48.284 47.821C117.22 448 288 448 288 448s170.78 0 213.371-11.486c23.497-6.321 42.003-24.171 48.284-47.821 11.412-42.867 11.412-132.305 11.412-132.305s0-89.438-11.412-132.305zm-317.51 213.508V175.185l142.739 81.205-142.739 81.201z\"\/><\/svg><\/span><\/a><\/div>\n<\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-md, 2rem);padding-right:var(--global-kb-spacing-md, 2rem);padding-bottom:var(--global-kb-spacing-md, 2rem);padding-left:var(--global-kb-spacing-md, 2rem);}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col,.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col:before{border-top-left-radius:5px;border-top-right-radius:5px;border-bottom-right-radius:5px;border-bottom-left-radius:5px;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{column-gap:0px;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{background-color:var(--global-palette8, #F7FAFC);}.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1114_ac3a5c-85{text-align:left;}.kadence-column1114_ac3a5c-85{position:relative;}@media all and (max-width: 1024px){.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1114_ac3a5c-85 > .kt-inside-inner-col{padding-top:var(--global-kb-spacing-xs, 1rem);padding-right:var(--global-kb-spacing-xs, 1rem);padding-bottom:var(--global-kb-spacing-xs, 1rem);padding-left:var(--global-kb-spacing-xs, 1rem);flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1114_ac3a5c-85 kb-section-dir-vertical inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-text-style-field, .kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-select-style-field{color:var(--global-palette3, #1A202C);border-width:0px 0px 3px 0px;background:rgba(0, 0, 0, 0);border-color:var(--global-palette2, #2B6CB0);}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit{border-radius:50px;background:var(--global-palette2, #2B6CB0);}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit:hover, .kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit:focus {background:#019141;}.kadence-form-1114_7d9556-ee .kb-form .kadence-blocks-form-field .kb-forms-submit{text-transform:uppercase;}.kb-form input.kadence-blocks-field.verify{opacity:0.0;position:absolute;top:0.0;left:0.0;width:0.0;height:0.0;z-index:-1;}<\/style>\n<div class=\"wp-block-kadence-form kadence-form-1114_7d9556-ee kb-form-wrap\"><form class=\"kb-form\" action=\"\" method=\"post\"><div class=\"kadence-blocks-form-field kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_0\" id=\"kb_field_1114_7d9556-ee_0\" data-label=\"Name\" type=\"text\" placeholder=\"Your Name\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-0\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-1 kb-field-desk-width-100 kb-input-size-standard\"><input name=\"kb_field_1\" id=\"kb_field_1114_7d9556-ee_1\" data-label=\"Email\" type=\"email\" placeholder=\"Email Address\" value=\"\" data-type=\"email\" class=\"kb-field kb-text-style-field kb-email-field kb-field-1\" data-required=\"yes\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-2 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_2\" id=\"kb_field_1114_7d9556-ee_2\" data-label=\"Phone\/WA\" type=\"text\" placeholder=\"Phone\/WA\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-2\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-3 kb-field-desk-width-50 kb-input-size-standard\"><input name=\"kb_field_3\" id=\"kb_field_1114_7d9556-ee_3\" data-label=\"Country\" type=\"text\" placeholder=\"Country\" value=\"\" data-type=\"text\" class=\"kb-field kb-text-style-field kb-text-field kb-field-3\"\/><\/div><div class=\"kadence-blocks-form-field kb-form-field-4 kb-field-desk-width-100 kb-input-size-standard\"><textarea name=\"kb_field_4\" id=\"kb_field_1114_7d9556-ee_4\" data-label=\"Message\" type=\"textarea\" placeholder=\"Message\" data-type=\"textarea\" class=\"kb-field kb-text-style-field kb-textarea-field kb-field-4\" rows=\"4\" data-required=\"yes\"><\/textarea><\/div><input type=\"hidden\" name=\"_kb_form_id\" value=\"1114_7d9556-ee\"\/><input type=\"hidden\" name=\"_kb_form_post_id\" value=\"1114\"\/><input type=\"hidden\" name=\"action\" value=\"kb_process_ajax_submit\"\/><label class=\"kadence-verify-label\">Email<input class=\"kadence-blocks-field verify\" type=\"text\" name=\"_kb_verify_email\" autocomplete=\"new-password\" aria-hidden=\"true\" placeholder=\"Email\" tabindex=\"-1\" data-1p-ignore=\"true\" data-lpignore=\"true\" \/><\/label><div class=\"kadence-blocks-form-field kb-submit-field kb-field-desk-width-100\"><button class=\"kb-forms-submit button kb-button-size-standard kb-button-width-full\"><strong>Send Your Inquiry Now<\/strong><\/button><\/div><\/form><\/div>\n<noscript><div class=\"kadence-blocks-form-message kadence-blocks-form-warning\">Please enable JavaScript in your browser to submit the form<\/div><style>.kadence-form-1114_7d9556-ee .kadence-blocks-form-field.kb-submit-field { display: none; }<\/style><\/noscript><\/div><\/div>\n\n<\/div><\/div>\n\n\n<p><\/p>\n<!-- [\/element-1114] -->\n","protected":false},"excerpt":{"rendered":"<p>Seri FYH dari Changyu Pump adalah Pompa Submersible Tahan Bahan Kimia utama dengan desain vertikal tanpa cat dasar. Dirancang untuk media agresif -20 \u00b0 C ~ 90 \u00b0 C, dilengkapi dengan lapisan fluoroplastik kelas militer untuk memastikan operasi yang stabil dan perawatan yang rendah di bah industri yang paling sulit.<\/p>","protected":false},"featured_media":4020,"menu_order":0,"template":"","format":"standard","meta":{"_acf_changed":false,"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"show","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"unboxed","_kad_post_vertical_padding":"hide","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"class_list":["post-4016","product","type-product","status-publish","format-standard","has-post-thumbnail","hentry"],"acf":[],"taxonomy_info":[],"featured_image_src_large":["https:\/\/changyupump.com\/wp-content\/uploads\/2026\/03\/Chemical-Resistant-Submersible-Pump-13-1024x768.webp",1024,768,true],"author_info":[],"comment_info":"","_links":{"self":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/product\/4016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/media\/4020"}],"wp:attachment":[{"href":"https:\/\/changyupump.com\/id\/wp-json\/wp\/v2\/media?parent=4016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}